{"id":34294,"date":"2021-04-17T16:52:13","date_gmt":"2021-04-17T14:52:13","guid":{"rendered":"https:\/\/www.laguiadepamplona.com\/actualidad\/?p=34294"},"modified":"2023-04-11T11:49:41","modified_gmt":"2023-04-11T09:49:41","slug":"pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/","title":{"rendered":"Pamplona recuerda a siete v\u00edctimas de ETA asesinadas en la ciudad con la colocaci\u00f3n de sendas placas de homenaje en los lugares donde perdieron la vida"},"content":{"rendered":"<h5>Hoy se ha rendido homenaje a Vicente Luis Garcera, Jos\u00e9 Manuel Baena, Jes\u00fas Vidaurre, Jos\u00e9 Oyaga, Alberto Toca, Diego Torrente y Tom\u00e1s Caballero<\/h5>\n<p><!--more--><\/p>\n<p>Tal d\u00eda como hoy hace 39 a\u00f1os, el 17 de abril de 1982, ETA asesinaba en el entorno del puente de la Magdalena al polic\u00eda nacional Vicente Luis Garcera L\u00f3pez. En ese lugar ha comenzado esta ma\u00f1ana el recorrido de homenaje a siete v\u00edctimas de ETA que fallecieron a consecuencia de atentados perpetrados por la banda terrorista ETA en Pamplona. Por cuarta vez desde el pasado mes de marzo, Ayuntamiento de Pamplona y ANVITE han querido visibilizar y dignificar la memoria de esas v\u00edctimas con la colocaci\u00f3n de sendas placas en los lugares de sus atentados.<\/p>\n<p>Durante la ma\u00f1ana, se han visitado tambi\u00e9n la avenida de San Jorge, donde fue asesinado el inspector del Cuerpo Nacional de Polic\u00eda, Jos\u00e9 Manuel Baena Mart\u00edn; la calle San Miguel, en su confluencia con la plaza de San Francisco, donde murieron Jes\u00fas Vidaurre Olleta y Jos\u00e9 Oyaga Mara\u00f1\u00f3n; la calle Castillo de Maya, donde perdi\u00f3 la vida el delegado de la mutua ASEPEYO, Alberto Toca Echeverr\u00eda; y el campus de la UPNA, donde antes de su creaci\u00f3n cuando era una zona de aparcamiento, fue asesinado el polic\u00eda nacional Diego Torrente Reverte. Estos actos de recuerdo y memoria han concluido en el lugar donde ETA asesin\u00f3 por \u00faltima vez en Pamplona. Fue en la calle Mutilva Baja, el 6 de mayo de 1998. La v\u00edctima, el concejal de UPN en el Ayuntamiento de Pamplona, Tom\u00e1s Caballero Pastor.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>El alcalde de Pamplona, Enrique Maya, la presidenta del Gobierno de Navarra, Mar\u00eda Chivite, y el presidente de ANVITE, Jos\u00e9 Ignacio Toca, han participado en los breves actos institucionales que se han realizado en estos seis puntos de la ciudad, donde ETA asesin\u00f3 a siete personas entre 1978 y 1998. Han acudido tambi\u00e9n autoridades como el presidente del Parlamento de Navarra, Unai Hualde, el delegado del Gobierno en Navarra, Jos\u00e9 Luis Arasti, la directora general de Apoyo a V\u00edctimas del Terrorismo del Gobierno Espa\u00f1a, Montserrat Torija Noguera, el director del Memorial V\u00edctimas del Terrorismo, Florencio Dom\u00ednguez, y la consejera de Relaciones Ciudadanas, Ana Ollo.<\/p>\n<p>Los cuerpos y fuerzas de seguridad del Estado y las diferentes polic\u00edas han estado tambi\u00e9n representados por el jefe superior del Cuerpo Nacional de Polic\u00eda, Jos\u00e9 M\u00aa Borja, por el jefe de la Polic\u00eda Foral, Juan Carlos Zapico, por el coronel jefe de la Guardia Civil, Jos\u00e9 Santiago Mart\u00edn, por el general comandante militar de Navarra, Francisco German Mart\u00ednez, y por el jefe de la Polic\u00eda Municipal de Pamplona, Javier Goya. Han asistido, adem\u00e1s, representantes de los grupos municipales de Navarra Suma, PSN y Geroa Bai en el Ayuntamiento de Pamplona y representantes de colectivos y asociaciones como la Fundaci\u00f3n Tom\u00e1s Caballero, la Fundaci\u00f3n V\u00edctimas del Terrorismo, la Asociaci\u00f3n de V\u00edctimas del Terrorismo (AVT), COVITE, ANVITE, Libertad Ya y Vecinos de Paz.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Ofrenda floral y minuto de silencio<\/strong><\/p>\n<p>Los actos celebrados en cada uno de estos lugares de memoria han mantenido la estructura habitual de los anteriores homenajes celebrados el 1, 11 y 21 de marzo. Familiares de las v\u00edctimas asesinadas han dirigido unas breves palabras a las personas asistentes y, posteriormente, se han descubierto en cada lugar las placas con el nombre y la leyenda \u201cfue asesinado (o asesinada) por la banda terrorista ETA el d\u00eda (fecha del atentado). Verdad, memoria, dignidad y justicia\u201d. La entrega de reproducci\u00f3n de esa placa a las familias, una ofrenda floral y un minuto de silencio han cerrado los breves actos institucionales. Esta iniciativa forma parte del convenio de colaboraci\u00f3n firmado en septiembre del a\u00f1o pasado por el Ayuntamiento de Pamplona y ANVITE para dignificar la memoria de las v\u00edctimas de ETA.<\/p>\n<p>El polic\u00eda nacional Vicente Luis Garcera L\u00f3pez era asesinado el 17 de abril de 1982 en la zona del puente de la Magdalena. De madrugada, una tanqueta de la Polic\u00eda Nacional que regresaba de prestar vigilancia en la subestaci\u00f3n de Fuerzas El\u00e9ctricas y se dirig\u00eda al cuartel de Beloso era atacada con una granada anticarro, que perfor\u00f3 la cubierta de la tanqueta y explot\u00f3 en su interior. Garcera era el conductor. Su hija Laura ha estado presente en este homenaje.<\/p>\n<p>El inspector del Cuerpo Nacional de Polic\u00eda, Jos\u00e9 Manuel Baena Mart\u00edn, era asesinado en la avenida de San Jorge 77 el 11 de enero de 1978. Fue la segunda v\u00edctima mortal de ETA en Pamplona. Baena hab\u00eda acudido al registro de un piso donde encontraron armas y documentaci\u00f3n falsa. Al t\u00e9rmino de ese registro, dos miembros de ETA aparecieron en el portal y, al identificar a los agentes, abrieron fuego. Tambi\u00e9n fallecieron los dos terroristas, que resultaron ser los asesinos del comandante Joaqu\u00edn \u00cdmaz. Esta ma\u00f1ana ha participado en el acto la sobrina del inspector, M\u00aa Carmen Fonta Baena.<\/p>\n<p>Jes\u00fas Vidaurre Olleta y Jos\u00e9 Oyaga Mara\u00f1\u00f3n murieron asesinados el 1 de mayo de 1980 en la calle San Miguel, en la esquina con la plaza de San Francisco. Ambos recibieron sendos disparos en la nuca. Durante a\u00f1os, el doble asesinato qued\u00f3 fuera de los listados de atentados terroristas por la ausencia de reivindicaci\u00f3n. Sin embargo, la banda terrorista se atribuy\u00f3 en documentos internos este doble crimen. Han acudido a este homenaje Ver\u00f3nica Zapata, nieta de Jos\u00e9 Oyaga, y Julio Vidaurre, hijo de Jes\u00fas Vidaurre.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Presencia de familiares de las v\u00edctimas<\/strong><\/p>\n<p>El 8 de octubre de 1982, dos miembros de ETA entraron a cara descubierta en las oficinas de la mutua ASEPEYO, en la calle Castillo de Maya de Pamplona. All\u00ed preguntaron por Alberto Toca Echeverr\u00eda, que charlaba en su despacho con el m\u00e9dico de la mutua. Los dos terroristas abrieron la puerta y, sin mediar palabra, dispararon contra Toca, que recibi\u00f3 dos impactos de bala en la cabeza. Su nieta Blanca Gispert ha dirigido unas palabras a las personas asistentes.<\/p>\n<p>En una zona de aparcamiento junto al estadio de El Sadar, ahora parte del campus de la UPNA, era asesinado el 7 de junio de 1984 el polic\u00eda nacional Diego Torrente Reverte. Los miembros de un comando etarra hab\u00edan planeado robar un veh\u00edculo en las inmediaciones del estadio de El Sadar. Sobre las nueve de la noche vieron a un hombre que estaba limpiando su veh\u00edculo. Tras revelar que era polic\u00eda, uno de los terroristas le dispar\u00f3 un tiro a quemarropa que lo mat\u00f3 en acto. Su familia ha participado tambi\u00e9n en el acto con una breve intervenci\u00f3n de agradecimiento.<\/p>\n<p>El recorrido ha terminado en la calle Mutilva Baja, donde el 6 de mayo de 1998, ETA asesinaba al concejal de UPN del Ayuntamiento de Pamplona, Tom\u00e1s Caballero. Ese d\u00eda, Tom\u00e1s Caballero acababa de subirse a su veh\u00edculo para ir a trabajar a la Casa Consistorial. Dos terroristas se le acercaron y le dispararon sendos\u00a0tiros en la cabeza. Ha intervenido, dedicando unas breves palabras, su hija Ana Caballero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy se ha rendido homenaje a Vicente Luis Garcera, Jos\u00e9 Manuel Baena, Jes\u00fas Vidaurre, Jos\u00e9 Oyaga, Alberto Toca, Diego Torrente y Tom\u00e1s Caballero<\/p>\n","protected":false},"author":1,"featured_media":34295,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-34294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pamplona recuerda a siete v\u00edctimas de ETA asesinadas en la ciudad con la colocaci\u00f3n de sendas placas de homenaje en los lugares donde perdieron la vida<\/title>\n<meta name=\"description\" content=\"Hoy se ha rendido homenaje a Vicente Luis Garcera, Jos\u00e9 Manuel Baena, Jes\u00fas Vidaurre, Jos\u00e9 Oyaga, Alberto Toca, Diego Torrente y Tom\u00e1s Caballero\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pamplona recuerda a siete v\u00edctimas de ETA asesinadas en la ciudad con la colocaci\u00f3n de sendas placas de homenaje en los lugares donde perdieron la vida\" \/>\n<meta property=\"og:description\" content=\"Hoy se ha rendido homenaje a Vicente Luis Garcera, Jos\u00e9 Manuel Baena, Jes\u00fas Vidaurre, Jos\u00e9 Oyaga, Alberto Toca, Diego Torrente y Tom\u00e1s Caballero\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-17T14:52:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-11T09:49:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/04\/placas-ETA-pamplona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"Pamplona recuerda a siete v\u00edctimas de ETA asesinadas en la ciudad con la colocaci\u00f3n de sendas placas de homenaje en los lugares donde perdieron la vida\",\"datePublished\":\"2021-04-17T14:52:13+00:00\",\"dateModified\":\"2023-04-11T09:49:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\\\/\"},\"wordCount\":1224,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/placas-ETA-pamplona.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\\\/\",\"name\":\"Pamplona recuerda a siete v\u00edctimas de ETA asesinadas en la ciudad con la colocaci\u00f3n de sendas placas de homenaje en los lugares donde perdieron la vida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/placas-ETA-pamplona.jpg\",\"datePublished\":\"2021-04-17T14:52:13+00:00\",\"dateModified\":\"2023-04-11T09:49:41+00:00\",\"description\":\"Hoy se ha rendido homenaje a Vicente Luis Garcera, Jos\u00e9 Manuel Baena, Jes\u00fas Vidaurre, Jos\u00e9 Oyaga, Alberto Toca, Diego Torrente y Tom\u00e1s Caballero\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/placas-ETA-pamplona.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/placas-ETA-pamplona.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pamplona recuerda a siete v\u00edctimas de ETA asesinadas en la ciudad con la colocaci\u00f3n de sendas placas de homenaje en los lugares donde perdieron la vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pamplona recuerda a siete v\u00edctimas de ETA asesinadas en la ciudad con la colocaci\u00f3n de sendas placas de homenaje en los lugares donde perdieron la vida","description":"Hoy se ha rendido homenaje a Vicente Luis Garcera, Jos\u00e9 Manuel Baena, Jes\u00fas Vidaurre, Jos\u00e9 Oyaga, Alberto Toca, Diego Torrente y Tom\u00e1s Caballero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/","og_locale":"es_ES","og_type":"article","og_title":"Pamplona recuerda a siete v\u00edctimas de ETA asesinadas en la ciudad con la colocaci\u00f3n de sendas placas de homenaje en los lugares donde perdieron la vida","og_description":"Hoy se ha rendido homenaje a Vicente Luis Garcera, Jos\u00e9 Manuel Baena, Jes\u00fas Vidaurre, Jos\u00e9 Oyaga, Alberto Toca, Diego Torrente y Tom\u00e1s Caballero","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2021-04-17T14:52:13+00:00","article_modified_time":"2023-04-11T09:49:41+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/04\/placas-ETA-pamplona.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"Pamplona recuerda a siete v\u00edctimas de ETA asesinadas en la ciudad con la colocaci\u00f3n de sendas placas de homenaje en los lugares donde perdieron la vida","datePublished":"2021-04-17T14:52:13+00:00","dateModified":"2023-04-11T09:49:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/"},"wordCount":1224,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/04\/placas-ETA-pamplona.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/","name":"Pamplona recuerda a siete v\u00edctimas de ETA asesinadas en la ciudad con la colocaci\u00f3n de sendas placas de homenaje en los lugares donde perdieron la vida","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/04\/placas-ETA-pamplona.jpg","datePublished":"2021-04-17T14:52:13+00:00","dateModified":"2023-04-11T09:49:41+00:00","description":"Hoy se ha rendido homenaje a Vicente Luis Garcera, Jos\u00e9 Manuel Baena, Jes\u00fas Vidaurre, Jos\u00e9 Oyaga, Alberto Toca, Diego Torrente y Tom\u00e1s Caballero","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/04\/placas-ETA-pamplona.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/04\/placas-ETA-pamplona.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-recuerda-a-siete-victimas-de-eta-asesinadas-en-la-ciudad-con-la-colocacion-de-sendas-placas-de-homenaje-en-los-lugares-donde-perdieron-la-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Pamplona recuerda a siete v\u00edctimas de ETA asesinadas en la ciudad con la colocaci\u00f3n de sendas placas de homenaje en los lugares donde perdieron la vida"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/34294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=34294"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/34294\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/34295"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=34294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=34294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=34294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}