{"id":34014,"date":"2021-03-30T17:54:44","date_gmt":"2021-03-30T15:54:44","guid":{"rendered":"https:\/\/www.laguiadepamplona.com\/actualidad\/?p=34014"},"modified":"2023-04-11T11:49:47","modified_gmt":"2023-04-11T09:49:47","slug":"el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/","title":{"rendered":"El alcalde recibe al atleta Rub\u00e9n Pascual, quien ha logrado tres medallas de oro y bronce en los Campeonatos de Europa para personas con discapacidad intelectual"},"content":{"rendered":"<h5>Rub\u00e9n Pascual se hizo con los oros en los relevos 4&#215;200 y 4&#215;400 y con el bronce en la prueba de 60 metros<\/h5>\n<p><!--more--><\/p>\n<p>El alcalde de Pamplona, Enrique Maya, ha recibido al atleta Rub\u00e9n Pascual, quien ha logrado tres medallas de oro y bronce en los Campeonatos de Europa de pista cubierta para personas con discapacidad intelectual. En concreto, se hizo con los oros en los relevos 4&#215;200 y 4&#215;400 y con el bronce en el 60 metros. El campeonato se celebr\u00f3 del 9 al 14 de marzo en Nantes(Francia). Adem\u00e1s, qued\u00f3 cuarto en la carrera de los 200 metros. A la visita, en la que tambi\u00e9n ha participado la concejala delegada de Servicios Sociales, Acci\u00f3n Comunitaria y Deporte, Mar\u00eda Caballero, ha acudido acompa\u00f1ado de su madre.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>Atleta del equipo Grupoempleo y de El Molino, Rub\u00e9n Pacual Cortes (17\/8\/1991) une estas medallas a la obtenidas en 2020 en el Mundial de Atletismo Adaptado celebrado en Torun (Polonia), donde logr\u00f3 tambi\u00e9n la medalla de oro en relevos y el tercer puesto en la carrera de 200 metros por equipos. Un a\u00f1o antes, en 2019, fue Campe\u00f3n del Mundo por equipos en <strong>Australia.<\/strong><\/p>\n<p>Adem\u00e1s de en el atletismo, Rub\u00e9n Pascual destaca en otros deportes como el esqu\u00ed de fondo, donde ha llegado a ser tambi\u00e9n campe\u00f3n internacional. En estos momentos se est\u00e1 preparando con el objetivo de conseguir plaza para los Juegos Paral\u00edmpicos de Tokio que se celebran este verano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rub\u00e9n Pascual se hizo con los oros en los relevos 4&#215;200 y 4&#215;400 y con el bronce en la prueba de 60 metros<\/p>\n","protected":false},"author":1,"featured_media":34015,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-34014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El alcalde recibe al atleta Rub\u00e9n Pascual, quien ha logrado tres medallas de oro y bronce en los Campeonatos de Europa para personas con discapacidad intelectual<\/title>\n<meta name=\"description\" content=\"Rub\u00e9n Pascual se hizo con los oros en los relevos 4x200 y 4x400 y con el bronce en la prueba de 60 metros\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El alcalde recibe al atleta Rub\u00e9n Pascual, quien ha logrado tres medallas de oro y bronce en los Campeonatos de Europa para personas con discapacidad intelectual\" \/>\n<meta property=\"og:description\" content=\"Rub\u00e9n Pascual se hizo con los oros en los relevos 4x200 y 4x400 y con el bronce en la prueba de 60 metros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-30T15:54:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-11T09:49:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/03\/ruben_pascual_jmg3747.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El alcalde recibe al atleta Rub\u00e9n Pascual, quien ha logrado tres medallas de oro y bronce en los Campeonatos de Europa para personas con discapacidad intelectual\",\"datePublished\":\"2021-03-30T15:54:44+00:00\",\"dateModified\":\"2023-04-11T09:49:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\\\/\"},\"wordCount\":273,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ruben_pascual_jmg3747.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\\\/\",\"name\":\"El alcalde recibe al atleta Rub\u00e9n Pascual, quien ha logrado tres medallas de oro y bronce en los Campeonatos de Europa para personas con discapacidad intelectual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ruben_pascual_jmg3747.jpg\",\"datePublished\":\"2021-03-30T15:54:44+00:00\",\"dateModified\":\"2023-04-11T09:49:47+00:00\",\"description\":\"Rub\u00e9n Pascual se hizo con los oros en los relevos 4x200 y 4x400 y con el bronce en la prueba de 60 metros\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ruben_pascual_jmg3747.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ruben_pascual_jmg3747.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"A* Jes\u00fas Garzaron F* 2021_03_30 T* Visita del deportista Rub\u00e9n Pascual L* Ayuntamiento de Pamplona\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El alcalde recibe al atleta Rub\u00e9n Pascual, quien ha logrado tres medallas de oro y bronce en los Campeonatos de Europa para personas con discapacidad intelectual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El alcalde recibe al atleta Rub\u00e9n Pascual, quien ha logrado tres medallas de oro y bronce en los Campeonatos de Europa para personas con discapacidad intelectual","description":"Rub\u00e9n Pascual se hizo con los oros en los relevos 4x200 y 4x400 y con el bronce en la prueba de 60 metros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/","og_locale":"es_ES","og_type":"article","og_title":"El alcalde recibe al atleta Rub\u00e9n Pascual, quien ha logrado tres medallas de oro y bronce en los Campeonatos de Europa para personas con discapacidad intelectual","og_description":"Rub\u00e9n Pascual se hizo con los oros en los relevos 4x200 y 4x400 y con el bronce en la prueba de 60 metros","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2021-03-30T15:54:44+00:00","article_modified_time":"2023-04-11T09:49:47+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/03\/ruben_pascual_jmg3747.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El alcalde recibe al atleta Rub\u00e9n Pascual, quien ha logrado tres medallas de oro y bronce en los Campeonatos de Europa para personas con discapacidad intelectual","datePublished":"2021-03-30T15:54:44+00:00","dateModified":"2023-04-11T09:49:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/"},"wordCount":273,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/03\/ruben_pascual_jmg3747.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/","name":"El alcalde recibe al atleta Rub\u00e9n Pascual, quien ha logrado tres medallas de oro y bronce en los Campeonatos de Europa para personas con discapacidad intelectual","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/03\/ruben_pascual_jmg3747.jpg","datePublished":"2021-03-30T15:54:44+00:00","dateModified":"2023-04-11T09:49:47+00:00","description":"Rub\u00e9n Pascual se hizo con los oros en los relevos 4x200 y 4x400 y con el bronce en la prueba de 60 metros","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/03\/ruben_pascual_jmg3747.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/03\/ruben_pascual_jmg3747.jpg","width":1920,"height":1280,"caption":"A* Jes\u00fas Garzaron F* 2021_03_30 T* Visita del deportista Rub\u00e9n Pascual L* Ayuntamiento de Pamplona"},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-al-atleta-ruben-pascual-quien-ha-logrado-tres-medallas-de-oro-y-bronce-en-los-campeonatos-de-europa-para-personas-con-discapacidad-intelectual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El alcalde recibe al atleta Rub\u00e9n Pascual, quien ha logrado tres medallas de oro y bronce en los Campeonatos de Europa para personas con discapacidad intelectual"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/34014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=34014"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/34014\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/34015"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=34014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=34014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=34014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}