{"id":33044,"date":"2021-02-03T17:39:30","date_gmt":"2021-02-03T15:39:30","guid":{"rendered":"https:\/\/www.laguiadepamplona.com\/actualidad\/?p=33044"},"modified":"2021-02-03T17:39:30","modified_gmt":"2021-02-03T15:39:30","slug":"el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/","title":{"rendered":"El Ayuntamiento de Pamplona participa en un taller on line sobre buenas pr\u00e1cticas en el desarrollo de la Agenda Urbana local organizado por FEMP"},"content":{"rendered":"<h5>Es un reconocimiento al esfuerzo de la ciudad en el desarrollo de su Estrategia 2030 hacia el logro de los Objetivos de Desarrollo Sostenible<\/h5>\n<p><!--more--><\/p>\n<p>El Ayuntamiento de Pamplona ha participado esta ma\u00f1ana en un Taller online sobre \u2018Cambio Clim\u00e1tico y Agenda Urbana\u2019\u201d organizado por la Red Espa\u00f1ola de Ciudades por el Clima, de la Federaci\u00f3n Espa\u00f1ola de Municipios y Provincias (FEMP). Pamplona ha sido elegida, junto con el Ayuntamiento de M\u00e1laga, entre las ciudades ejemplo de buenas pr\u00e1cticas por su trabajo en este campo a trav\u00e9s del desarrollo de una Agenda Urbana a largo plazo en apoyo a los Objetivos de Desarrollo Sostenible (ODS) y la implementaci\u00f3n de un Estrategia de Transici\u00f3n Energ\u00e9tica y Cambio Clim\u00e1tico. La jornada, dirigida prioritariamente a t\u00e9cnicos, ha estado abierta al p\u00fablico a trav\u00e9s de la aplicaci\u00f3n zoom.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>Jose Ferm\u00edn Costero, responsable de la Oficina Estrat\u00e9gica del Ayuntamiento de Pamplona, ha participado en la mesa redonda eje del encuentro en el que se pretend\u00eda mostrar la importancia de introducir en los Planes de Acci\u00f3n de la Agenda Urbana medidas de adaptaci\u00f3n y mitigaci\u00f3n del cambio clim\u00e1tico, as\u00ed como reflexionar sobre proyectos que podr\u00edan desarrollar los gobiernos locales en este sentido. La cita ha contado con el apoyo la Oficina Espa\u00f1ola de Cambio Clim\u00e1tico (OECC) y el Ministerio de Transporte, Movilidad y Agenda Urbana.<\/p>\n<p>El Ayuntamiento de Pamplona firm\u00f3 con ese ministerio el pasado diciembre un protocolo para elaborar la Estrategia 2030\/ Agenda Urbana local (E2030) que es uno de los proyectos pilotos de la Agenda Urbana Espa\u00f1ola. As\u00ed, en estos momentos el Consistorio es pionero en el trabajo de conseguir una ciudad en la que el desarrollo sostenible garantice la calidad de vida de todos los ciudadanos. La Estrategia 2030 de Pamplona incluye 29 objetivos estrat\u00e9gicos divididos en 5 grandes dimensiones: cambio clim\u00e1tico y sostenibilidad, inclusi\u00f3n social, gesti\u00f3n p\u00fablica innovadora, cultura y turismo, y econom\u00eda del conocimiento. Esta estrategia ha sido elaborada con un enfoque transversal, multisectorial y multinivel, con la implicaci\u00f3n de unos 100 agentes relevantes de la ciudad y la participaci\u00f3n de m\u00e1s de 1.000 personas. El trabajo municipal se alinea con los esfuerzos que se desarrollan a nivel nacional e internacional.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>M\u00e1s de dos d\u00e9cadas repensando el desarrollo urbano<\/strong><\/p>\n<p>La ciudad inici\u00f3 el compromiso con el desarrollo sostenible hace m\u00e1s de dos d\u00e9cadas, cuando suscribi\u00f3 la Carta de las Ciudades Europeas hacia la Sostenibilidad o Carta de Aalborg (1998), asumiendo la realizaci\u00f3n de una Agenda 21 propia. En 2011 el Pleno aprob\u00f3 por unanimidad el II Plan de Acci\u00f3n de Agenda 21 de Pamplona y continu\u00f3 con su trabajo de medici\u00f3n de indicadores, sensibilizaci\u00f3n por la sostenibilidad<\/p>\n<p>M\u00e1s recientemente, este mismo \u00f3rgano aprob\u00f3 una declaraci\u00f3n institucional impulsada por la FEMP a favor de la Agenda 2030 y los Objetivos de Desarrollo Sostenible definidos por la ONU (septiembre de 2019). En ese sentido se desarrolla en trabajo de la ciudad en diversos foros como el \u2018Foro Permanente de la Agenda Urbana Espa\u00f1ola\u2019, un grupo de trabajo de ciudades que est\u00e1n impulsando la Agenda Urbana en sus territorios, pero tambi\u00e9n en otras dos redes espec\u00edficas: \u2018Red de Entidades Locales para el Desarrollo de los Objetivos de Desarrollo Sostenible de la Agenda\u2019 (desde 2020) y la \u2018Red Espa\u00f1ola de Ciudades por el Clima\u2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es un reconocimiento al esfuerzo de la ciudad en el desarrollo de su Estrategia 2030 hacia el logro de los Objetivos de Desarrollo Sostenible<\/p>\n","protected":false},"author":1,"featured_media":33045,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-33044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Ayuntamiento de Pamplona participa en un taller on line sobre buenas pr\u00e1cticas en el desarrollo de la Agenda Urbana local organizado por FEMP<\/title>\n<meta name=\"description\" content=\"Es un reconocimiento al esfuerzo de la ciudad en el desarrollo de su Estrategia 2030 hacia el logro de los Objetivos de Desarrollo Sostenible\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Ayuntamiento de Pamplona participa en un taller on line sobre buenas pr\u00e1cticas en el desarrollo de la Agenda Urbana local organizado por FEMP\" \/>\n<meta property=\"og:description\" content=\"Es un reconocimiento al esfuerzo de la ciudad en el desarrollo de su Estrategia 2030 hacia el logro de los Objetivos de Desarrollo Sostenible\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-03T15:39:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/02\/taller_cambio_climatico_y_agenda_urbana_3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1363\" \/>\n\t<meta property=\"og:image:height\" content=\"697\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El Ayuntamiento de Pamplona participa en un taller on line sobre buenas pr\u00e1cticas en el desarrollo de la Agenda Urbana local organizado por FEMP\",\"datePublished\":\"2021-02-03T15:39:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\\\/\"},\"wordCount\":600,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/taller_cambio_climatico_y_agenda_urbana_3.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\\\/\",\"name\":\"El Ayuntamiento de Pamplona participa en un taller on line sobre buenas pr\u00e1cticas en el desarrollo de la Agenda Urbana local organizado por FEMP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/taller_cambio_climatico_y_agenda_urbana_3.jpg\",\"datePublished\":\"2021-02-03T15:39:30+00:00\",\"description\":\"Es un reconocimiento al esfuerzo de la ciudad en el desarrollo de su Estrategia 2030 hacia el logro de los Objetivos de Desarrollo Sostenible\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/taller_cambio_climatico_y_agenda_urbana_3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/taller_cambio_climatico_y_agenda_urbana_3.jpg\",\"width\":1363,\"height\":697},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Ayuntamiento de Pamplona participa en un taller on line sobre buenas pr\u00e1cticas en el desarrollo de la Agenda Urbana local organizado por FEMP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Ayuntamiento de Pamplona participa en un taller on line sobre buenas pr\u00e1cticas en el desarrollo de la Agenda Urbana local organizado por FEMP","description":"Es un reconocimiento al esfuerzo de la ciudad en el desarrollo de su Estrategia 2030 hacia el logro de los Objetivos de Desarrollo Sostenible","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/","og_locale":"es_ES","og_type":"article","og_title":"El Ayuntamiento de Pamplona participa en un taller on line sobre buenas pr\u00e1cticas en el desarrollo de la Agenda Urbana local organizado por FEMP","og_description":"Es un reconocimiento al esfuerzo de la ciudad en el desarrollo de su Estrategia 2030 hacia el logro de los Objetivos de Desarrollo Sostenible","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2021-02-03T15:39:30+00:00","og_image":[{"width":1363,"height":697,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/02\/taller_cambio_climatico_y_agenda_urbana_3.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El Ayuntamiento de Pamplona participa en un taller on line sobre buenas pr\u00e1cticas en el desarrollo de la Agenda Urbana local organizado por FEMP","datePublished":"2021-02-03T15:39:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/"},"wordCount":600,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/02\/taller_cambio_climatico_y_agenda_urbana_3.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/","name":"El Ayuntamiento de Pamplona participa en un taller on line sobre buenas pr\u00e1cticas en el desarrollo de la Agenda Urbana local organizado por FEMP","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/02\/taller_cambio_climatico_y_agenda_urbana_3.jpg","datePublished":"2021-02-03T15:39:30+00:00","description":"Es un reconocimiento al esfuerzo de la ciudad en el desarrollo de su Estrategia 2030 hacia el logro de los Objetivos de Desarrollo Sostenible","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/02\/taller_cambio_climatico_y_agenda_urbana_3.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2021\/02\/taller_cambio_climatico_y_agenda_urbana_3.jpg","width":1363,"height":697},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-participa-en-un-taller-on-line-sobre-buenas-practicas-en-el-desarrollo-de-la-agenda-urbana-local-organizado-por-femp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El Ayuntamiento de Pamplona participa en un taller on line sobre buenas pr\u00e1cticas en el desarrollo de la Agenda Urbana local organizado por FEMP"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/33044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=33044"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/33044\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/33045"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=33044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=33044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=33044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}