{"id":33018,"date":"2021-02-01T15:33:52","date_gmt":"2021-02-01T13:33:52","guid":{"rendered":"https:\/\/www.laguiadepamplona.com\/actualidad\/?p=33018"},"modified":"2021-02-01T15:33:52","modified_gmt":"2021-02-01T13:33:52","slug":"el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/","title":{"rendered":"El paseo de Sarasate acoge este mi\u00e9rcoles el tradicional mercadillo de San Blas, con 21 puestos que vender\u00e1n roscos y dulces y acceso controlado al recinto"},"content":{"rendered":"<h5>El mercadillo cambia este a\u00f1o de ubicaci\u00f3n para garantizar las medidas de seguridad y cumplir la normativa derivada de la COVID-19<\/h5>\n<p><!--more--><\/p>\n<p>Este mi\u00e9rcoles 3 de febrero Pamplona celebra la festividad de San Blas con novedades en el tradicional mercadillo de roscos y dulces. El cumplimiento de la normativa derivada de la pandemia de la COVID-19 ha llevado al Ayuntamiento de Pamplona a trasladar el mercadillo de la plazuela de San Nicol\u00e1s y la calle San Miguel al paseo de Sarasate, con una mayor amplitud tanto para los puestos como para el tr\u00e1nsito peatonal.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>Los 21 puestos del mercadillo se colocar\u00e1n en una sola l\u00ednea, en la parte central del paseo, desde la zona frente a la iglesia de San Nicol\u00e1s hasta el entorno del Monumento a los Fueros. El espacio se cerrar\u00e1 con 200 vallas y cuatro personas vigilar\u00e1n los accesos para poder controlar los aforos, las distancias y las medidas preventivas establecidas por la normativa para evitar contagios. El aforo m\u00e1ximo permitido dentro de todo el recinto del mercadillo de San Blas, ser\u00e1 de 165 personas.<\/p>\n<p>El mercadillo contar\u00e1 con una entrada y una salida diferenciadas. La entrada se ubicar\u00e1 en la zona cercana a la puerta de la iglesia de San Nicol\u00e1s y la salida, junto al Monumento a los Fueros. Se podr\u00e1n vender productos desde las 9 horas hasta las 20.30 horas. Los puestos podr\u00e1n comenzar a instalarse a partir de las 7 horas del mismo mi\u00e9rcoles y deben estar montados antes de las 9 horas. A las 21 horas, los puestos deben estar ya quitados.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>Esos puestos no ocupar\u00e1n m\u00e1s espacio que el autorizado por el Ayuntamiento (3 metros) y, una vez montados, deber\u00e1n dejar un espacio en la calzada que permita el paso de los veh\u00edculos de emergencia y servicio de limpieza. Los puestos dispondr\u00e1n de palets para mantener elevadas las cajas almacenadas y dispondr\u00e1n de toldos adecuados para proteger la mercanc\u00eda.<\/p>\n<p>Solamente se expondr\u00e1n a la venta productos alimenticios t\u00edpicos de la fiesta de San Blas (roscos y dulces), con la documentaci\u00f3n acreditativa de su origen. Se proh\u00edbe la venta de pan, as\u00ed como la venta de productos con nata o crema pastelera. Todos los productos se deber\u00e1n mantener protegidos fuera del alcance del p\u00fablico mediante vitrinas o dispositivo similar y, en su caso, debidamente envueltos o envasados, respetando las fechas de consumo preferente. Los productos se servir\u00e1n con pinzas o guantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mercadillo cambia este a\u00f1o de ubicaci\u00f3n para garantizar las medidas de seguridad y cumplir la normativa derivada de la COVID-19<\/p>\n","protected":false},"author":1,"featured_media":11646,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-33018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El paseo de Sarasate acoge este mi\u00e9rcoles el tradicional mercadillo de San Blas, con 21 puestos que vender\u00e1n roscos y dulces y acceso controlado al recinto<\/title>\n<meta name=\"description\" content=\"El mercadillo cambia este a\u00f1o de ubicaci\u00f3n para garantizar las medidas de seguridad y cumplir la normativa derivada de la COVID-19\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El paseo de Sarasate acoge este mi\u00e9rcoles el tradicional mercadillo de San Blas, con 21 puestos que vender\u00e1n roscos y dulces y acceso controlado al recinto\" \/>\n<meta property=\"og:description\" content=\"El mercadillo cambia este a\u00f1o de ubicaci\u00f3n para garantizar las medidas de seguridad y cumplir la normativa derivada de la COVID-19\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-01T13:33:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/02\/san_blas2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El paseo de Sarasate acoge este mi\u00e9rcoles el tradicional mercadillo de San Blas, con 21 puestos que vender\u00e1n roscos y dulces y acceso controlado al recinto\",\"datePublished\":\"2021-02-01T13:33:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\\\/\"},\"wordCount\":443,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/san_blas2.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\\\/\",\"name\":\"El paseo de Sarasate acoge este mi\u00e9rcoles el tradicional mercadillo de San Blas, con 21 puestos que vender\u00e1n roscos y dulces y acceso controlado al recinto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/san_blas2.jpg\",\"datePublished\":\"2021-02-01T13:33:52+00:00\",\"description\":\"El mercadillo cambia este a\u00f1o de ubicaci\u00f3n para garantizar las medidas de seguridad y cumplir la normativa derivada de la COVID-19\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/san_blas2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/san_blas2.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El paseo de Sarasate acoge este mi\u00e9rcoles el tradicional mercadillo de San Blas, con 21 puestos que vender\u00e1n roscos y dulces y acceso controlado al recinto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El paseo de Sarasate acoge este mi\u00e9rcoles el tradicional mercadillo de San Blas, con 21 puestos que vender\u00e1n roscos y dulces y acceso controlado al recinto","description":"El mercadillo cambia este a\u00f1o de ubicaci\u00f3n para garantizar las medidas de seguridad y cumplir la normativa derivada de la COVID-19","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/","og_locale":"es_ES","og_type":"article","og_title":"El paseo de Sarasate acoge este mi\u00e9rcoles el tradicional mercadillo de San Blas, con 21 puestos que vender\u00e1n roscos y dulces y acceso controlado al recinto","og_description":"El mercadillo cambia este a\u00f1o de ubicaci\u00f3n para garantizar las medidas de seguridad y cumplir la normativa derivada de la COVID-19","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2021-02-01T13:33:52+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/02\/san_blas2.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El paseo de Sarasate acoge este mi\u00e9rcoles el tradicional mercadillo de San Blas, con 21 puestos que vender\u00e1n roscos y dulces y acceso controlado al recinto","datePublished":"2021-02-01T13:33:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/"},"wordCount":443,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/02\/san_blas2.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/","name":"El paseo de Sarasate acoge este mi\u00e9rcoles el tradicional mercadillo de San Blas, con 21 puestos que vender\u00e1n roscos y dulces y acceso controlado al recinto","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/02\/san_blas2.jpg","datePublished":"2021-02-01T13:33:52+00:00","description":"El mercadillo cambia este a\u00f1o de ubicaci\u00f3n para garantizar las medidas de seguridad y cumplir la normativa derivada de la COVID-19","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/02\/san_blas2.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/02\/san_blas2.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-paseo-de-sarasate-acoge-este-miercoles-el-tradicional-mercadillo-de-san-blas-con-21-puestos-que-venderan-roscos-y-dulces-y-acceso-controlado-al-recinto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El paseo de Sarasate acoge este mi\u00e9rcoles el tradicional mercadillo de San Blas, con 21 puestos que vender\u00e1n roscos y dulces y acceso controlado al recinto"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/33018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=33018"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/33018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/11646"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=33018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=33018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=33018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}