{"id":32325,"date":"2020-11-17T17:10:35","date_gmt":"2020-11-17T15:10:35","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=32325"},"modified":"2020-11-17T17:10:35","modified_gmt":"2020-11-17T15:10:35","slug":"pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/","title":{"rendered":"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad"},"content":{"rendered":"<h5>Dentro de la Estrategia de Transici\u00f3n Energ\u00e9tica y Cambio Clim\u00e1tico 2030 se evaluar\u00e1 el potencial de generaci\u00f3n renovable (fotovoltaica y t\u00e9rmica) de cada cubierta de la ciudad<\/h5>\n<p><!--more--><\/p>\n<p>El Ayuntamiento de Pamplona est\u00e1 trabajando en el desarrollo de su Mapa Solar, una iniciativa con la que se podr\u00e1 identificar el potencial de generaci\u00f3n energ\u00e9tica de la ciudad. Incluido dentro de la Estrategia de Transici\u00f3n Energ\u00e9tica y Cambio Clim\u00e1tico 2030 (ETEyCC2030), servir\u00e1 para evaluar el potencial de generaci\u00f3n renovable (fotovoltaica y t\u00e9rmica) de cada cubierta de la ciudad. En estos primeros meses de desarrollo de la ETEyCC2030 se est\u00e1n definiendo tanto la situaci\u00f3n actual de la ciudad desde el punto de vista de demanda energ\u00e9tica, emisiones de gases de efecto invernadero y vulnerabilidad clim\u00e1tica como los objetivos a marcar para los siguientes a\u00f1os.<\/p>\n<p>Para definir estos objetivos es necesario conocer la situaci\u00f3n actual de la ciudad y sus escenarios futuros. En esta l\u00ednea, el Ayuntamiento ha comenzado el desarrollo del Mapa Solar de Pamplona, que se est\u00e1 desarrollando de la mano de investigadores de la Universidad P\u00fablica de Navarra, miembros del Instituto de Smart Cities. Este trabajo contar\u00e1 con dos l\u00edneas de acci\u00f3n: evaluaci\u00f3n del potencial solar de la ciudad y aproximaci\u00f3n al an\u00e1lisis de los puntos de temperatura extrema en Pamplona.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Evaluaci\u00f3n del potencial solar<\/strong><\/p>\n<p>Para complementar la ETEyCC2030 y poder dise\u00f1ar las l\u00edneas de acci\u00f3n ligadas a la generaci\u00f3n renovable distribuida, el Consistorio pamplon\u00e9s considera fundamental conocer el potencial que tiene la misma en la ciudad, algo que lograr\u00e1 con esta nueva iniciativa.<\/p>\n<p>Uno de los puntos de partida del Mapa Solar es que la energ\u00eda solar tiene un gran potencial en estas latitudes y posee la capacidad de convertirse en energ\u00eda el\u00e9ctrica a trav\u00e9s de tecnolog\u00eda fotovoltaica o energ\u00eda t\u00e9rmica por medio de energ\u00eda solar t\u00e9rmica. La primera de ellas se sit\u00faa actualmente como una de las fuentes de generaci\u00f3n de energ\u00eda el\u00e9ctrica m\u00e1s baratas del momento y su versatilidad y posibilidad de generar energ\u00eda en los mismos puntos de suministro la convierte en una de las energ\u00edas renovables con m\u00e1s potencial.<\/p>\n<p>Otro, la energ\u00eda solar que recibe la ciudad anualmente es muy superior a la que demanda (teniendo en cuenta la suma de lo necesitado por personas, negocios, industrias o transporte) pero no toda es utilizable. Por ello se est\u00e1 desarrollando este primer trabajo que definir\u00e1 la capacidad real de generar energ\u00eda \u00fatil tanto el\u00e9ctrica como t\u00e9rmica.<\/p>\n<p>El estudio toma como referencia una cuadr\u00edcula de an\u00e1lisis de 2&#215;2 metros y tiene en cuenta la inclinaci\u00f3n de las cubiertas y la sombra que recibe. As\u00ed se ofrecer\u00e1 el dato real en el punto previo a la instalaci\u00f3n. Para el c\u00e1lculo de la energ\u00eda prevista que saldr\u00e1 de cada metro cuadro de panel se est\u00e1 teniendo en cuenta las caracter\u00edsticas t\u00e9cnicas de modelos de paneles comerciales.<\/p>\n<p>El resultado final del Mapa Solar ser\u00e1 puesto a disposici\u00f3n de ciudadan\u00eda, industrias y empresas de la ciudad. De esa forma se podr\u00e1 identificar la capacidad de cada cubierta y espacio de la ciudad para la toma de decisiones en torno a la generaci\u00f3n de energ\u00eda renovable. El estudio complementar\u00e1 los esfuerzos realizados por el Ayuntamiento de Pamplona para el desarrollo de las energ\u00edas renovables en la ciudad e impulsar\u00e1 un crecimiento sustancial de las mismas.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Identificar espacios p\u00fablicos de temperatura extrema para adaptarlos<\/strong><\/p>\n<p>De forma paralela, el Ayuntamiento est\u00e1 identificando espacios p\u00fablicos que resultan poco confortables debido al exceso de sol o de fr\u00edo para adaptarlos y hacerlos m\u00e1s acogedores, teniendo en cuenta, sobre todo, que con el cambio clim\u00e1tico subir\u00e1n las temperaturas y cambiar\u00e1n las condiciones metereol\u00f3gicas de la ciudad.<\/p>\n<p>Esta parte del estudio se desarrollar\u00e1 de la mano de la colaboraci\u00f3n ciudadana. Para ello, se ha abierto un espacio dentro de la plataforma municipal de participaci\u00f3n <a href=\"https:\/\/erabaki.pamplona.es\/processes\/EstrategiaEnergeticaCambioClimatico\/f\/224\/meetings\/189\" target=\"_blank\" rel=\"noopener noreferrer\">ERABAKI<\/a> que permite a las personas que han identificado estos puntos en la ciudad describirlos y situarlos. Las aportaciones recibidas servir\u00e1n de base, tras su identificaci\u00f3n y an\u00e1lisis, para establecer un m\u00e9todo anal\u00edtico de medici\u00f3n y realizar propuestas de mejora futuras. De esa forma se podr\u00e1 establecer si el efecto isla de calor est\u00e1 presente en Pamplona.<\/p>\n<p>Este efecto consiste en que en la ciudad, la temperatura, especialmente durante la noche, es distinta a la de las \u00e1reas de alrededor, el extrarradio y las zonas rurales colindantes. Los factores a los que se atribuye este fen\u00f3meno son diversos: los materiales con los que est\u00e1 construida la ciudad que desprenden durante la noche lentamente el calor que captan durante el d\u00eda, los elementos que sueltan calor como climatizaciones y veh\u00edculos, o la impermeabilizaci\u00f3n de la superficie que altera la infiltraci\u00f3n y la humedad del subsuelo.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>En Pamplona no est\u00e1 constatado que se perciba el efecto isla de calor aunque s\u00ed se podr\u00edan dar condicionantes para ello en algunas zonas por los materiales de construcci\u00f3n utilizados, la exposici\u00f3n a radiaci\u00f3n solar y a vientos dominantes o la impermeabilizaci\u00f3n. Estos espacios, al ser utilizados por la ciudadan\u00eda, pueden tener condiciones t\u00e9rmicas poco adecuadas, por ser m\u00e1s fr\u00edos o c\u00e1lidos que el resto. El objetivo del estudio es identificarlos, de manera que se conozca a trav\u00e9s de esta consulta, por ejemplo, qu\u00e9 parques infantiles, patios de escuelas, zonas de paseo o espacios de estancia no resultan c\u00f3modos por este motivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dentro de la Estrategia de Transici\u00f3n Energ\u00e9tica y Cambio Clim\u00e1tico 2030 se evaluar\u00e1 el potencial de generaci\u00f3n renovable (fotovoltaica y t\u00e9rmica) de cada cubierta de la ciudad<\/p>\n","protected":false},"author":1,"featured_media":32326,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-32325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad<\/title>\n<meta name=\"description\" content=\"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad\" \/>\n<meta property=\"og:description\" content=\"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-17T15:10:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/11\/isf_rochapea_energia-renovables-paneles-solares.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad\",\"datePublished\":\"2020-11-17T15:10:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\\\/\"},\"wordCount\":986,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/isf_rochapea_energia-renovables-paneles-solares.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\\\/\",\"name\":\"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/isf_rochapea_energia-renovables-paneles-solares.jpg\",\"datePublished\":\"2020-11-17T15:10:35+00:00\",\"description\":\"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/isf_rochapea_energia-renovables-paneles-solares.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/isf_rochapea_energia-renovables-paneles-solares.jpg\",\"width\":1920,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad","description":"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/","og_locale":"es_ES","og_type":"article","og_title":"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad","og_description":"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-11-17T15:10:35+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/11\/isf_rochapea_energia-renovables-paneles-solares.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad","datePublished":"2020-11-17T15:10:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/"},"wordCount":986,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/11\/isf_rochapea_energia-renovables-paneles-solares.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/","name":"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/11\/isf_rochapea_energia-renovables-paneles-solares.jpg","datePublished":"2020-11-17T15:10:35+00:00","description":"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/11\/isf_rochapea_energia-renovables-paneles-solares.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/11\/isf_rochapea_energia-renovables-paneles-solares.jpg","width":1920,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/pamplona-esta-desarrollando-su-mapa-solar-para-identificar-el-potencial-de-generacion-energetica-renovable-de-la-ciudad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Pamplona est\u00e1 desarrollando su Mapa Solar para identificar el potencial de generaci\u00f3n energ\u00e9tica renovable de la ciudad"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/32325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=32325"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/32325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/32326"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=32325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=32325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=32325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}