{"id":32168,"date":"2020-11-02T13:13:35","date_gmt":"2020-11-02T11:13:35","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=32168"},"modified":"2020-11-02T13:13:35","modified_gmt":"2020-11-02T11:13:35","slug":"el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/","title":{"rendered":"El Ayuntamiento continuar\u00e1 ofreciendo a los centros escolares clases de bertsolarismo para el alumnado de 5\u00ba y 6\u00ba de Primaria"},"content":{"rendered":"<h5>El contrato prev\u00e9 un m\u00e1ximo de 570 horas que podr\u00edan impartir a 38 grupos de modelos D de colegios p\u00fablicos<\/h5>\n<p><!--more--><\/p>\n<p>El Ayuntamiento de Pamplona va a continuar ofreciendo a los centros escolares clases de bertsolarismo tras aprobar hoy la Junta de Gobierno Local la tercera pr\u00f3rroga del contrato con la Asociaci\u00f3n Navarra de Amigos del Bertsolarismo\/Nafarroako Bertsozale Elkartea. El gasto aprobado para este curso es de 40.000 euros, la misma cantidad que en ediciones anteriores. La iniciativa busca que el alumnado pueda conocer las t\u00e9cnicas b\u00e1sicas del bertsolarismo y trabaje la expresi\u00f3n oral.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>El programa est\u00e1 dirigido al alumnado de 5\u00ba y 6\u00ba de Primaria del modelo D de colegios p\u00fablicos de Pamplona. Est\u00e1 previsto que este curso participen diferentes clases de C.P. San Francisco I.P., C.P. Etxepare I.P., C.P. Patxi Larrainzar I.P., C.P. Mendigoiti I.P., Ikastola Amaiur, C.P. Buztintxuri I.P., C.P. Elorri I.P., Ikastola Hegoalde y C.P. Sanduzelai I.P.<\/p>\n<p>Trabajar la expresi\u00f3n oral y las destrezas comunicativas y sociales<\/p>\n<p>Cuatro profesores especialistas de la Asociaci\u00f3n de Amigos del Bertsolarismo de Navarra\/Nafarroako Bertsozale Elkartea se encargar\u00e1n de dar a conocer las nociones b\u00e1sicas del bertsolarismo y de trabajar especialmente la expresi\u00f3n oral, as\u00ed como las destrezas comunicativas y sociales. Cada grupo recibir\u00e1 el programa una vez por semana en horario lectivo a trav\u00e9s de uno de los profesores, hasta completar 15 horas.<\/p>\n<p>Se trabaja el bertsolarismo a partir de cuatro \u00e1reas: el lenguaje, la cultura, la m\u00fasica y las habilidades personales\/sociales. La base del programa lo conforman el libro \u2018Mundu bat bertso\u2019 acompa\u00f1ado de v\u00eddeos y audios y la nueva web <a href=\"http:\/\/www.bertsoikasgela.eus\" target=\"_blank\" rel=\"noopener noreferrer\">www.bertsoikasgela.eus<\/a> que sirve de biblioteca de recursos (juegos, ejercicios, bertsos\u2026) para el desarrollo de las clases.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Posibilidad de adaptar el programa seg\u00fan sea el curso escolar<\/strong><\/p>\n<p>A trav\u00e9s del programa \u2018Bertsolarismo en la ense\u00f1anza\u2019 se transmiten los principios b\u00e1sicos del bertsolarismo (historia, melod\u00edas, m\u00e9tricas, rimas\u2026) mediante ejercicios y juegos, llegando a realizar bertsos escritos e improvisados. Siempre en un entorno l\u00fadico, se profundiza en el uso del lenguaje actuando en las capacidades ling\u00fc\u00edsticas y comunicativas. Por tanto, a trav\u00e9s de los ejercicios planteados, se desarrollan multitud de competencias (citadas en el curr\u00edculum de Primaria): la oralidad, la capacidad de trabajar en grupo, la auto-confianza, el sentido cr\u00edtico, la iniciativa, el inter\u00e9s, la creatividad y la capacidad de exponer los trabajos en p\u00fablico, entre otras.<\/p>\n<p>Teniendo en cuenta la situaci\u00f3n sanitaria actual, Nafarroako Bertsozale Elkartea ha dise\u00f1ado una forma de trabajo alternativa para seguir impartiendo el programa en caso de no poder realizarlo de manera presencial. El portal Bertsoikasgela.eus pone a disposici\u00f3n del alumnado diverso material: m\u00e1s de 150 bertsos musicalizados especialmente para el p\u00fablico infantil, m\u00e1s de 150 bertsos en video de bertsolaris de primer nivel, juegos y ejercicios de lenguaje para hacer desde la pantalla, y m\u00e1s de 50 fichas para la elaboraci\u00f3n de bertsos desde casa. Esto se completar\u00e1 con el contacto directo que el profesorado del programa mantendr\u00e1 con los centros escolares para la elaboraci\u00f3n de trabajos en casa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El contrato prev\u00e9 un m\u00e1ximo de 570 horas que podr\u00edan impartir a 38 grupos de modelos D de colegios p\u00fablicos<\/p>\n","protected":false},"author":1,"featured_media":11091,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-32168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Ayuntamiento continuar\u00e1 ofreciendo a los centros escolares clases de bertsolarismo para el alumnado de 5\u00ba y 6\u00ba de Primaria<\/title>\n<meta name=\"description\" content=\"El contrato prev\u00e9 un m\u00e1ximo de 570 horas que podr\u00edan impartir a 38 grupos de modelos D de colegios p\u00fablicos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Ayuntamiento continuar\u00e1 ofreciendo a los centros escolares clases de bertsolarismo para el alumnado de 5\u00ba y 6\u00ba de Primaria\" \/>\n<meta property=\"og:description\" content=\"El contrato prev\u00e9 un m\u00e1ximo de 570 horas que podr\u00edan impartir a 38 grupos de modelos D de colegios p\u00fablicos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-02T11:13:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/Bertsoaroa-2014.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El Ayuntamiento continuar\u00e1 ofreciendo a los centros escolares clases de bertsolarismo para el alumnado de 5\u00ba y 6\u00ba de Primaria\",\"datePublished\":\"2020-11-02T11:13:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\\\/\"},\"wordCount\":562,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Bertsoaroa-2014.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\\\/\",\"name\":\"El Ayuntamiento continuar\u00e1 ofreciendo a los centros escolares clases de bertsolarismo para el alumnado de 5\u00ba y 6\u00ba de Primaria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Bertsoaroa-2014.jpg\",\"datePublished\":\"2020-11-02T11:13:35+00:00\",\"description\":\"El contrato prev\u00e9 un m\u00e1ximo de 570 horas que podr\u00edan impartir a 38 grupos de modelos D de colegios p\u00fablicos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Bertsoaroa-2014.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Bertsoaroa-2014.jpg\",\"width\":800,\"height\":532},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Ayuntamiento continuar\u00e1 ofreciendo a los centros escolares clases de bertsolarismo para el alumnado de 5\u00ba y 6\u00ba de Primaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Ayuntamiento continuar\u00e1 ofreciendo a los centros escolares clases de bertsolarismo para el alumnado de 5\u00ba y 6\u00ba de Primaria","description":"El contrato prev\u00e9 un m\u00e1ximo de 570 horas que podr\u00edan impartir a 38 grupos de modelos D de colegios p\u00fablicos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/","og_locale":"es_ES","og_type":"article","og_title":"El Ayuntamiento continuar\u00e1 ofreciendo a los centros escolares clases de bertsolarismo para el alumnado de 5\u00ba y 6\u00ba de Primaria","og_description":"El contrato prev\u00e9 un m\u00e1ximo de 570 horas que podr\u00edan impartir a 38 grupos de modelos D de colegios p\u00fablicos","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-11-02T11:13:35+00:00","og_image":[{"width":800,"height":532,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/Bertsoaroa-2014.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El Ayuntamiento continuar\u00e1 ofreciendo a los centros escolares clases de bertsolarismo para el alumnado de 5\u00ba y 6\u00ba de Primaria","datePublished":"2020-11-02T11:13:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/"},"wordCount":562,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/Bertsoaroa-2014.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/","name":"El Ayuntamiento continuar\u00e1 ofreciendo a los centros escolares clases de bertsolarismo para el alumnado de 5\u00ba y 6\u00ba de Primaria","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/Bertsoaroa-2014.jpg","datePublished":"2020-11-02T11:13:35+00:00","description":"El contrato prev\u00e9 un m\u00e1ximo de 570 horas que podr\u00edan impartir a 38 grupos de modelos D de colegios p\u00fablicos","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/Bertsoaroa-2014.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/Bertsoaroa-2014.jpg","width":800,"height":532},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-continuara-ofreciendo-a-los-centros-escolares-clases-de-bertsolarismo-para-el-alumnado-de-5o-y-6o-de-primaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El Ayuntamiento continuar\u00e1 ofreciendo a los centros escolares clases de bertsolarismo para el alumnado de 5\u00ba y 6\u00ba de Primaria"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/32168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=32168"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/32168\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/11091"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=32168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=32168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=32168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}