{"id":31819,"date":"2020-09-24T11:25:16","date_gmt":"2020-09-24T09:25:16","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=31819"},"modified":"2020-09-24T11:25:16","modified_gmt":"2020-09-24T09:25:16","slug":"cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/","title":{"rendered":"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares"},"content":{"rendered":"<h5>Ayuntamiento, Fundaci\u00f3n \u201cla Caixa\u201d y CaixaBank ponen en marcha el programa de apoyo escolar TIC TAC, coordinado por las Unidades de Barrio<\/h5>\n<p><!--more--><\/p>\n<p>Garantizar y preservar los derechos de la infancia y la adolescencia y poner remedio a la llamada \u2018brecha digital\u2019 en la actual situaci\u00f3n de pandemia por la Covid-19 son los objetivos del programa TIC TAC, de apoyo escolar a menores a trav\u00e9s de las nuevas tecnolog\u00edas, puesto en marcha por el Ayuntamiento de Pamplona, Fundaci\u00f3n \u201cla Caixa\u201d y CaixaBank. Gracias a este programa 50 familias de Pamplona con menores en situaci\u00f3n de vulnerabilidad podr\u00e1n contar con un ordenador y con conexi\u00f3n a internet para as\u00ed estudiar y hacer las tareas escolares.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>El alcalde de Pamplona, Enrique Maya, y la directora territorial Ebro de CaixaBank, Isabel Moreno, han presentado este programa \u2018TIC TAC\u2019, un ejemplo de colaboraci\u00f3n p\u00fablico \u2013 privada, que cuenta adem\u00e1s con el apoyo tecnol\u00f3gico de la empresa p\u00fablica ANIMSA. Los 50 equipos inform\u00e1ticos que se han adquirido por un importe de 15.000 euros los ha aportado Fundaci\u00f3n \u201cla Caixa\u201d a trav\u00e9s de la Acci\u00f3n Social de CaixaBank. El programa se pone en marcha de forma coordinada con el Departamento de Educaci\u00f3n del Gobierno de Navarra para que pueda complementarse con otras iniciativas que se llevan a cabo desde ese departamento.<\/p>\n<p>La participaci\u00f3n en este programa se coordinar\u00e1 desde las Unidades de Barrio, con la colaboraci\u00f3n de los centros escolares, que identificar\u00e1n a la poblaci\u00f3n que carezca de estos recursos y que necesite del uso de las TIC para el mantenimiento de las redes de educaci\u00f3n, socializaci\u00f3n y seguimiento de su desarrollo escolar. Se atender\u00e1 a criterios como el de familias numerosas, situaciones de riesgo y\/o vulnerabilidad, unidades familiares que posean alg\u00fan tipo de acceso a internet, familias que hayan agotado otras v\u00edas de concesi\u00f3n de equipos por medio del Departamento de Educaci\u00f3n o para casos de intervenci\u00f3n educativa. En este mes de septiembre se est\u00e1 procediendo a la detecci\u00f3n de las necesidades m\u00e1s urgentes para, ya en octubre, llevar a cabo el reparto de los equipos.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Pr\u00e9stamo hasta final de curso<\/strong><\/p>\n<p>Los equipos inform\u00e1ticos se ceder\u00e1n en formato de pr\u00e9stamo por medio de un contrato de uso y con una fianza simb\u00f3lica para garantizar su cuidado y la corresponsabilidad de las familias en su utilizaci\u00f3n. Se ha determinado un reparto en cada unidad de barrio para intentar mantener una proporcionalidad respecto a las atenciones que se llevan a cabo en esos centros, aunque tambi\u00e9n se prev\u00e9n equipos para cubrir otras necesidades que puedan surgir. Formar parte de este programa TIC TAC conlleva el compromiso de acudir a la sesi\u00f3n informativa que se desarrollar\u00e1 para explicar el uso de esos equipos inform\u00e1ticos y su devoluci\u00f3n en buen estado una vez que acabe el curso escolar.<\/p>\n<p>Adem\u00e1s, se contar\u00e1 para ese desarrollo del programa con un servicio de voluntariado, que estar\u00e1 compuesto por j\u00f3venes que se encargar\u00e1n de tutelar a los menores que participen en TIC TAC. A lo largo del curso escolar se realizar\u00e1 una labor de seguimiento y una vez que concluyan las clases har\u00e1 una evaluaci\u00f3n del funcionamiento del programa. La idea del programa es que pueda extenderse durante m\u00e1s cursos escolares y que sea, adem\u00e1s, el germen de otros proyectos relacionados con la brecha digital y el derecho a la educaci\u00f3n infantil y adolescente.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Cubrir necesidades en el actual contexto de la Covid-19<\/strong><\/p>\n<p>En el actual contexto derivado de la Covid-19, tras la experiencia del confinamiento de marzo y abril y con los protocolos actuales en los centros escolares, la educaci\u00f3n de los menores y los j\u00f3venes pasa, necesariamente, por tener un acceso a internet seguro y por disponer de los dispositivos adecuados en condiciones de seguridad y eficiencia. La \u2018brecha digital\u2019 es un hecho, sobre todo en la poblaci\u00f3n infantil en situaci\u00f3n de vulnerabilidad. De ah\u00ed, la cesi\u00f3n de estos ordenadores como elementos para favorecer el derecho a una educaci\u00f3n de calidad y el acceso a herramientas y metodolog\u00edas digitales.<\/p>\n<p>Consistorio, Fundaci\u00f3n \u201cla Caixa\u201d y CaixaBank consideran una prioridad garantizar y preservar los derechos de la infancia y la adolescencia. El proyecto se enmarca, adem\u00e1s, en los Objetivos de Desarrollo Sostenible de la Agenda 2030. En esta l\u00ednea, el Ayuntamiento de Pamplona est\u00e1 desarrollando el I Plan de Atenci\u00f3n a la Infancia y la Adolescencia que prioriza la atenci\u00f3n, la seguridad y la garant\u00eda de derechos de los menores y adolescentes. Asimismo, Pamplona pertenece a la Red de Ciudades Amigas de la Infancia, promovida por UNICEF.<\/p>\n<p>Gracias a su capilaridad territorial, la red de oficinas de CaixaBank puede apoyar a la Fundaci\u00f3n \u201cla Caixa\u201d en su labor social, detectando necesidades de entidades sociales locales y canalizando una parte del presupuesto de la Fundaci\u00f3n. En 2019, el 92% de las oficinas del banco apoyaron alg\u00fan proyecto social e hicieron posible que miles de peque\u00f1as y medianas entidades sociales solidarias pudieran acceder a ayudas econ\u00f3micas para sacar adelante sus programas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayuntamiento, Fundaci\u00f3n \u201cla Caixa\u201d y CaixaBank ponen en marcha el programa de apoyo escolar TIC TAC, coordinado por las Unidades de Barrio<\/p>\n","protected":false},"author":1,"featured_media":31820,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-31819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares<\/title>\n<meta name=\"description\" content=\"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares\" \/>\n<meta property=\"og:description\" content=\"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-24T09:25:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/alcalde_1mb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1608\" \/>\n\t<meta property=\"og:image:height\" content=\"1206\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares\",\"datePublished\":\"2020-09-24T09:25:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\\\/\"},\"wordCount\":901,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/alcalde_1mb.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\\\/\",\"name\":\"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/alcalde_1mb.jpg\",\"datePublished\":\"2020-09-24T09:25:16+00:00\",\"description\":\"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/alcalde_1mb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/alcalde_1mb.jpg\",\"width\":1608,\"height\":1206},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares","description":"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/","og_locale":"es_ES","og_type":"article","og_title":"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares","og_description":"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-09-24T09:25:16+00:00","og_image":[{"width":1608,"height":1206,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/alcalde_1mb.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares","datePublished":"2020-09-24T09:25:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/"},"wordCount":901,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/alcalde_1mb.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/","name":"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/alcalde_1mb.jpg","datePublished":"2020-09-24T09:25:16+00:00","description":"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/alcalde_1mb.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/alcalde_1mb.jpg","width":1608,"height":1206},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cincuenta-familias-con-menores-en-situacion-de-vulnerabilidad-accederan-a-ordenadores-con-conexion-a-internet-para-estudiar-y-desarrollar-sus-tareas-escolares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Cincuenta familias con menores en situaci\u00f3n de vulnerabilidad acceder\u00e1n a ordenadores con conexi\u00f3n a internet para estudiar y desarrollar sus tareas escolares"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/31819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=31819"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/31819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/31820"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=31819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=31819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=31819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}