{"id":31808,"date":"2020-09-23T16:22:35","date_gmt":"2020-09-23T14:22:35","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=31808"},"modified":"2020-09-23T16:35:40","modified_gmt":"2020-09-23T14:35:40","slug":"comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/","title":{"rendered":"Comienza el derribo del edificio del Grupo Oscoz 12-14 en Rochapea, que generar\u00e1 una nueva plaza peatonal para el barrio"},"content":{"rendered":"<h5>Se prev\u00e9 que el inmueble quede demolido esta semana y durante la que viene se proceda al desescombro del espacio<\/h5>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/www.laguiadepamplona.es\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.23_derribo_grupo_oscoz2_0.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-31810\" src=\"https:\/\/www.laguiadepamplona.es\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.23_derribo_grupo_oscoz2_0-169x300.jpg\" alt=\"\" width=\"169\" height=\"300\" srcset=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.23_derribo_grupo_oscoz2_0-169x300.jpg 169w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.23_derribo_grupo_oscoz2_0-384x682.jpg 384w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.23_derribo_grupo_oscoz2_0-768x1365.jpg 768w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.23_derribo_grupo_oscoz2_0-864x1536.jpg 864w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.23_derribo_grupo_oscoz2_0-640x1138.jpg 640w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.23_derribo_grupo_oscoz2_0.jpg 1080w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a>Para finales de esta semana se prev\u00e9 que el edificio del Grupo Oscoz 12 \u2013 14 est\u00e9 ya derribado. Tras los trabajos previos realizados durante el lunes y el martes, hoy mi\u00e9rcoles ha comenzado la demolici\u00f3n del inmueble. La semana que viene se proceder\u00e1 al desescombro de una zona, que se convertir\u00e1 en plaza peatonal para el barrio. El edificio, de planta baja y tres alturas, data de 1917, no estaba habitado, se encontraba fuera de ordenaci\u00f3n y ten\u00eda un alto grado de deterioro.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>Para llevar a cabo estos trabajos se han tomado las necesarias medidas de prevenci\u00f3n, dada la proximidad de otros inmuebles a la zona del derribo. Se ha colocado, por ejemplo, un andamio perimetral con una red tupida exterior para evitar la ca\u00edda de elementos que puedan impactar en esos edificios y se busca minimizar la afecci\u00f3n del polvo del derribo mediante el riego y una valla de dos metros de altura. El presupuesto del derribo es de 143.000 euros, despu\u00e9s del incremento generado por la aparici\u00f3n de fibrocemento y escombro mezclado, que necesitan de tratamientos especiales. El derribo se va a llevar a cabo por medios manuales, elemento a elemento, y por medios mec\u00e1nicos, derribando hacia dentro del edificio.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>Una vez generado el solar tras el derribo del inmueble, se llevar\u00e1n a cabo los trabajos de urbanizaci\u00f3n de la zona para crear una plaza peatonal. Se revisar\u00e1n las instalaciones soterradas y se pondr\u00e1n nuevas arquetas y conductos para que se oculten las infraestructuras a\u00e9reas existentes de telefon\u00eda y electricidad. El desnivel entre la calle Joaqu\u00edn Beunza y la nueva plaza se salvar\u00e1 mediante escaleras y una rampa. La nueva plaza se completar\u00e1 con mobiliario urbano, bancos y una renovaci\u00f3n completa de la iluminaci\u00f3n eliminando las farolas en las fachadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se prev\u00e9 que el inmueble quede demolido esta semana y durante la que viene se proceda al desescombro del espacio<\/p>\n","protected":false},"author":1,"featured_media":31809,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-31808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comienza el derribo del edificio del Grupo Oscoz 12-14 en Rochapea, que generar\u00e1 una nueva plaza peatonal para el barrio<\/title>\n<meta name=\"description\" content=\"Se prev\u00e9 que el inmueble quede demolido esta semana y durante la que viene se proceda al desescombro del espacio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comienza el derribo del edificio del Grupo Oscoz 12-14 en Rochapea, que generar\u00e1 una nueva plaza peatonal para el barrio\" \/>\n<meta property=\"og:description\" content=\"Se prev\u00e9 que el inmueble quede demolido esta semana y durante la que viene se proceda al desescombro del espacio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-23T14:22:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-23T14:35:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.23_derribo_grupo_oscoz2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1836\" \/>\n\t<meta property=\"og:image:height\" content=\"1140\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"Comienza el derribo del edificio del Grupo Oscoz 12-14 en Rochapea, que generar\u00e1 una nueva plaza peatonal para el barrio\",\"datePublished\":\"2020-09-23T14:22:35+00:00\",\"dateModified\":\"2020-09-23T14:35:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\\\/\"},\"wordCount\":347,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20.09.23_derribo_grupo_oscoz2.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\\\/\",\"name\":\"Comienza el derribo del edificio del Grupo Oscoz 12-14 en Rochapea, que generar\u00e1 una nueva plaza peatonal para el barrio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20.09.23_derribo_grupo_oscoz2.jpg\",\"datePublished\":\"2020-09-23T14:22:35+00:00\",\"dateModified\":\"2020-09-23T14:35:40+00:00\",\"description\":\"Se prev\u00e9 que el inmueble quede demolido esta semana y durante la que viene se proceda al desescombro del espacio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20.09.23_derribo_grupo_oscoz2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20.09.23_derribo_grupo_oscoz2.jpg\",\"width\":1836,\"height\":1140},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comienza el derribo del edificio del Grupo Oscoz 12-14 en Rochapea, que generar\u00e1 una nueva plaza peatonal para el barrio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comienza el derribo del edificio del Grupo Oscoz 12-14 en Rochapea, que generar\u00e1 una nueva plaza peatonal para el barrio","description":"Se prev\u00e9 que el inmueble quede demolido esta semana y durante la que viene se proceda al desescombro del espacio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/","og_locale":"es_ES","og_type":"article","og_title":"Comienza el derribo del edificio del Grupo Oscoz 12-14 en Rochapea, que generar\u00e1 una nueva plaza peatonal para el barrio","og_description":"Se prev\u00e9 que el inmueble quede demolido esta semana y durante la que viene se proceda al desescombro del espacio","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-09-23T14:22:35+00:00","article_modified_time":"2020-09-23T14:35:40+00:00","og_image":[{"width":1836,"height":1140,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.23_derribo_grupo_oscoz2.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"Comienza el derribo del edificio del Grupo Oscoz 12-14 en Rochapea, que generar\u00e1 una nueva plaza peatonal para el barrio","datePublished":"2020-09-23T14:22:35+00:00","dateModified":"2020-09-23T14:35:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/"},"wordCount":347,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.23_derribo_grupo_oscoz2.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/","name":"Comienza el derribo del edificio del Grupo Oscoz 12-14 en Rochapea, que generar\u00e1 una nueva plaza peatonal para el barrio","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.23_derribo_grupo_oscoz2.jpg","datePublished":"2020-09-23T14:22:35+00:00","dateModified":"2020-09-23T14:35:40+00:00","description":"Se prev\u00e9 que el inmueble quede demolido esta semana y durante la que viene se proceda al desescombro del espacio","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.23_derribo_grupo_oscoz2.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.23_derribo_grupo_oscoz2.jpg","width":1836,"height":1140},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/comienza-el-derribo-del-edificio-del-grupo-oscoz-12-14-en-rochapea-que-generara-una-nueva-plaza-peatonal-para-el-barrio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Comienza el derribo del edificio del Grupo Oscoz 12-14 en Rochapea, que generar\u00e1 una nueva plaza peatonal para el barrio"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/31808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=31808"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/31808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/31809"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=31808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=31808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=31808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}