{"id":31748,"date":"2020-09-17T17:26:19","date_gmt":"2020-09-17T15:26:19","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=31748"},"modified":"2020-09-17T17:26:19","modified_gmt":"2020-09-17T15:26:19","slug":"el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/","title":{"rendered":"El Consistorio ofrece a los centros escolares \u2018Educ\u00e1ndonos en sostenibilidad\u2019 con salidas a parques para \u2018Sentir naturaleza\u2019 y visitas al Museo de Educaci\u00f3n Ambiental y su exterior"},"content":{"rendered":"<h5>El programa tambi\u00e9n incluye actividades <em>online<\/em> y pr\u00e9stamos de recursos y materiales did\u00e1cticos para utilizar en las aulas<\/h5>\n<p><!--more--><\/p>\n<p>El Ayuntamiento de Pamplona ha puesto en marcha con el inicio del curso el programa \u2018Educ\u00e1ndonos en la sostenibilidad\u2019 que incluye actividades guiadas en el Museo de Educaci\u00f3n Ambiental y en su exterior y la oportunidad de acercarse a las zonas verdes cercanas a los centros escolares con el programa \u2018Sentir naturaleza\u2019. Otras opciones son las actividades online, el pr\u00e9stamo de material para hacer actividades en los centros, la Secci\u00f3n Joven del Festival Ecozine o participar en \u2018Haz tuyo el Museo con tu centro escolar\u2019.<\/p>\n<p>En \u2018Educ\u00e1ndonos en la Sostenibilidad\u2019, el Equipo de Educaci\u00f3n Ambiental municipal quiere, a trav\u00e9s de experiencias lo m\u00e1s vivenciales posibles, acercar al alumnado a la realidad del entorno que les rodea, para su disfrute, conocimiento, puesta en valor e impulso de una relaci\u00f3n m\u00e1s respetuosa y cuidadosa. Este curso escolar se ha adaptado la oferta de actividades a las circunstancias sanitarias cambiantes para garantizar en todo momento la seguridad.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Actividades preferentemente en el exterior del Museo de Educaci\u00f3n Ambiental<\/strong><\/p>\n<p>Como en a\u00f1os anteriores continuar\u00e1 el programa presencial en el equipamiento del Museo de Educaci\u00f3n Ambiental aunque, este curso, las actividades se realizar\u00e1n preferentemente en el exterior, en el parque de Aranzadi o el patio, o en espacios amplios como la Sala de Exposiciones. Se tratar\u00e1n diferentes \u00e1mbitos del entorno como la biodiversidad, los residuos, el consumo o el cambio clim\u00e1tico. Dirigido a las etapas de Infantil, Primaria, Secundaria y Formaci\u00f3n Profesional de cualquier centro educativo de Navarra, se desarrollar\u00e1 los martes y los jueves en horario de ma\u00f1ana a lo largo de todo el curso escolar.<\/p>\n<p>El programa se llevar\u00e1 a cabo en una constante adaptaci\u00f3n a las medidas sanitarias que se vayan marcando, con la intenci\u00f3n de poder ofrecerlo en las mismas condiciones en las que se ha venido llevando a cabo desde hace m\u00e1s de una d\u00e9cada.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Nueva propuesta para aprender a \u2018Sentir naturaleza\u2019<\/strong><\/p>\n<p>El Ayuntamiento ha organizado por primera vez el programa \u2018Sentir naturaleza\u2019 con el objetivo de facilitar el trabajo sobre aspectos de sensibilizaci\u00f3n ambiental de un modo seguro teniendo en cuenta la situaci\u00f3n sanitaria actual. Ha optado por favorecer la realizaci\u00f3n de actividades en espacios verdes cercanos a los centros educativos que posibiliten un mayor bienestar f\u00edsico y social por la reconexi\u00f3n con la naturaleza urbana de Pamplona.<\/p>\n<p>Son actividades guiadas en zonas abiertas donde el alumnado descubrir\u00e1, de otra manera, los parques y jardines cercanos en los que vivir su d\u00eda a d\u00eda. Pueden apuntarse centros escolares de Infantil y Primaria de Pamplona para una actividad que se desarrollar\u00e1 durante este primer trimestre del curso 2020\/21 de martes a jueves en horario de ma\u00f1ana. Existir\u00e1 la opci\u00f3n de llevar a cabo la propuesta de manera aut\u00f3noma por el profesorado, las propias familias o por otros centros escolares no municipales.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Opciones de actividades en el propio centro o desde casa<\/strong><\/p>\n<p>Otras propuestas del programa son las actividades relacionadas con la sostenibilidad que se pueden realizar en el centro educativo o desde casa. Dirigido a todas las etapas educativas de cualquier centro escolar se pueden descargar desde <a href=\"http:\/\/www.educacionambiental.pamplona.es\" target=\"_blank\" rel=\"noopener noreferrer\">www.educacionambiental.pamplona.es<\/a>.<\/p>\n<p>Adem\u00e1s, el Ayuntamiento posibilita otro tipo de actividades y recursos que complementan la oferta educativa. As\u00ed, propone actividades dentro del propio centro a trav\u00e9s del uso de los materiales viajeros, un conjunto de recursos en pr\u00e9stamo adecuados para diferentes niveles educativos sobre la energ\u00eda, el cambio clim\u00e1tico, el ruido, la huerta escolar y el agua. Por ejemplo, hay aparatos de medida o fichas de aplicaci\u00f3n curricular.<\/p>\n<p>Los centros educativos tienen a su disposici\u00f3n, desde el 2017, la Secci\u00f3n Educativa del Festival Ecozine de cine y medio ambiente. Est\u00e1 pensado para sensibilizar al alumnado de Secundaria sobre los problemas ambientales a trav\u00e9s de materiales audiovisuales. Se desarrollar\u00e1 a finales del segundo trimestre escolar y se ir\u00e1 adaptando a la situaci\u00f3n sanitaria para ofrecer el formato que mejor se adapte a las circunstancias del momento.<\/p>\n<p>Por \u00faltimo, a trav\u00e9s de la iniciativa \u2018Haz tuyo el Museo con tu centro escolar\u2019, se ofrece a los centros la opci\u00f3n de dar a conocer, en las instalaciones del Museo de Educaci\u00f3n Ambiental, un proyecto que tenga que ver con alg\u00fan tema ambiental. Se ofrece el espacio as\u00ed como sus medios de difusi\u00f3n para cualquier iniciativa, trabajo, exposici\u00f3n, charla, etc.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Actividades gratuitas en castellano y en euskera<\/strong><\/p>\n<p>Todas las actividades son gratuitas aunque es obligatoria hacer reserva previa, excepto en las actividades online. Las propuestas est\u00e1n adaptadas al ciclo educativo correspondiente, pudi\u00e9ndose realizar en dos idiomas, castellano y euskera. Las reservas se realizan a trav\u00e9s de <a href=\"mailto:museoambiental@pamplona.es\">museoambiental@pamplona.es<\/a> y el tel\u00e9fono 948 420 984. Una vez realizada la inscripci\u00f3n, el Equipo de Educaci\u00f3n Ambiental trabajar\u00e1 para ajustar la actividad a las necesidades del grupo y a la situaci\u00f3n sanitaria del momento.<\/p>\n<p>La oferta completa est\u00e1 en la p\u00e1gina web municipal <a href=\"http:\/\/www.educacionambiental.pamplona.es\" target=\"_blank\" rel=\"noopener noreferrer\">www.educacionambiental.pamplona.es<\/a>, pudiendo descargarse en <a href=\"http:\/\/educacionambiental.pamplona.es\/wp-content\/uploads\/2020\/09\/Educandonos_Sostenibilidad_20-21.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">castellano<\/a> y en <a href=\"http:\/\/educacionambiental.pamplona.es\/wp-content\/uploads\/2020\/09\/Educandonos_Sostenibilidad_20-21.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">euskera<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El programa tambi\u00e9n incluye actividades online y pr\u00e9stamos de recursos y materiales did\u00e1cticos para utilizar en las aulas<\/p>\n","protected":false},"author":1,"featured_media":11071,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-31748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Consistorio ofrece a los centros escolares \u2018Educ\u00e1ndonos en sostenibilidad\u2019 con salidas a parques para \u2018Sentir naturaleza\u2019 y visitas al Museo de Educaci\u00f3n Ambiental y su exterior<\/title>\n<meta name=\"description\" content=\"El programa tambi\u00e9n incluye actividades online y pr\u00e9stamos de recursos y materiales did\u00e1cticos para utilizar en las aulas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Consistorio ofrece a los centros escolares \u2018Educ\u00e1ndonos en sostenibilidad\u2019 con salidas a parques para \u2018Sentir naturaleza\u2019 y visitas al Museo de Educaci\u00f3n Ambiental y su exterior\" \/>\n<meta property=\"og:description\" content=\"El programa tambi\u00e9n incluye actividades online y pr\u00e9stamos de recursos y materiales did\u00e1cticos para utilizar en las aulas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-17T15:26:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/Museo-Educacion-Ambiental-Pamplona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"627\" \/>\n\t<meta property=\"og:image:height\" content=\"352\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El Consistorio ofrece a los centros escolares \u2018Educ\u00e1ndonos en sostenibilidad\u2019 con salidas a parques para \u2018Sentir naturaleza\u2019 y visitas al Museo de Educaci\u00f3n Ambiental y su exterior\",\"datePublished\":\"2020-09-17T15:26:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\\\/\"},\"wordCount\":907,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Museo-Educacion-Ambiental-Pamplona.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\\\/\",\"name\":\"El Consistorio ofrece a los centros escolares \u2018Educ\u00e1ndonos en sostenibilidad\u2019 con salidas a parques para \u2018Sentir naturaleza\u2019 y visitas al Museo de Educaci\u00f3n Ambiental y su exterior\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Museo-Educacion-Ambiental-Pamplona.jpg\",\"datePublished\":\"2020-09-17T15:26:19+00:00\",\"description\":\"El programa tambi\u00e9n incluye actividades online y pr\u00e9stamos de recursos y materiales did\u00e1cticos para utilizar en las aulas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Museo-Educacion-Ambiental-Pamplona.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Museo-Educacion-Ambiental-Pamplona.jpg\",\"width\":627,\"height\":352},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Consistorio ofrece a los centros escolares \u2018Educ\u00e1ndonos en sostenibilidad\u2019 con salidas a parques para \u2018Sentir naturaleza\u2019 y visitas al Museo de Educaci\u00f3n Ambiental y su exterior\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Consistorio ofrece a los centros escolares \u2018Educ\u00e1ndonos en sostenibilidad\u2019 con salidas a parques para \u2018Sentir naturaleza\u2019 y visitas al Museo de Educaci\u00f3n Ambiental y su exterior","description":"El programa tambi\u00e9n incluye actividades online y pr\u00e9stamos de recursos y materiales did\u00e1cticos para utilizar en las aulas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/","og_locale":"es_ES","og_type":"article","og_title":"El Consistorio ofrece a los centros escolares \u2018Educ\u00e1ndonos en sostenibilidad\u2019 con salidas a parques para \u2018Sentir naturaleza\u2019 y visitas al Museo de Educaci\u00f3n Ambiental y su exterior","og_description":"El programa tambi\u00e9n incluye actividades online y pr\u00e9stamos de recursos y materiales did\u00e1cticos para utilizar en las aulas","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-09-17T15:26:19+00:00","og_image":[{"width":627,"height":352,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/Museo-Educacion-Ambiental-Pamplona.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El Consistorio ofrece a los centros escolares \u2018Educ\u00e1ndonos en sostenibilidad\u2019 con salidas a parques para \u2018Sentir naturaleza\u2019 y visitas al Museo de Educaci\u00f3n Ambiental y su exterior","datePublished":"2020-09-17T15:26:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/"},"wordCount":907,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/Museo-Educacion-Ambiental-Pamplona.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/","name":"El Consistorio ofrece a los centros escolares \u2018Educ\u00e1ndonos en sostenibilidad\u2019 con salidas a parques para \u2018Sentir naturaleza\u2019 y visitas al Museo de Educaci\u00f3n Ambiental y su exterior","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/Museo-Educacion-Ambiental-Pamplona.jpg","datePublished":"2020-09-17T15:26:19+00:00","description":"El programa tambi\u00e9n incluye actividades online y pr\u00e9stamos de recursos y materiales did\u00e1cticos para utilizar en las aulas","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/Museo-Educacion-Ambiental-Pamplona.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/Museo-Educacion-Ambiental-Pamplona.jpg","width":627,"height":352},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-consistorio-ofrece-a-los-centros-escolares-educandonos-en-sostenibilidad-con-salidas-a-parques-para-sentir-naturaleza-y-visitas-al-museo-de-educacion-ambiental-y\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El Consistorio ofrece a los centros escolares \u2018Educ\u00e1ndonos en sostenibilidad\u2019 con salidas a parques para \u2018Sentir naturaleza\u2019 y visitas al Museo de Educaci\u00f3n Ambiental y su exterior"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/31748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=31748"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/31748\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/11071"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=31748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=31748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=31748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}