{"id":31687,"date":"2020-09-11T12:09:31","date_gmt":"2020-09-11T10:09:31","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=31687"},"modified":"2020-09-11T12:09:31","modified_gmt":"2020-09-11T10:09:31","slug":"el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/","title":{"rendered":"El Ayuntamiento renueva su convenio de colaboraci\u00f3n con Cruz Roja poniendo el foco en la colaboraci\u00f3n en acciones de lucha contra la pandemia"},"content":{"rendered":"<h5>Con una aportaci\u00f3n de 30.000 euros, el acuerdo tendr\u00e1 vigencia hasta que finalice el presente a\u00f1o<\/h5>\n<p><!--more--><\/p>\n<p>El Ayuntamiento de Pamplona y la Asamblea Local de la capital de Cruz Roja han renovado su acuerdo de colaboraci\u00f3n, extendiendo su vinculaci\u00f3n hasta el final del presente a\u00f1o con una aportaci\u00f3n por parte del consistorio de 30.000 euros. En el encuentro en el que se ha firmado el convenio han participado el alcalde de Pamplona, Enrique Maya; el concejal delegado de Seguridad Ciudadana, Javier Labairu; y la presidenta de la Asamblea Local de Cruz Roja en Pamplona, Mercedes Ruiz de Galarreta. El objeto del nuevo acuerdo es fomentar una mayor protecci\u00f3n para la ciudadan\u00eda de Pamplona, as\u00ed como la promoci\u00f3n del voluntariado que participe en las labores de Protecci\u00f3n Civil, poniendo especial atenci\u00f3n en las actuaciones que se deriven de las medidas a adoptar para combatir la pandemia generada por la Covid-19.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>Cruz Roja Asamblea Local de Pamplona participar\u00e1 en el presente a\u00f1o en los Planes de Protecci\u00f3n Civil del Ayuntamiento de Pamplona y en los dispositivos preventivos y de actuaci\u00f3n para combatir la pandemia generada por la Covid-19, realizando las funciones que en ellos se le asignen. En aquellas situaciones de emergencia no recogidas en Planes de Protecci\u00f3n Civil, o en procedimientos operativos no establecidos, Cruz Roja Asamblea Local de Pamplona se compromete a participar con todos los recursos materiales y humanos recogidos en el convenio de colaboraci\u00f3n, desarrollando sus actuaciones bajo las \u00f3rdenes de sus mandos naturales que atender\u00e1n las indicaciones que les sean transmitidas por personal de Protecci\u00f3n Civil del Ayuntamiento de Pamplona.<\/p>\n<p>Adem\u00e1s de en los planes de Protecci\u00f3n Civil, Cruz Roja Asamblea Local de Pamplona se compromete con la firma de este convenio a colaborar con el Ayuntamiento de Pamplona en eventos y actuaciones organizados a lo largo del a\u00f1o. As\u00ed, participar\u00e1n por ejemplo en marchas ciclistas y actividades deportivas en la v\u00eda p\u00fablica; la cabalgata de Reyes Magos, procesiones y otros desfiles con necesidad de control y seguridad; y ferias organizadas por el consistorio.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Cruz Roja pone sus recursos en Pamplona a disposici\u00f3n del Ayuntamiento<\/strong><\/p>\n<p>Con la firma del convenio con el Consistorio, Cruz Roja Asamblea Local de Pamplona, se compromete a adecuar la organizaci\u00f3n de los medios humanos y materiales de su base en la capital a las tareas que tiene asignadas en los planes de Protecci\u00f3n Civil aprobados por el Ayuntamiento de Pamplona, as\u00ed como a la atenci\u00f3n de otras necesidades sanitarias en eventos y actuaciones.<\/p>\n<p>Para el cumplimiento de lo establecido en el presente convenio, Cruz Roja Asamblea Local de Pamplona, dispondr\u00e1 permanentemente de personal localizable para intervenci\u00f3n en emergencias. En los turnos con disponibilidad de voluntariado, Cruz Roja mantendr\u00e1 activada la Base de Pamplona para salida y actuaci\u00f3n inmediata. Del mismo modo, Cruz Roja Asamblea Local de Pamplona cuenta con personal y material en diversos puntos de la geograf\u00eda navarra, que podr\u00edan ser desplazados a Pamplona en un momento de necesidad.<\/p>\n<p>En virtud del convenio suscrito, el Ayuntamiento de Pamplona pagar\u00e1 a Cruz Roja Asamblea Local de Pamplona en el a\u00f1o 2020 treinta mil euros. Un 75% se pagar\u00e1 a los treinta d\u00edas de la firma del convenio y el 25% restante al finalizar el a\u00f1o. Esta cantidad se destinar\u00e1 a la atenci\u00f3n de gastos de mantenimiento gen\u00e9rico de la entidad. El convenio tendr\u00e1 vigencia hasta que finalice el presente a\u00f1o, y a lo largo del pr\u00f3ximo mes de enero se presentar\u00e1 una memoria con las actividades realizadas.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una aportaci\u00f3n de 30.000 euros, el acuerdo tendr\u00e1 vigencia hasta que finalice el presente a\u00f1o<\/p>\n","protected":false},"author":1,"featured_media":31688,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-31687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Ayuntamiento renueva su convenio de colaboraci\u00f3n con Cruz Roja poniendo el foco en la colaboraci\u00f3n en acciones de lucha contra la pandemia<\/title>\n<meta name=\"description\" content=\"Con una aportaci\u00f3n de 30.000 euros, el acuerdo tendr\u00e1 vigencia hasta que finalice el presente a\u00f1o\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Ayuntamiento renueva su convenio de colaboraci\u00f3n con Cruz Roja poniendo el foco en la colaboraci\u00f3n en acciones de lucha contra la pandemia\" \/>\n<meta property=\"og:description\" content=\"Con una aportaci\u00f3n de 30.000 euros, el acuerdo tendr\u00e1 vigencia hasta que finalice el presente a\u00f1o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-11T10:09:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.11.convenio-cruz-roja.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El Ayuntamiento renueva su convenio de colaboraci\u00f3n con Cruz Roja poniendo el foco en la colaboraci\u00f3n en acciones de lucha contra la pandemia\",\"datePublished\":\"2020-09-11T10:09:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\\\/\"},\"wordCount\":635,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20.09.11.convenio-cruz-roja.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\\\/\",\"name\":\"El Ayuntamiento renueva su convenio de colaboraci\u00f3n con Cruz Roja poniendo el foco en la colaboraci\u00f3n en acciones de lucha contra la pandemia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20.09.11.convenio-cruz-roja.jpg\",\"datePublished\":\"2020-09-11T10:09:31+00:00\",\"description\":\"Con una aportaci\u00f3n de 30.000 euros, el acuerdo tendr\u00e1 vigencia hasta que finalice el presente a\u00f1o\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20.09.11.convenio-cruz-roja.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20.09.11.convenio-cruz-roja.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"A* Jes\u00fas Garzaron F* 2020_09_10 T* Firma de convenio con Cruz Roja L* Ayuntamiento de Pamplona\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Ayuntamiento renueva su convenio de colaboraci\u00f3n con Cruz Roja poniendo el foco en la colaboraci\u00f3n en acciones de lucha contra la pandemia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Ayuntamiento renueva su convenio de colaboraci\u00f3n con Cruz Roja poniendo el foco en la colaboraci\u00f3n en acciones de lucha contra la pandemia","description":"Con una aportaci\u00f3n de 30.000 euros, el acuerdo tendr\u00e1 vigencia hasta que finalice el presente a\u00f1o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/","og_locale":"es_ES","og_type":"article","og_title":"El Ayuntamiento renueva su convenio de colaboraci\u00f3n con Cruz Roja poniendo el foco en la colaboraci\u00f3n en acciones de lucha contra la pandemia","og_description":"Con una aportaci\u00f3n de 30.000 euros, el acuerdo tendr\u00e1 vigencia hasta que finalice el presente a\u00f1o","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-09-11T10:09:31+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.11.convenio-cruz-roja.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El Ayuntamiento renueva su convenio de colaboraci\u00f3n con Cruz Roja poniendo el foco en la colaboraci\u00f3n en acciones de lucha contra la pandemia","datePublished":"2020-09-11T10:09:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/"},"wordCount":635,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.11.convenio-cruz-roja.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/","name":"El Ayuntamiento renueva su convenio de colaboraci\u00f3n con Cruz Roja poniendo el foco en la colaboraci\u00f3n en acciones de lucha contra la pandemia","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.11.convenio-cruz-roja.jpg","datePublished":"2020-09-11T10:09:31+00:00","description":"Con una aportaci\u00f3n de 30.000 euros, el acuerdo tendr\u00e1 vigencia hasta que finalice el presente a\u00f1o","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.11.convenio-cruz-roja.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/09\/20.09.11.convenio-cruz-roja.jpg","width":1920,"height":1280,"caption":"A* Jes\u00fas Garzaron F* 2020_09_10 T* Firma de convenio con Cruz Roja L* Ayuntamiento de Pamplona"},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-renueva-su-convenio-de-colaboracion-con-cruz-roja-poniendo-el-foco-en-la-colaboracion-en-acciones-de-lucha-contra-la-pandemia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El Ayuntamiento renueva su convenio de colaboraci\u00f3n con Cruz Roja poniendo el foco en la colaboraci\u00f3n en acciones de lucha contra la pandemia"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/31687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=31687"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/31687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/31688"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=31687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=31687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=31687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}