{"id":31598,"date":"2020-09-02T17:02:43","date_gmt":"2020-09-02T15:02:43","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=31598"},"modified":"2020-09-02T17:16:56","modified_gmt":"2020-09-02T15:16:56","slug":"el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/","title":{"rendered":"El Festival Pim Pam Ville 2020 se celebra este fin de semana en la Ciudadela con una apuesta por grupos nacionales de rock &#038; roll con toques de m\u00fasica americana"},"content":{"rendered":"<h5>Bifannah, J\u00b4Aime, Pelo Mono, The Limboos, Serpiente, Adi\u00f3s Amores, Melenas e Hinds componen el cartel que ha adaptado horarios a la situaci\u00f3n<\/h5>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/www.laguiadepamplona.es\/actualidad\/wp-content\/uploads\/2020\/08\/20.08.05_Pim_Pam_Ville.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.laguiadepamplona.es\/actualidad\/wp-content\/uploads\/2020\/08\/20.08.05_Pim_Pam_Ville-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" class=\"alignleft size-medium wp-image-31293\" srcset=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/08\/20.08.05_Pim_Pam_Ville-212x300.jpg 212w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/08\/20.08.05_Pim_Pam_Ville-482x682.jpg 482w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/08\/20.08.05_Pim_Pam_Ville-768x1086.jpg 768w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/08\/20.08.05_Pim_Pam_Ville-640x905.jpg 640w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/08\/20.08.05_Pim_Pam_Ville.jpg 1061w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a>El Festival Pim Pam Ville 2020, que se va a celebrar\u00e1 el fin de semana en la Ciudadela, ha apostado en esta edici\u00f3n por grupos nacionales de rock &amp; roll de diversos g\u00e9neros con ra\u00edces en la m\u00fasica americana. Bifannah, J\u00b4Aime, Pelo Mono, The Limboos, Serpiente, Adi\u00f3s Amores, Melenas e Hinds componen el cartel del 4 y el 5 de septiembre que ha adaptado sus horarios a la nueva situaci\u00f3n sanitaria. Ha habido peque\u00f1os ajustes en la subida al escenario de los grupos respecto a lo anunciado inicialmente. Las actuaciones comenzar\u00e1n los dos d\u00edas a las 20.30 horas.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>El cambio de ubicaci\u00f3n del festival desde la plaza de los Burgos a la Ciudadela en esta cuarta edici\u00f3n tambi\u00e9n vino motivado por la misma raz\u00f3n, ya que se trata de un espacio m\u00e1s amplio en el que es posible controlar el aforo y mantener todas las medidas de seguridad necesarias en estos momentos como la distancia entre el p\u00fablico asistente. Las entradas para cada d\u00eda cuestan 10 euros m\u00e1s gastos de gesti\u00f3n. Existe la opci\u00f3n de un abono para todo el festival al precio de 15 euros m\u00e1s gastos. Se pueden adquirir en <a href=\"http:\/\/www.pamplonaescultura.es\" target=\"_blank\" rel=\"noopener noreferrer\">www.pamplonaescultura.es<\/a>.<\/p>\n<p>Pim Pam Ville se ha convertido este a\u00f1o en una cita con el rock &amp; roll que abarca diversos g\u00e9neros en torno a las ra\u00edces de la m\u00fasica americana: el folk, el country, el blues y todos sus derivados como pueden ser el punk, el pop, el garage o sonidos m\u00e1s industriales del tipo krautrock o post-punk. Se ha apostado por la escena nacional, en la que abundan bandas de gran calidad, evitando as\u00ed riesgos y cancelaciones de \u00faltima hora debido a posibles restricciones en vuelos desde otros pa\u00edses como consecuencia de la Covid-19. En ediciones anteriores han pasado por el escenario de Pim Pam Ville 25 bandas de diferentes procedencias y estilos que han congregado 20.000 espectadores, algunos de ellos de fuera de la Comunidad Foral.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Traer a Pamplona grupos alejados del circuito comercial<\/strong><\/p>\n<p>El objetivo de este evento es acercar a la calle bandas y estilos musicales alejados del circuito comercial y que no son habituales en la ciudad en espacios abiertos o grandes escenarios, combinando formaciones m\u00edticas con grupos locales de gran calidad. De esta forma se potencia al mismo tiempo la escena underground y las numerosas bandas locales que pertenecen a la misma. Quiere convertirse en un festival urbano, popular y accesible para toda la ciudadan\u00eda con un d\u00eda de celebraci\u00f3n de la m\u00fasica.<\/p>\n<p>Dentro de los grupos navarros que el festival apoya se encuentran los que tienen una larga trayectoria como nuevos creadores. Un ejemplo es Melenas, que debut\u00f3 en el primer Pim Pam Ville y que a d\u00eda de hoy es uno de los grupos nacionales con mayor proyecci\u00f3n internacional. Edita con el reconocido sello estadounidense Trouble Mind Records y ha participado en importantes festivales internacionales. Otro aspecto en el que el festival incide es en el de la paridad, para lo que se busca una participaci\u00f3n similar de hombres y mujeres en los conciertos. Este a\u00f1o ser\u00e1n cuatro bandas formadas por mujeres las que subir\u00e1n al escenario en la tarde noche del s\u00e1bado.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Grupos participantes<\/strong><\/p>\n<p>La representaci\u00f3n local de esta edici\u00f3n incluye a Melenas, J\u00b4aime o las bilba\u00ednas Serpiente junto a grandes bandas nacionales de la talla de The Limboos, Bifannah o Pelo Mono y grupos emergentes como las sevillanas Adi\u00f3s Amores. Cerrar\u00e1 con la banda de mayor repercusi\u00f3n a nivel internacional, Hinds.<\/p>\n<p>El viernes 4 de septiembre abrir\u00e1 Pim Pam Ville 2020 Bifannah (tropicalismo atl\u00e1ntico, dan\u00e7as e lisergia), que en portugu\u00e9s se erige como la respuesta hispana a la nueva ola psych anglosajona. La mistura de sus influencias va desde el pop de la costa oeste y el tropicalismo a los ritmos latinos de finales de los setenta. A continuaci\u00f3n, subir\u00e1n al escenario J\u00b4Aime (rock&amp;roll, country, pop) y Pelo Mono o Pilus Hominidae con una propuesta en la que unen rock and roll, country, rhythm and blues y \u2018una variable fractal entre sci fi y ex\u00f3tica\u2019. Cerrar\u00e1 el d\u00eda a partir de las doce menos diez de la noche The Limboos (exotic R&amp;B). Con \u2018Ba\u00eda\u2019, su tercer \u00e1lbum en cinco a\u00f1os, muestran que dentro de este mundo posmoderno, existe otro, un territorio limbo\u00f3tico en el que habitan quienes guardan los secretos de la buena m\u00fasica y donde todo es real, caliente y excitante.<\/p>\n<p>El s\u00e1bado d\u00eda 5 actuar\u00e1n en primer lugar en Ciudadela Serpiente (wew wave, post punk), una representaci\u00f3n \u2018del estilo p\u00e9rfido y necroso de los a\u00f1os 80, las cavilaciones hacia el surf-pop m\u00e1s g\u00f3tico y una evidente conexi\u00f3n con el movimiento cultural vasco Ez Dok Amairu\u2019. A las nueve y media de la noche comenzar\u00e1 el concierto de Adi\u00f3s Amores (pop), un joven d\u00fao femenino de pop con una dosis de dramatismo que no pierde de vista los elementos recurrentes y cargados de embrujo del folclore andaluz. Melenas (garage, pop, psych, kraut) presentar\u00e1 \u2018D\u00edas Raros\u2019, antes de que finalice el festival con la actuaci\u00f3n de Hinds (indie-rock). Tras dos primeros \u00e1lbumes que situaron a Hinds no s\u00f3lo como el grupo espa\u00f1ol m\u00e1s internacional sino como una de las bandas de guitarras m\u00e1s reconocibles del circuito global; ha regresado con un trabajo que marca la trayectoria del grupo madrile\u00f1o.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #ff0000;\">Festival de m\u00fasica Pim Pam Ville 2020<\/span><\/h3>\n<ul>\n<li><u>Viernes 4 septiembre<\/u><\/li>\n<li><strong>Bifannah<\/strong>. 20:30. Lisergia tropical<\/li>\n<li><strong>J\u00e1ime<\/strong>. 21:35. Twang-pop<\/li>\n<li><strong>Pelo Mono<\/strong>. 22:35. Surf selv\u00e1tico<\/li>\n<li><strong>The Limboos<\/strong>. 23:50. R&amp;B Soul ex\u00f3tico<\/li>\n<li><u>S\u00e1bado 5 septiembre<\/u><\/li>\n<li><strong>Serpiente<\/strong>. 20:30. Euskal wave<\/li>\n<li><strong>Adios Amores<\/strong>. 21:30. Synth-pop<\/li>\n<li><strong>Melenas<\/strong>. 22:30. Reverb Core. Fuzz Pop<\/li>\n<li><strong>Hinds<\/strong>. 23:30 Indie rock<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Bifannah, J\u00b4Aime, Pelo Mono, The Limboos, Serpiente, Adi\u00f3s Amores, Melenas e Hinds componen el cartel que ha adaptado horarios a la situaci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":31292,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-31598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Festival Pim Pam Ville 2020 se celebra este fin de semana en la Ciudadela con una apuesta por grupos nacionales de rock &amp; roll con toques de m\u00fasica americana<\/title>\n<meta name=\"description\" content=\"Bifannah, J\u00b4Aime, Pelo Mono, The Limboos, Serpiente, Adi\u00f3s Amores, Melenas e Hinds componen el cartel que ha adaptado horarios a la situaci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Festival Pim Pam Ville 2020 se celebra este fin de semana en la Ciudadela con una apuesta por grupos nacionales de rock &amp; roll con toques de m\u00fasica americana\" \/>\n<meta property=\"og:description\" content=\"Bifannah, J\u00b4Aime, Pelo Mono, The Limboos, Serpiente, Adi\u00f3s Amores, Melenas e Hinds componen el cartel que ha adaptado horarios a la situaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-02T15:02:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-02T15:16:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/08\/20.08.05_Pim_Pam_Ville-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El Festival Pim Pam Ville 2020 se celebra este fin de semana en la Ciudadela con una apuesta por grupos nacionales de rock &#038; roll con toques de m\u00fasica americana\",\"datePublished\":\"2020-09-02T15:02:43+00:00\",\"dateModified\":\"2020-09-02T15:16:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\\\/\"},\"wordCount\":1040,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/20.08.05_Pim_Pam_Ville-1.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\\\/\",\"name\":\"El Festival Pim Pam Ville 2020 se celebra este fin de semana en la Ciudadela con una apuesta por grupos nacionales de rock & roll con toques de m\u00fasica americana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/20.08.05_Pim_Pam_Ville-1.jpg\",\"datePublished\":\"2020-09-02T15:02:43+00:00\",\"dateModified\":\"2020-09-02T15:16:56+00:00\",\"description\":\"Bifannah, J\u00b4Aime, Pelo Mono, The Limboos, Serpiente, Adi\u00f3s Amores, Melenas e Hinds componen el cartel que ha adaptado horarios a la situaci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/20.08.05_Pim_Pam_Ville-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/20.08.05_Pim_Pam_Ville-1.jpg\",\"width\":1920,\"height\":1278},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Festival Pim Pam Ville 2020 se celebra este fin de semana en la Ciudadela con una apuesta por grupos nacionales de rock &#038; roll con toques de m\u00fasica americana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Festival Pim Pam Ville 2020 se celebra este fin de semana en la Ciudadela con una apuesta por grupos nacionales de rock & roll con toques de m\u00fasica americana","description":"Bifannah, J\u00b4Aime, Pelo Mono, The Limboos, Serpiente, Adi\u00f3s Amores, Melenas e Hinds componen el cartel que ha adaptado horarios a la situaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/","og_locale":"es_ES","og_type":"article","og_title":"El Festival Pim Pam Ville 2020 se celebra este fin de semana en la Ciudadela con una apuesta por grupos nacionales de rock & roll con toques de m\u00fasica americana","og_description":"Bifannah, J\u00b4Aime, Pelo Mono, The Limboos, Serpiente, Adi\u00f3s Amores, Melenas e Hinds componen el cartel que ha adaptado horarios a la situaci\u00f3n","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-09-02T15:02:43+00:00","article_modified_time":"2020-09-02T15:16:56+00:00","og_image":[{"width":1920,"height":1278,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/08\/20.08.05_Pim_Pam_Ville-1.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El Festival Pim Pam Ville 2020 se celebra este fin de semana en la Ciudadela con una apuesta por grupos nacionales de rock &#038; roll con toques de m\u00fasica americana","datePublished":"2020-09-02T15:02:43+00:00","dateModified":"2020-09-02T15:16:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/"},"wordCount":1040,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/08\/20.08.05_Pim_Pam_Ville-1.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/","name":"El Festival Pim Pam Ville 2020 se celebra este fin de semana en la Ciudadela con una apuesta por grupos nacionales de rock & roll con toques de m\u00fasica americana","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/08\/20.08.05_Pim_Pam_Ville-1.jpg","datePublished":"2020-09-02T15:02:43+00:00","dateModified":"2020-09-02T15:16:56+00:00","description":"Bifannah, J\u00b4Aime, Pelo Mono, The Limboos, Serpiente, Adi\u00f3s Amores, Melenas e Hinds componen el cartel que ha adaptado horarios a la situaci\u00f3n","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/08\/20.08.05_Pim_Pam_Ville-1.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/08\/20.08.05_Pim_Pam_Ville-1.jpg","width":1920,"height":1278},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-pim-pam-ville-2020-se-celebra-este-fin-de-semana-en-la-ciudadela-con-una-apuesta-por-grupos-nacionales-de-rock-roll-con-toques-de-musica-americana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El Festival Pim Pam Ville 2020 se celebra este fin de semana en la Ciudadela con una apuesta por grupos nacionales de rock &#038; roll con toques de m\u00fasica americana"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/31598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=31598"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/31598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/31292"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=31598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=31598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=31598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}