{"id":29623,"date":"2020-05-05T18:52:06","date_gmt":"2020-05-05T16:52:06","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=29623"},"modified":"2020-05-05T18:52:06","modified_gmt":"2020-05-05T16:52:06","slug":"un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/","title":{"rendered":"Un total de 104 trabajadores del Ayuntamiento de Pamplona se han visto afectados por el coronavirus desde el comienzo del Estado de Alarma"},"content":{"rendered":"<h5>En la actualidad, permanecen de baja 20 personas, de las que 14 han dado positivo y otras 6 se encuentran en aislamiento<\/h5>\n<p><!--more--><\/p>\n<p>Al igual que en el conjunto de poblaci\u00f3n, la expansi\u00f3n de la pandemia del coronavirus ha tenido sus efectos en la plantilla del Ayuntamiento de Pamplona. Desde que se decret\u00f3 el Estado de Alarma y hasta el d\u00eda de ayer, un total de 104 trabajadores municipales se han visto afectados por el Covid-19 o han mostrado s\u00edntomas compatibles con la enfermedad. Esta cifra supone en torno a un 6,5% del conjunto de la plantilla, que asciende a alrededor de 1.600 personas, entre personal funcionario y contratado. El momento m\u00e1s cr\u00edtico en cuanto a afecciones se registr\u00f3 en la segunda semana del Estado de Alarma. Entonces se alcanz\u00f3 el pico, con 55 casos entre los empleados municipales, el grueso de ellos entre agentes de Polic\u00eda Municipal y trabajadoras del Equipo Municipal de Atenci\u00f3n Domiciliaria (EMAD). En estos momentos, el n\u00famero de personas de baja por coronavirus es de 20, de las que 14 son positivos confirmados y 6 se encuentran en aislamiento.<\/p>\n<p>De esos 104 casos registrados hasta la fecha entre la plantilla del Ayuntamiento, 38 corresponden a personal de Polic\u00eda Municipal. Por su parte, en el EMAD se han dado 14 casos, a los que se suman otros 12 surgidos entre la plantilla de las unidades de barrio y 4 m\u00e1s en los servicios sociales municipales. Entre el resto de personal municipal se han detectado 36 casos. Tras los correspondientes an\u00e1lisis, de entre esos 104 casos se han confirmado 33 positivos por coronavirus, mientras que otros 27 resultaron negativos. Un total de 35 trabajadores han permanecido aislados por recomendaci\u00f3n del Servicio Navarro de Salud, y 5 est\u00e1n a la espera de que se les realicen las pruebas diagn\u00f3sticas.<\/p>\n<p>La mayor incidencia se ha dado entre el personal masculino mayor de 41 a\u00f1os. En concreto, en la franja de edad de 41 a 50 a\u00f1os, se han dado 12 positivos confirmados en hombres, frente a 5 en mujeres. La tendencia es similar en el rango de edad inmediatamente superior, de 51 a 60 a\u00f1os, con 9 positivos en hombres y 3 en mujeres.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Plan frente al coronavirus<\/strong><\/p>\n<p>Todos estos datos han sido presentados esta ma\u00f1ana a los grupos municipales por parte de la concejala delegada de Servicios Generales del Ayuntamiento de Pamplona, Mar\u00eda Ech\u00e1varri, en la Comisi\u00f3n de Presidencia, donde tambi\u00e9n ha dado cuenta de las actuaciones que ha llevado a cabo el Consistorio para garantizar la seguridad de sus trabajadores y reorganizar la actividad de acuerdo a las exigencias marcadas por el Estado de Alarma.<\/p>\n<p>En este sentido, antes incluso de decretarse el Estado de Alarma, y ante el creciente n\u00famero de contagio entre la poblaci\u00f3n en general, desde el Servicio de Prevenci\u00f3n de Riesgos Labores del Ayuntamiento se llevaron a cabo en la primera semana de marzo charlas informativas sobre medidas higi\u00e9nicas a los responsables y delegados de prevenci\u00f3n del Equipo Municipal de Atenci\u00f3n Domiciliaria y de Polic\u00eda Municipal, al tratarse de los puestos de trabajo m\u00e1s expuestos por su contacto directo con un amplio n\u00famero de personas. Asimismo, se ofreci\u00f3 informaci\u00f3n espec\u00edfica al personal del cementerio sobre manipulaci\u00f3n de f\u00e9retros de personas fallecidas a causa del Covid-19. Ya el 11 de marzo se establecieron distancias de seguridad en los puestos de atenci\u00f3n al p\u00fablico. Las normas higi\u00e9nicas se generalizaron al conjunto de la plantilla a trav\u00e9s de carteles y la intranet municipal.<\/p>\n<p>El Consistorio elabor\u00f3, adem\u00e1s, un Plan de Acciones y Estrategia propio, como gu\u00eda de actuaci\u00f3n ante la pandemia, que incluye distintos aspectos, desde la definici\u00f3n de responsabilidades y \u00e1reas sobre las que actuar hasta los criterios que se usan en la toma de decisiones.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Equipos de Protecci\u00f3n Individual<\/strong><\/p>\n<p>Como complemento a ese plan, el Ayuntamiento hizo una primera compra de material higi\u00e9nico, en concreto, geles desinfectantes hidroalcoh\u00f3licos para dotar a la plantilla de los puestos especialmente comprometidos. La adquisici\u00f3n de mascarillas, sin embargo, ha resultado m\u00e1s complicada. Este elemento de protecci\u00f3n es b\u00e1sico para el Servicio de Atenci\u00f3n Domiciliaria. De hecho, en un a\u00f1o habitual, usan en torno a 400 mascarillas. Ante la creciente expansi\u00f3n del coronavirus, en un primer momento el Ayuntamiento solicit\u00f3 al Servicio Navarro de Salud entre 150 y 200 mascarillas para este servicio. La solicitud, sin embargo, no obtuvo respuesta. Finalmente, aunque en un primer momento las compras iban a ser centralizadas por los Ejecutivos central y auton\u00f3mico, ante la imposibilidad de suministrar el material el propio Consistorio se ha encargado de adquirir parte los EPIS necesarios para la plantilla. En el conjunto de la plantilla municipal, el consumo de mascarillas ha sido superior a 9.000 unidades; todo ello sin contar las usadas en Polic\u00eda Municipal.<\/p>\n<p>En base a un acuerdo alcanzado entre la Federaci\u00f3n Espa\u00f1ola de Municipios y el Ministerio de Sanidad, el Ayuntamiento recibi\u00f3 ayer de manos de la Delegaci\u00f3n del Gobierno 30.000 mascarillas, destinadas a los colectivos m\u00e1s vulnerables de la ciudad, junto con operarios municipales de limpieza, residuos s\u00f3lidos, empleados de transporte p\u00fablico urbano, trabajadores sociales, polic\u00edas locales, bomberos, etc.<\/p>\n<p>Adem\u00e1s, el Servicio de Prevenci\u00f3n ha posibilitado que el personal municipal pueda acceder a la realizaci\u00f3n de test r\u00e1pidos de detecci\u00f3n del coronavirus, que se realizan en las instalaciones de REFENA, dependientes del Gobierno de Navarra. En un primer momento, se hicieron las pruebas al personal del Equipo Municipal de Atenci\u00f3n a Domicilio (EMAD) y, posteriormente, a todos los servicios declarados como esenciales, es decir, Polic\u00eda Municipal y del \u00e1rea de Servicios Sociales, para poder garantizar su prestaci\u00f3n.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>450 empleados teletrabajando<\/strong><\/p>\n<p>Con el decreto del Estado de Alarma, el Ayuntamiento prioriz\u00f3 el teletrabajo entre la plantilla, en coordinaci\u00f3n con ANIMSA, empresa encargada de dar el soporte t\u00e9cnico. Antes de la propagaci\u00f3n del coronavirus, el Consistorio contaba con capacidad para que 400 puestos pudieran operar en teletrabajo. La cifra, no obstante, pod\u00eda ampliarse excepcionalmente si fuera necesario, como as\u00ed ha sido. En la actualidad, se han gestionado y activado m\u00e1s de 450 solicitudes de teletrabajo entre la plantilla. En aquellos puestos en los que la actividad presencial no era fundamental se ha priorizado el trabajo en remoto. Tal es el caso, por ejemplo, del servicio de atenci\u00f3n municipal 010, para el que se elabor\u00f3 un plan de respuesta y operatividad ante la crisis sanitaria.<\/p>\n<p>En materia de contrataci\u00f3n, para hacer frente a las nuevas necesidades de personal derivadas del incremento de servicios asistenciales, el Consistorio ha procedido a la contrataci\u00f3n de ocho trabajadores de Integraci\u00f3n Social, para atender el albergue de Jes\u00fas y Mar\u00eda, dedicado a acoger transe\u00fantes; y para reforzar el \u00e1rea de Asuntos Sociales. Por el contrario, el \u00e1rea de Recursos Humanos acord\u00f3, dadas las dimensiones que estaba tomando la pandemia, suspender la prueba de selecci\u00f3n de Auxiliares de Protecci\u00f3n Civil para Sanfermines, prevista para el pasado 14 de marzo.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Medidas de protecci\u00f3n ante la vuelta al trabajo<\/strong><\/p>\n<p>A la espera de conocer en qu\u00e9 medida pondr\u00e1n reincorporarse f\u00edsicamente los trabajadores municipales que ahora desarrollan su trabajo de forma remota, se han desarrollado una serie de normas siguiendo los criterios del Instituto de Salud P\u00fablica y Laboral de Navarra. Adem\u00e1s, se ha hecho una evaluaci\u00f3n individualizada de todas las oficinas municipales, puesto a puesto. El Servicio de Prevenci\u00f3n municipal ha planteado 104 actuaciones individualizadas para mejorar las garant\u00edas de seguridad e higiene de los trabajadores. Entre otras, se plantea separaciones f\u00edsicas con mamparas o biombos, as\u00ed como la reubicaci\u00f3n de puestos de trabajo para aumentar el distanciamiento entre personas de un mismo servicio o \u00e1rea.<\/p>\n<p>Tambi\u00e9n se ha impulsado la toma de temperatura a los trabajadores y visitantes que acudan a las instalaciones municipales, como medida de control de la salud y para evitar la propagaci\u00f3n de contagios. Para ello, se ha elaborado unas instrucciones desde el punto de vista de prevenci\u00f3n y se han dado pautas a los trabajadores designados para esta tarea en cada una de los edificios municipales.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la actualidad, permanecen de baja 20 personas, de las que 14 han dado positivo y otras 6 se encuentran en aislamiento<\/p>\n","protected":false},"author":1,"featured_media":29405,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-29623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un total de 104 trabajadores del Ayuntamiento de Pamplona se han visto afectados por el coronavirus desde el comienzo del Estado de Alarma<\/title>\n<meta name=\"description\" content=\"En la actualidad, permanecen de baja 20 personas, de las que 14 han dado positivo y otras 6 se encuentran en aislamiento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un total de 104 trabajadores del Ayuntamiento de Pamplona se han visto afectados por el coronavirus desde el comienzo del Estado de Alarma\" \/>\n<meta property=\"og:description\" content=\"En la actualidad, permanecen de baja 20 personas, de las que 14 han dado positivo y otras 6 se encuentran en aislamiento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-05T16:52:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.22_medicion_temperatura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1560\" \/>\n\t<meta property=\"og:image:height\" content=\"1170\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"Un total de 104 trabajadores del Ayuntamiento de Pamplona se han visto afectados por el coronavirus desde el comienzo del Estado de Alarma\",\"datePublished\":\"2020-05-05T16:52:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\\\/\"},\"wordCount\":1395,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20.04.22_medicion_temperatura.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\\\/\",\"name\":\"Un total de 104 trabajadores del Ayuntamiento de Pamplona se han visto afectados por el coronavirus desde el comienzo del Estado de Alarma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20.04.22_medicion_temperatura.jpg\",\"datePublished\":\"2020-05-05T16:52:06+00:00\",\"description\":\"En la actualidad, permanecen de baja 20 personas, de las que 14 han dado positivo y otras 6 se encuentran en aislamiento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20.04.22_medicion_temperatura.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20.04.22_medicion_temperatura.jpg\",\"width\":1560,\"height\":1170},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un total de 104 trabajadores del Ayuntamiento de Pamplona se han visto afectados por el coronavirus desde el comienzo del Estado de Alarma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un total de 104 trabajadores del Ayuntamiento de Pamplona se han visto afectados por el coronavirus desde el comienzo del Estado de Alarma","description":"En la actualidad, permanecen de baja 20 personas, de las que 14 han dado positivo y otras 6 se encuentran en aislamiento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/","og_locale":"es_ES","og_type":"article","og_title":"Un total de 104 trabajadores del Ayuntamiento de Pamplona se han visto afectados por el coronavirus desde el comienzo del Estado de Alarma","og_description":"En la actualidad, permanecen de baja 20 personas, de las que 14 han dado positivo y otras 6 se encuentran en aislamiento.","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-05-05T16:52:06+00:00","og_image":[{"width":1560,"height":1170,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.22_medicion_temperatura.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"Un total de 104 trabajadores del Ayuntamiento de Pamplona se han visto afectados por el coronavirus desde el comienzo del Estado de Alarma","datePublished":"2020-05-05T16:52:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/"},"wordCount":1395,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.22_medicion_temperatura.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/","name":"Un total de 104 trabajadores del Ayuntamiento de Pamplona se han visto afectados por el coronavirus desde el comienzo del Estado de Alarma","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.22_medicion_temperatura.jpg","datePublished":"2020-05-05T16:52:06+00:00","description":"En la actualidad, permanecen de baja 20 personas, de las que 14 han dado positivo y otras 6 se encuentran en aislamiento.","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.22_medicion_temperatura.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.22_medicion_temperatura.jpg","width":1560,"height":1170},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/un-total-de-104-trabajadores-del-ayuntamiento-de-pamplona-se-han-visto-afectados-por-el-coronavirus-desde-el-comienzo-del-estado-de-alarma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Un total de 104 trabajadores del Ayuntamiento de Pamplona se han visto afectados por el coronavirus desde el comienzo del Estado de Alarma"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/29623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=29623"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/29623\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/29405"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=29623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=29623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=29623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}