{"id":29310,"date":"2020-04-15T16:39:59","date_gmt":"2020-04-15T14:39:59","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=29310"},"modified":"2020-04-15T16:44:06","modified_gmt":"2020-04-15T14:44:06","slug":"la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/","title":{"rendered":"La Polic\u00eda Municipal de Pamplona ha realizado en este mes de confinamiento 2.023 actuaciones y ha propuesto sanciones a 1.096 personas por diferentes incumplimientos"},"content":{"rendered":"<h5>Las llamadas al CECOP, es decir al 092, han aumentado en un 36% respecto al mismo periodo del a\u00f1o anterior<\/h5>\n<p><!--more--><\/p>\n<p>Desde que entrara el vigor el Estado de Alarma, decretado el 14 de marzo con efectos a partir de la medianoche del d\u00eda 15, la Polic\u00eda Municipal de Pamplona ha realizado 2.023 intervenciones en la ciudad. En este \u00faltimo mes la Policia Municipal ha propuesto que se sancione a 1.096 personas por incumplir las restricciones establecidas en la legislaci\u00f3n derivada de la crisis sanitaria del coronavirus.<\/p>\n<p>De esas 1.096 propuestas de sanci\u00f3n, 195 se han realizado en controles de veh\u00edculos en la v\u00eda p\u00fablica motivadas, principalmente, por desplazamientos injustificados. Se han controlado en este \u00faltimo mes un total de 10.173 veh\u00edculos, de los que casi un 5%, es decir 503, han sido autobuses de transporte urbano. El resto de propuestas de sanci\u00f3n, 901 se han interpuesto a diferentes ciudadanos por incumplimientos como ruidos o molestias al vecindario, quebrantamiento del orden p\u00fablico, celebraci\u00f3n de fiestas o reuniones en viviendas.<\/p>\n<p>La labor que la Polic\u00eda Municipal est\u00e1 llevando a cabo desde la implantaci\u00f3n del Estado del Alarma ha provocado una mayor exposici\u00f3n de los agentes al contagio del coronavirus. En estos momentos el cuerpo local cuenta con 14 polic\u00edas municipales contagiados.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Menos denuncias y menos personas detenidas en la Oficina De Atenci\u00f3n Ciudadana<\/strong><\/p>\n<p>El Grupo de Central de Coordinaci\u00f3n Operativa (CECOP) ha recibido en este mes desde que se decret\u00f3 el Estado de Alarma un total de 22.936 llamadas, lo que supone un 36% m\u00e1s que en el mismo periodo del a\u00f1o anterior. En 2019 se registraron 16.833 llamadas en la centralita del 092 de Polic\u00eda Municipal de Pamplona. Ese incremento de llamadas se debe, entre otros factores, a las consultas relacionadas con el coronavirus, en aspectos como la interpretaci\u00f3n del Real Decreto del Estado de Alarma, las restricciones en la movilidad personal o la apertura de diferentes tipos de negocios o establecimiento, entre otras dudas.<\/p>\n<p>Las restricciones en la movilidad tambi\u00e9n han provocado un descenso en las denuncias presentadas en la ODAC (Oficina De Atenci\u00f3n Ciudadana). En este periodo de un mes se interpusieron en 2019 un total de 664 denuncias, por las 137 de los \u00faltimos 31 d\u00edas, un 80% menos. Este dato conlleva, igualmente, una bajada en las personas detenidas derivadas de esas denuncias en la ODAC. El a\u00f1o pasado se detuvo entre mediados de marzo y mediados de abril a 54 personas y en este 2020 a 13, un 76% menos.<\/p>\n<p>El descenso del tr\u00e1fico en la ciudad, cifrado ya en las primeras semanas de confinamiento en un 70% los d\u00edas laborables y en m\u00e1s de un 80% los festivos, ha provocado tambi\u00e9n una bajada de los accidentes de tr\u00e1fico en Pamplona. El a\u00f1o pasado en el periodo comprendido entre el 15 de marzo y el 15 de abril se produjeron en la ciudad 255 accidente. En esta 2020 la cifra se ha reducido hasta los 38 accidentes, un 85% menos.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las llamadas al CECOP, es decir al 092, han aumentado en un 36% respecto al mismo periodo del a\u00f1o anterior<\/p>\n","protected":false},"author":1,"featured_media":16252,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-29310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Polic\u00eda Municipal de Pamplona ha realizado en este mes de confinamiento 2.023 actuaciones y ha propuesto sanciones a 1.096 personas por diferentes incumplimientos<\/title>\n<meta name=\"description\" content=\"Las llamadas al CECOP, es decir al 092, han aumentado en un 36% respecto al mismo periodo del a\u00f1o anterior\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Polic\u00eda Municipal de Pamplona ha realizado en este mes de confinamiento 2.023 actuaciones y ha propuesto sanciones a 1.096 personas por diferentes incumplimientos\" \/>\n<meta property=\"og:description\" content=\"Las llamadas al CECOP, es decir al 092, han aumentado en un 36% respecto al mismo periodo del a\u00f1o anterior\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-15T14:39:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-15T14:44:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/02\/18.02.23_control-Polic\u00eda-Municipal-pasos-peatones.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"La Polic\u00eda Municipal de Pamplona ha realizado en este mes de confinamiento 2.023 actuaciones y ha propuesto sanciones a 1.096 personas por diferentes incumplimientos\",\"datePublished\":\"2020-04-15T14:39:59+00:00\",\"dateModified\":\"2020-04-15T14:44:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\\\/\"},\"wordCount\":514,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/18.02.23_control-Polic\u00eda-Municipal-pasos-peatones.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\\\/\",\"name\":\"La Polic\u00eda Municipal de Pamplona ha realizado en este mes de confinamiento 2.023 actuaciones y ha propuesto sanciones a 1.096 personas por diferentes incumplimientos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/18.02.23_control-Polic\u00eda-Municipal-pasos-peatones.jpg\",\"datePublished\":\"2020-04-15T14:39:59+00:00\",\"dateModified\":\"2020-04-15T14:44:06+00:00\",\"description\":\"Las llamadas al CECOP, es decir al 092, han aumentado en un 36% respecto al mismo periodo del a\u00f1o anterior\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/18.02.23_control-Polic\u00eda-Municipal-pasos-peatones.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/18.02.23_control-Polic\u00eda-Municipal-pasos-peatones.jpg\",\"width\":1000,\"height\":718},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Polic\u00eda Municipal de Pamplona ha realizado en este mes de confinamiento 2.023 actuaciones y ha propuesto sanciones a 1.096 personas por diferentes incumplimientos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Polic\u00eda Municipal de Pamplona ha realizado en este mes de confinamiento 2.023 actuaciones y ha propuesto sanciones a 1.096 personas por diferentes incumplimientos","description":"Las llamadas al CECOP, es decir al 092, han aumentado en un 36% respecto al mismo periodo del a\u00f1o anterior","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/","og_locale":"es_ES","og_type":"article","og_title":"La Polic\u00eda Municipal de Pamplona ha realizado en este mes de confinamiento 2.023 actuaciones y ha propuesto sanciones a 1.096 personas por diferentes incumplimientos","og_description":"Las llamadas al CECOP, es decir al 092, han aumentado en un 36% respecto al mismo periodo del a\u00f1o anterior","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-04-15T14:39:59+00:00","article_modified_time":"2020-04-15T14:44:06+00:00","og_image":[{"width":1000,"height":718,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/02\/18.02.23_control-Polic\u00eda-Municipal-pasos-peatones.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"La Polic\u00eda Municipal de Pamplona ha realizado en este mes de confinamiento 2.023 actuaciones y ha propuesto sanciones a 1.096 personas por diferentes incumplimientos","datePublished":"2020-04-15T14:39:59+00:00","dateModified":"2020-04-15T14:44:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/"},"wordCount":514,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/02\/18.02.23_control-Polic\u00eda-Municipal-pasos-peatones.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/","name":"La Polic\u00eda Municipal de Pamplona ha realizado en este mes de confinamiento 2.023 actuaciones y ha propuesto sanciones a 1.096 personas por diferentes incumplimientos","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/02\/18.02.23_control-Polic\u00eda-Municipal-pasos-peatones.jpg","datePublished":"2020-04-15T14:39:59+00:00","dateModified":"2020-04-15T14:44:06+00:00","description":"Las llamadas al CECOP, es decir al 092, han aumentado en un 36% respecto al mismo periodo del a\u00f1o anterior","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/02\/18.02.23_control-Polic\u00eda-Municipal-pasos-peatones.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/02\/18.02.23_control-Polic\u00eda-Municipal-pasos-peatones.jpg","width":1000,"height":718},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-policia-municipal-de-pamplona-ha-realizado-en-este-mes-de-confinamiento-2-023-actuaciones-y-ha-propuesto-sanciones-a-1-096-personas-por-diferentes-incumplimientos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"La Polic\u00eda Municipal de Pamplona ha realizado en este mes de confinamiento 2.023 actuaciones y ha propuesto sanciones a 1.096 personas por diferentes incumplimientos"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/29310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=29310"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/29310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/16252"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=29310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=29310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=29310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}