{"id":29206,"date":"2020-04-06T12:52:05","date_gmt":"2020-04-06T10:52:05","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=29206"},"modified":"2020-04-06T12:52:05","modified_gmt":"2020-04-06T10:52:05","slug":"el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/","title":{"rendered":"El Ayuntamiento pone en marcha un centro de apoyo a las unidades de barrio ante el aumento de solicitudes de renta garantizada y ayudas de emergencia"},"content":{"rendered":"<h5>M\u00e1s de 385 personas trabajan en servicios sociales esenciales como unidades de barrio, SAD, SMAM, EAIA, EISOL, albergues y Comedor Municipal<\/h5>\n<p><!--more--><\/p>\n<p>Los primeros 13 d\u00edas de marzo el Ayuntamiento de Pamplona abon\u00f3 17.600 euros para ayudas de emergencia. La segunda quincena esa cantidad casi se multiplic\u00f3 por cuatro hasta llegar a 65.000 euros. Teniendo en cuenta estos datos y un estudio que se\u00f1ala que el n\u00famero de personas para las que habr\u00eda que tramitar las prestaciones de renta garantizada entre marzo y mayo supera el millar, el Consistorio pamplon\u00e9s ha puesto en funcionamiento hoy, lunes 6 de abril, un nuevo recurso. Servir\u00e1 de apoyo a las 13 unidades de barrio de la ciudad que desde que se decret\u00f3 el estado de alarma el pasado 14 de marzo para la gesti\u00f3n de la situaci\u00f3n de crisis sanitaria ocasionada por el COVID-19 han visto un incremento importante de solicitudes para tramitar las prestaciones de la renta garantizada y de ayudas de emergencia.<\/p>\n<p>De esta manera, el \u00c1rea de Servicios Sociales, Acci\u00f3n Comunitaria y Deporte ha querido apoyar a las unidades de barrio, que conforman la puerta de entrada a los servicios sociales, y a los profesionales, que lejos de aminorar su actividad la ven incrementada con mayor presi\u00f3n y esfuerzo laboral, tal y como ha explicado en rueda de prensa virtual la concejala del \u00e1rea, Mar\u00eda Caballero. Esta experiencia innovadora servir\u00e1 para atender las nuevas necesidades y urgencias sociales tratando de evitar que se colapse la tramitaci\u00f3n de todas las solicitudes de ayuda que el Consistorio pamplon\u00e9s est\u00e1 recibiendo las \u00faltimas semanas y dar as\u00ed una respuesta eficaz a la ciudadan\u00eda. M\u00e1s de 385 profesionales se encargan de atender a las personas usuarias en los servicios sociales municipales.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>El nuevo recurso no atender\u00e1 directamente al p\u00fablico<\/strong><\/p>\n<p>Adem\u00e1s de las unidades de barrio, el Ayuntamiento mantiene operativos otros recursos como el Servicio de Atenci\u00f3n a Domicilio (SAD), el Servicio Municipal de Atenci\u00f3n a la Mujer (SMAM) o el Equipo de Atenci\u00f3n a la Infancia en Dificultad Social (EAIA), el equipo de inserci\u00f3n socio-laboral (EISOL). Asimismo, est\u00e1n abiertos el Comedor Municipal y el Centro de Atenci\u00f3n a Personas sin Hogar, espacios que se han completado de manera excepcional en esta crisis sanitaria con los albergues de Jes\u00fas y Mar\u00eda y Casa Paderborn, el antiguo convento de Mar\u00eda Auxiliadora y algunas pensiones. Adem\u00e1s, esta semana comenzar\u00e1 a funcionar el servicio de urgencia que har\u00e1 frente durante Semana Santa a los casos graves.<\/p>\n<p>Otros ejemplos del incremento de las necesidades de atenci\u00f3n es que han aumentado las solicitudes de alimentaci\u00f3n del SAD con un incremento de gasto de 12.760 euros; en coordinaci\u00f3n con Gobierno de Navarra , el Ayuntamiento le informa de los beneficiarios de beca comedor y otras unidades familiares y hogares unipersonales desde las unidades de barrio para que le entreguen la tarjeta monetaria para alimentaci\u00f3n y junto con DYA se adelanta el pago de la cesta de la compra y f\u00e1rmacos a las familias confinadas que no tienen recursos y\/o que no tienen en ese momento dinero en met\u00e1lico, si queda demostrada la imposibilidad de pago.<\/p>\n<p>El centro de apoyo municipal de servicios sociales est\u00e1 ubicado en la nueva Unidad de Barrio de Lezkairu, en el antiguo Colegio Jos\u00e9 Vila de la Milagrosa. Cuenta con 6 trabajadores sociales y tres figuras educativas provenientes de los equipos preventivos de Acci\u00f3n Comunitaria y tres t\u00e9cnicas municipales que ejercen la coordinaci\u00f3n. Tramita prestaciones de renta garantizada y ayudas de emergencia que son derivadas por las propias unidades de barrio para poder abarcar la demanda. No hace atenci\u00f3n directa a personas sino que nace como un recurso de apoyo a profesionales. Tambi\u00e9n se encargan del seguimiento telef\u00f3nicos a poblaci\u00f3n de riesgo: personas mayores, menores, familias con situaciones dif\u00edciles, etc.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Ayudas para alimentaci\u00f3n y alojamiento la \u00faltima semana de marzo<\/strong><\/p>\n<p>El Ayuntamiento de Pamplona cuenta con una convocatoria de subvenciones destinada a personas y familias que se encuentran en situaci\u00f3n de emergencia social y necesitan ayuda para hacer frente al pago de necesidades b\u00e1sicas de alojamiento (pagos de alquileres o de hipotecas), suministros de luz o gas, alimentaci\u00f3n e higiene. En marzo, del 1 al 13, se realizaron abonos por un total de 17.600 euros, mientras que del 16 al 30 la cantidad ascendi\u00f3 a 65.000 euros. Esta convocatoria part\u00eda con una cantidad de 630.000 euros, que si sigue esta tendencia de solicitudes, tendr\u00e1 que ser incrementada.<\/p>\n<p>La renta garantizada es una prestaci\u00f3n econ\u00f3mica peri\u00f3dica destinada a las personas que no tienen cubiertas sus necesidades b\u00e1sicas y que puede ser complementaria de cualquiera otra a las que se tenga derecho. La concede el Gobierno de Navarra pero se tramita a trav\u00e9s de las unidades de barrio. Un estudio municipal cifra en 1.067 las renovaciones de rentas garantizadas que habr\u00e1 que tramitar desde marzo hasta mayo. A ellas se unen las 295 solicitudes de ayudas de emergencia recibidas entre el 16 de marzo y el 3 de abril y todas las que puedan ir llegando los pr\u00f3ximos meses.<\/p>\n<p>Durante el mes de marzo se han atendido a 121 personas que quer\u00edan renovar la renta garantizada. En abril est\u00e1 previsto que sean 434 y que en mayo lleguen a 512. Por barrios, la unidad de barrio con m\u00e1s solicitudes est\u00e1 previsto que sea Rochapea con 198, seguida de Milagrosa con 185, Txantrea con 133 y San Jorge con 108. Entre 50 y 100 solicitudes se recibir\u00e1n en Casco Antiguo (86), San Juan (72), Buztintxuri (69), Mendillorri (54), Ensanche (53) y Etxabakoitz (51). Por debajo de esas cifras se encuentran Ermitaga\u00f1a (32) e Iturrama (26) y la unidad de barrio de Lezkairu que entr\u00f3 en funcionamiento recientemente, que ser\u00e1n tramitadas desde Milagrosa.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Seguimiento a mayores, mujeres en riesgo de sufrir violencia de g\u00e9nero y menores<\/strong><\/p>\n<p>De forma paralela, el \u00c1rea de Servicios Sociales, Acci\u00f3n Comunitaria y Deporte ha intensificado los seguimientos a colectivos concretos como personas mayores, menores en situaci\u00f3n de desprotecci\u00f3n y mujeres en riesgo de sufrir violencia de g\u00e9nero. Entre el primer colectivo se prioriza a personas usuarias del Servicio de Atenci\u00f3n a Domicilio (SAD) y a aquellas que han suspendido esta atenci\u00f3n pero que pueden precisar una ayuda puntual; a quienes se encuentran en los apartamentos municipales; personas dependientes a las que se les ha tramitado alguna prestaci\u00f3n y que pueden ser susceptibles de supervisi\u00f3n; ancianos fr\u00e1giles de acuerdo al listado de los centros de salud o poblaci\u00f3n de la que se tiene constancia a trav\u00e9s de los movimientos vecinales de voluntariado.<\/p>\n<p>Por lo que respecta al seguimiento de mujeres con riesgo de sufrir violencia de g\u00e9nero durante el estado de alarma, se tienen en cuenta las usuarias atendidas por el Servicio Municipal de Atenci\u00f3n a la Mujer (SMAM) durante los \u00faltimos seis meses. Se les ha recordado, mediante llamada telef\u00f3nica, que el SMAM sigue activo y pueden contactar por tel\u00e9fono, presencialmente o por correo electr\u00f3nico, adem\u00e1s de en caso de urgencia, llamar a los tel\u00e9fonos 016, 092 y 112. Adem\u00e1s, teniendo en cuenta la situaci\u00f3n de confinamiento y el especial riesgo que puede conllevar para determinadas mujeres, se contact\u00f3 con el Instituto Navarro para la Igualdad (INAI) y los cuerpos policiales para conocer la situaci\u00f3n y facilitar la coordinaci\u00f3n en las actuaciones de seguimiento y atenci\u00f3n durante estas semanas.<\/p>\n<p>De forma paralela, los equipos de infancia y familia tambi\u00e9n est\u00e1n contactando con todas las familias donde ha sido diagnosticado cualquier riesgo de desprotecci\u00f3n para esos menores, para valorar si la situaci\u00f3n puede haberse visto incrementada con el confinamiento.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Atenci\u00f3n de situaciones urgentes en Semana Santa<\/strong><\/p>\n<p>Dada la especial situaci\u00f3n del estado de alarma, desde el \u00c1rea de Servicios Sociales se ha establecido un servicio especial de atenci\u00f3n durante Semana Santa, del 9 al 13 de abril. Est\u00e1 dirigido principalmente a familias y menores en situaciones urgentes de desprotecci\u00f3n, mujeres que sufren violencia de g\u00e9nero o se encuentran en riesgo de sufrirla y a quienes se queden sin vivienda por situaciones de conflicto en la convivencia, por salir de hospitales, excarcelaciones, etc. Asimismo, se tendr\u00e1n en cuenta personas que se encuentren en situaci\u00f3n de calle por tr\u00e1nsito entre poblaciones.<\/p>\n<p>De esta manera se ofrecer\u00e1 atenci\u00f3n telef\u00f3nica y\/o presencial en situaciones de car\u00e1cter grave y urgente en coordinaci\u00f3n con la red de dispositivos existentes para para proporcionar medidas de seguridad y protecci\u00f3n de mujeres, familias y menores o acompa\u00f1amiento a recursos residenciales.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Recursos sociales municipales que se han completado en el estado de alarma<\/strong><\/p>\n<p>El Ayuntamiento mantiene en funcionamiento recursos de servicios sociales habituales como las unidades de barrio, el Servicio de Atenci\u00f3n a Domicilio (EMAD), el Servicio Municipal de Atenci\u00f3n a la Mujer (SMAM), el Comedor Municipal de Pamplona y el Centro de Atenci\u00f3n a Personas sin Hogar. Tambi\u00e9n est\u00e1n operativos los programas del Equipo de Incorporaci\u00f3n Sociolaboral (EISOL), el Equipo de Atenci\u00f3n a la Infancia en Dificultad Social (EAIA) y algunos tajos de Empleo Social.<\/p>\n<p>Durante la crisis sanitaria se han completado con la puesta en marcha de nuevos recursos de alojamiento como el albergue tur\u00edstico y de peregrinos Jes\u00fas y Mar\u00eda para atender a personas sin hogar al estar completo el de Trinitarios; o el albergue de peregrinos Casa Paderborn, ubicado en el chalet Iraizoz, y la residencia de estudiantes del antiguo convento de Mar\u00eda Auxiliadora en el barrio de la Txantrea como centros de acogida provisional para personas en situaci\u00f3n de emergencia social. Tambi\u00e9n se han incorporado algunas pensiones para atender a quienes durante estas semanas se queden sin vivienda.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Refuerzo de personal y medidas de seguridad frente al coronavirus<\/strong><\/p>\n<p>El refuerzo tambi\u00e9n se ha plasmado en la incorporaci\u00f3n de personal, ya que a los m\u00e1s de 350 trabajadores de los servicios sociales de base que comenzaron atendiendo los diversos recursos se han unido los 24 profesionales del \u00e1mbito social y educativo de los contratos de preventivos para reforzar y mejorar la atenci\u00f3n ciudadana. Adem\u00e1s de 12 nuevos profesionales para prestar el acompa\u00f1amiento socio-educativo del Albergue Jes\u00fas y Mar\u00eda.<\/p>\n<p>Para la prestaci\u00f3n de estos servicios, en todos los casos, se est\u00e1n teniendo en cuenta las medidas aprobadas como el mantenimiento de distancias m\u00ednimas entre personas, priorizar la atenci\u00f3n telef\u00f3nica sobre la presencial y reforzar las medidas de higiene y limpieza, con especial cuidado en la seguridad de la atenci\u00f3n que presta el SAD. Por ejemplo, en el comedor municipal se entregan los alimentos en tupper; la limpieza se ha intensifica en los centros de trabajo con personal de empleo social y contratas y se ha contado con el apoyo del equipo de escuelas infantiles para el albergue Jes\u00fas y Mar\u00eda, y se ha exceptuado el pago a los m\u00e1s de 250 beneficiarios del SAD que han suspendido temporalmente el servicio y se les ha reservado la plaza con un coste de 11.400 euros.<\/p>\n<p>Para garantizar la seguridad frente al Covid.19 se han invertido m\u00e1s de 15.000 euros para equipos de protecci\u00f3n EPIs en el SAD, se ha priorizado la consideraci\u00f3n de las profesionales en las pruebas diagn\u00f3sticas y se ha impulsado la elaboraci\u00f3n de mascarillas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 385 personas trabajan en servicios sociales esenciales como unidades de barrio, SAD, SMAM, EAIA, EISOL, albergues y Comedor Municipal<\/p>\n","protected":false},"author":1,"featured_media":21939,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-29206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Ayuntamiento pone en marcha un centro de apoyo a las unidades de barrio ante el aumento de solicitudes de renta garantizada y ayudas de emergencia<\/title>\n<meta name=\"description\" content=\"M\u00e1s de 385 personas trabajan en servicios sociales esenciales como unidades de barrio, SAD, SMAM, EAIA, EISOL, albergues y Comedor Municipal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Ayuntamiento pone en marcha un centro de apoyo a las unidades de barrio ante el aumento de solicitudes de renta garantizada y ayudas de emergencia\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s de 385 personas trabajan en servicios sociales esenciales como unidades de barrio, SAD, SMAM, EAIA, EISOL, albergues y Comedor Municipal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-06T10:52:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El Ayuntamiento pone en marcha un centro de apoyo a las unidades de barrio ante el aumento de solicitudes de renta garantizada y ayudas de emergencia\",\"datePublished\":\"2020-04-06T10:52:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\\\/\"},\"wordCount\":1932,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\\\/\",\"name\":\"El Ayuntamiento pone en marcha un centro de apoyo a las unidades de barrio ante el aumento de solicitudes de renta garantizada y ayudas de emergencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"datePublished\":\"2020-04-06T10:52:05+00:00\",\"description\":\"M\u00e1s de 385 personas trabajan en servicios sociales esenciales como unidades de barrio, SAD, SMAM, EAIA, EISOL, albergues y Comedor Municipal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"width\":1920,\"height\":1100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Ayuntamiento pone en marcha un centro de apoyo a las unidades de barrio ante el aumento de solicitudes de renta garantizada y ayudas de emergencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Ayuntamiento pone en marcha un centro de apoyo a las unidades de barrio ante el aumento de solicitudes de renta garantizada y ayudas de emergencia","description":"M\u00e1s de 385 personas trabajan en servicios sociales esenciales como unidades de barrio, SAD, SMAM, EAIA, EISOL, albergues y Comedor Municipal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/","og_locale":"es_ES","og_type":"article","og_title":"El Ayuntamiento pone en marcha un centro de apoyo a las unidades de barrio ante el aumento de solicitudes de renta garantizada y ayudas de emergencia","og_description":"M\u00e1s de 385 personas trabajan en servicios sociales esenciales como unidades de barrio, SAD, SMAM, EAIA, EISOL, albergues y Comedor Municipal.","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-04-06T10:52:05+00:00","og_image":[{"width":1920,"height":1100,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El Ayuntamiento pone en marcha un centro de apoyo a las unidades de barrio ante el aumento de solicitudes de renta garantizada y ayudas de emergencia","datePublished":"2020-04-06T10:52:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/"},"wordCount":1932,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/","name":"El Ayuntamiento pone en marcha un centro de apoyo a las unidades de barrio ante el aumento de solicitudes de renta garantizada y ayudas de emergencia","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","datePublished":"2020-04-06T10:52:05+00:00","description":"M\u00e1s de 385 personas trabajan en servicios sociales esenciales como unidades de barrio, SAD, SMAM, EAIA, EISOL, albergues y Comedor Municipal.","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","width":1920,"height":1100},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-pone-en-marcha-un-centro-de-apoyo-a-las-unidades-de-barrio-ante-el-aumento-de-solicitudes-de-renta-garantizada-y-ayudas-de-emergencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El Ayuntamiento pone en marcha un centro de apoyo a las unidades de barrio ante el aumento de solicitudes de renta garantizada y ayudas de emergencia"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/29206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=29206"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/29206\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/21939"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=29206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=29206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=29206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}