{"id":29161,"date":"2020-04-02T17:23:45","date_gmt":"2020-04-02T15:23:45","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=29161"},"modified":"2020-04-02T17:23:45","modified_gmt":"2020-04-02T15:23:45","slug":"el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/","title":{"rendered":"El Ayuntamiento promueve una campa\u00f1a informativa sobre el servicio de compra y entrega a domicilio de los mercados municipales del Ensanche, Ermitaga\u00f1a y Santo Domingo"},"content":{"rendered":"<h5>Un d\u00edptico, accesible en <a href=\"http:\/\/www.pamplona.es\" target=\"_blank\" rel=\"noopener noreferrer\">www.pamplona.es<\/a>, en los peri\u00f3dicos, en los mercados y en farmacias, recoge los tel\u00e9fonos de los casi 80 puestos que est\u00e1n abiertos<\/h5>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/www.laguiadepamplona.es\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-29164\" src=\"https:\/\/www.laguiadepamplona.es\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-1-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-1-300x300.jpg 300w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-1-682x682.jpg 682w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-1-150x150.jpg 150w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-1-768x768.jpg 768w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-1-1536x1536.jpg 1536w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-1-640x640.jpg 640w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-1-550x550.jpg 550w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-1-1100x1100.jpg 1100w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-1.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.laguiadepamplona.es\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-29165\" src=\"https:\/\/www.laguiadepamplona.es\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-2-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-2-300x300.jpg 300w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-2-682x682.jpg 682w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-2-150x150.jpg 150w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-2-768x768.jpg 768w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-2-1536x1536.jpg 1536w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-2-640x640.jpg 640w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-2-550x550.jpg 550w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-2-1100x1100.jpg 1100w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales-2.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\u2018El mercado va a tu casa, para que t\u00fa no tengas que salir\u2019 es el lema de la campa\u00f1a informativa con la que el Ayuntamiento de Pamplona promueve el servicio de compra y entrega a domicilio de los tres mercados municipales de la ciudad. Para ello, se ha elaborado un d\u00edptico que recoge el tel\u00e9fono de los 80 puestos abiertos en los mercados de Santo Domingo, Ensanche y Ermitaga\u00f1a, as\u00ed como informaci\u00f3n de los horarios de apertura y atenci\u00f3n al p\u00fablico.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>La difusi\u00f3n de esos d\u00edpticos se ha llevado a cabo mediante su encarte en la edici\u00f3n de hoy jueves de los peri\u00f3dicos Diario de Navarra y Diario de Noticias y se podr\u00e1n conseguir tambi\u00e9n en los propios mercados municipales de Santo Domingo, Ensanche y Ermitaga\u00f1a desde este mismo jueves. Adem\u00e1s, en colaboraci\u00f3n con Nafarco, se va a distribuir en farmacias de la ciudad. La informaci\u00f3n se podr\u00e1 consultar en la p\u00e1gina web municipal, <a href=\"http:\/\/www.pamplona.es\/elmercadoencasa\" target=\"_blank\" rel=\"noopener noreferrer\">www.pamplona.es\/elmercadoencasa<\/a>, eligiendo el mercado al que se quiera dirigir o el tipo de producto que se quiera comprar y, adem\u00e1s, se colgar\u00e1 en distintas redes sociales municipales para que pueda ser visualizada por el mayor n\u00famero de personas.<\/p>\n<p>Cada mercado municipal gestiona ese servicio de venta y entrega a domicilio de manera propia, centralizando los pedidos un tel\u00e9fono o dirigi\u00e9ndose a cada puesto. Adem\u00e1s, esa compra se puede recoger en el propio mercado o la pueden enviar a los domicilios. El d\u00edptico recoge los 5 puestos abiertos del mercado de Ermitaga\u00f1a, los 26 del mercado de Santo Domingo y los 47 del mercado del Ensanche. A pesar de la actual situaci\u00f3n, los mercados siguen apostando por el producto fresco y de primera calidad en carnes, verduras, frutas, encurtidos, pescados, pan, huevos, l\u00e1cteos o frutos secos.<\/p>\n<p>El Ayuntamiento recuerda que los mercados municipales permanecen abiertos y ofrecen su habitual servicio a la ciudadan\u00eda. Para garantizar la seguridad de la clientela que acude a ellos de forma presencial, se ha reforzado la limpieza y desinfecci\u00f3n de las zonas comunes y de elementos de contacto, como manillas, mostradores\u2026 Asimismo, se protege de manera especial, con cortinas de pl\u00e1stico, los puestos de frutas y verduras y otros puestos para disminuir notablemente la posibilidad de contaminaci\u00f3n de estos productos.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Pedidos en el mercado del Ensanche por tel\u00e9fono, web o whatsapp<\/strong><\/p>\n<p>El mercado del Ensanche abre de lunes a s\u00e1bado, de 8.30 a 14.30 horas, y los viernes y v\u00edsperas de festivos tambi\u00e9n por la tarde, de 17 a 20 horas. El acceso a las instalaciones se puede realizar por cualquiera de sus cuatro puertas de entrada. Los viernes y s\u00e1bados, debido a la mayor afluencia de personas, el mercado se reserva el derecho a la apertura de las dos puertas situadas en la calle Gorriti con calle Amaya y calle Olite para controlar los aforos.<\/p>\n<p>La clientela puede realizar la compra por v\u00eda telef\u00f3nica, whatsapp o a trav\u00e9s de la web de sus puestos habituales, donde se les informar\u00e1 de los m\u00e9todos de compra y entrega disponibles. Si lo que se necesita es \u00fanicamente informaci\u00f3n general, se puede llamar al tel\u00e9fono 948 230 861. Debido a la actual situaci\u00f3n, los env\u00edos se est\u00e1n realizando de manera gratuita, siendo conscientes en el mercado del Ensanche de las necesidades de clientes, familias y dem\u00e1s ciudadan\u00eda de Pamplona.<\/p>\n<p>Por medidas higi\u00e9nicas y sanitarias, se ha procedido al cierre de los ba\u00f1os p\u00fablicos del mercado y se ha reforzado la limpieza de todas las zonas y elementos comunes cada 30 minutos, adem\u00e1s de cumplir con todas las recomendaciones propuestas desde Gobierno de Navarra para poder realizar su labor de venta de productos alimenticios.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Env\u00edo de pedidos la misma tarde en el mercado de Santo Domingo<\/strong><\/p>\n<p>El mercado Santo Domingo permanece abierto al p\u00fablico de lunes a s\u00e1bado, de 8 a 14 horas. Desde el inicio de esta crisis sanitaria, se decidi\u00f3 cerrar por las tardes para evitar desplazamientos y mantener el equilibrio entre el Estado de Alarma decretado y la obligaci\u00f3n de abastecimiento a la poblaci\u00f3n. El acceso al mercado se puede realizar por la calle Ma\u00f1ueta y por la plaza de Santiago (trasera del Ayuntamiento). La fila que se genera en esta \u00faltima zona tiene que ver con el acceso al supermercado, no con el acceso a los puestos del mercado. Quienes accedan al mercado de Santo Domingo por la puerta de la plaza de Santiago deber\u00e1n bajar a los puestos de la parte inferior por las escaleras ubicadas a la derecha.<\/p>\n<p>Para mayor comodidad de la clientela, el mercado de Santo Domingo ha reforzado el servicio de compra a domicilio, cuyo env\u00edo es gratuito para los pedidos superiores a 50 euros en la suma de todos los encargos. Si el gasto es inferior, el coste del env\u00edo ser\u00e1 de 7 euros. Las zonas de env\u00edo y la lista de localidades se pueden consultar en Facebook. Tambi\u00e9n se puede hacer la compra por tel\u00e9fono e ir a recogerla, sin esperas, disminuyendo as\u00ed notablemente los riesgos de contagio.<\/p>\n<p>Para realizar los pedidos se debe llamar a cada uno de los puestos para realizar la compra en ellos y confirmar si se van a hacer encargos en m\u00e1s de un puesto del mercado. El pago se realiza de forma individual en cada uno de los puestos indicando el n\u00famero de la tarjeta. Los propios comerciantes re\u00fanen el pedido del cliente y el repartidor sale de ruta a las 13.15 horas. Normalmente, antes de las 18 horas el pedido estar\u00e1 en casa del cliente, aunque puede haber retrasos debido a alta demanda de este servicio en estos d\u00edas.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>El mercado de Ermitaga\u00f1a centraliza los encargos en un tel\u00e9fono m\u00f3vil<\/strong><\/p>\n<p>Tambi\u00e9n contin\u00faa con su trabajo y su horario habitual el mercado de Ermitaga\u00f1a. Permanece abierto de lunes a s\u00e1bado, de 8 a 14 horas, y las tardes de los jueves y los viernes, de 17 a 20 horas. Para esta situaci\u00f3n extraordinaria se ha habilitado un servicio de compra conjunta y entrega a domicilio gratuita para personas con problemas de movilidad que vivan en el entorno del mercado, es decir, en los barrios de San Juan, Ermitaga\u00f1a y Mendebaldea. El tel\u00e9fono para pedidos es el 644 519 569 y los encargos se entregar\u00e1n al d\u00eda siguiente.<\/p>\n<p>El mercado mantiene tambi\u00e9n el servicio de encargos y posterior recogida de la compra en el propio mercado y tambi\u00e9n la posibilidad de encargar directamente en cada uno de los puestos. Toda la informaci\u00f3n se puede consultar en el d\u00edptico editado por el Ayuntamiento, en la web municipal, <a href=\"http:\/\/www.pamplona.es\" target=\"_blank\" rel=\"noopener noreferrer\">www.pamplona.es<\/a>, y en la web del mercado, <a href=\"http:\/\/www.mercadoermitagana.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.mercadoermitagana.com<\/a>. Desde el mercado se recuerda a los clientes que, al igual que ocurre en el de Santo Domingo, la fila que se suele generar en la entrada la conforman personas que acuden a comprar al supermercado ubicado en las mismas instalaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un d\u00edptico, accesible en www.pamplona.es, en los peri\u00f3dicos, en los mercados y en farmacias, recoge los tel\u00e9fonos de los casi 80 puestos que est\u00e1n abiertos<\/p>\n","protected":false},"author":1,"featured_media":29163,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-29161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Ayuntamiento promueve una campa\u00f1a informativa sobre el servicio de compra y entrega a domicilio de los mercados municipales del Ensanche, Ermitaga\u00f1a y Santo Domingo<\/title>\n<meta name=\"description\" content=\"Un d\u00edptico, accesible en www.pamplona.es, en los peri\u00f3dicos, en los mercados y en farmacias, recoge los tel\u00e9fonos de los casi 80 puestos que est\u00e1n abiertos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Ayuntamiento promueve una campa\u00f1a informativa sobre el servicio de compra y entrega a domicilio de los mercados municipales del Ensanche, Ermitaga\u00f1a y Santo Domingo\" \/>\n<meta property=\"og:description\" content=\"Un d\u00edptico, accesible en www.pamplona.es, en los peri\u00f3dicos, en los mercados y en farmacias, recoge los tel\u00e9fonos de los casi 80 puestos que est\u00e1n abiertos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-02T15:23:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El Ayuntamiento promueve una campa\u00f1a informativa sobre el servicio de compra y entrega a domicilio de los mercados municipales del Ensanche, Ermitaga\u00f1a y Santo Domingo\",\"datePublished\":\"2020-04-02T15:23:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\\\/\"},\"wordCount\":1247,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20.04.02_diptico_mercados_municipales.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\\\/\",\"name\":\"El Ayuntamiento promueve una campa\u00f1a informativa sobre el servicio de compra y entrega a domicilio de los mercados municipales del Ensanche, Ermitaga\u00f1a y Santo Domingo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20.04.02_diptico_mercados_municipales.jpg\",\"datePublished\":\"2020-04-02T15:23:45+00:00\",\"description\":\"Un d\u00edptico, accesible en www.pamplona.es, en los peri\u00f3dicos, en los mercados y en farmacias, recoge los tel\u00e9fonos de los casi 80 puestos que est\u00e1n abiertos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20.04.02_diptico_mercados_municipales.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20.04.02_diptico_mercados_municipales.jpg\",\"width\":1920,\"height\":1406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Ayuntamiento promueve una campa\u00f1a informativa sobre el servicio de compra y entrega a domicilio de los mercados municipales del Ensanche, Ermitaga\u00f1a y Santo Domingo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Ayuntamiento promueve una campa\u00f1a informativa sobre el servicio de compra y entrega a domicilio de los mercados municipales del Ensanche, Ermitaga\u00f1a y Santo Domingo","description":"Un d\u00edptico, accesible en www.pamplona.es, en los peri\u00f3dicos, en los mercados y en farmacias, recoge los tel\u00e9fonos de los casi 80 puestos que est\u00e1n abiertos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/","og_locale":"es_ES","og_type":"article","og_title":"El Ayuntamiento promueve una campa\u00f1a informativa sobre el servicio de compra y entrega a domicilio de los mercados municipales del Ensanche, Ermitaga\u00f1a y Santo Domingo","og_description":"Un d\u00edptico, accesible en www.pamplona.es, en los peri\u00f3dicos, en los mercados y en farmacias, recoge los tel\u00e9fonos de los casi 80 puestos que est\u00e1n abiertos.","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-04-02T15:23:45+00:00","og_image":[{"width":1920,"height":1406,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El Ayuntamiento promueve una campa\u00f1a informativa sobre el servicio de compra y entrega a domicilio de los mercados municipales del Ensanche, Ermitaga\u00f1a y Santo Domingo","datePublished":"2020-04-02T15:23:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/"},"wordCount":1247,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/","name":"El Ayuntamiento promueve una campa\u00f1a informativa sobre el servicio de compra y entrega a domicilio de los mercados municipales del Ensanche, Ermitaga\u00f1a y Santo Domingo","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales.jpg","datePublished":"2020-04-02T15:23:45+00:00","description":"Un d\u00edptico, accesible en www.pamplona.es, en los peri\u00f3dicos, en los mercados y en farmacias, recoge los tel\u00e9fonos de los casi 80 puestos que est\u00e1n abiertos.","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/04\/20.04.02_diptico_mercados_municipales.jpg","width":1920,"height":1406},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-promueve-una-campana-informativa-sobre-el-servicio-de-compra-y-entrega-a-domicilio-de-los-mercados-municipales-del-ensanche-ermitagana-y-santo-domingo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El Ayuntamiento promueve una campa\u00f1a informativa sobre el servicio de compra y entrega a domicilio de los mercados municipales del Ensanche, Ermitaga\u00f1a y Santo Domingo"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/29161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=29161"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/29161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/29163"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=29161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=29161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=29161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}