{"id":29066,"date":"2020-03-26T13:16:27","date_gmt":"2020-03-26T11:16:27","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=29066"},"modified":"2020-03-26T13:16:27","modified_gmt":"2020-03-26T11:16:27","slug":"policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/","title":{"rendered":"Polic\u00eda Municipal recomienda llevar un certificado de trabajo para agilizar controles de tr\u00e1fico y habilita un formulario tipo en la web del Ayuntamiento"},"content":{"rendered":"<h5>Aunque no es obligatorio llevar este certificado de necesidades de desplazamiento, \u00e9ste facilita las gestiones en este periodo de confinamiento<\/h5>\n<p><!--more--><\/p>\n<p>Polic\u00eda Municipal de Pamplona recomienda a aquellas personas que deban salir de sus domicilios para trabajar que lleven el certificado de empresa que lo acredite, aunque la normativa no obligue a ello. De esta forma, recalcan, se agilizan las gestiones si la persona o veh\u00edculo es detenido en alguno de los m\u00faltiples controles de tr\u00e1fico que se han extendido en los accesos de la ciudad para hacer cumplir las normas derivadas del Estado de Alarma, que incluyen, entre otras, el confinamiento de la poblaci\u00f3n en sus hogares.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>Portar ese documento, debidamente cumplimentado y firmado y sellado por la empresa, permitir\u00e1 facilitar los pasos que se llevan a cabo en estos controles. Por ello, en la p\u00e1gina web del Ayuntamiento de Pamplona se ha habilitado un modelo est\u00e1ndar de documento descargable, que las empresas pueden usar para certificar a sus empleados. Este certificado individual de necesidades de desplazamiento por motivos laborales debe incluir los datos la empresa y del trabajador o trabajadora, adem\u00e1s de la ubicaci\u00f3n de centro de trabajo y el horario habitual de la jornada laboral.<\/p>\n<p>Desde el pasado 16 de marzo, cuando entr\u00f3 en vigor el Estado de Alarma, la poblaci\u00f3n debe permanecer en sus hogares salvo si necesita acudir a sus puestos de trabajo o bien adquirir productos de primera necesidad, como alimentos y medicamentos, principalmente. Es por ello que, para hacer cumplir esta norma, los diferentes cuerpos y fuerzas de seguridad de Estado desarrollan estos d\u00edas controles intensivos de tr\u00e1fico. En principio, esta situaci\u00f3n se prolongar\u00e1 hasta el 12 de abril.<\/p>\n<p>El documento, un pdf editable, puede descargarse <a href=\"https:\/\/bit.ly\/2wu9w95\" target=\"_blank\" rel=\"noopener noreferrer\">aqu\u00ed<\/a> y tambi\u00e9n est\u00e1 disponible en la p\u00e1gina web <a href=\"http:\/\/www.pamplona.es\/coronavirus\" target=\"_blank\" rel=\"noopener noreferrer\">www.pamplona.es\/coronavirus<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque no es obligatorio llevar este certificado de necesidades de desplazamiento, \u00e9ste facilita las gestiones en este periodo de confinamiento<\/p>\n","protected":false},"author":1,"featured_media":29068,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-29066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Polic\u00eda Municipal recomienda llevar un certificado de trabajo para agilizar controles de tr\u00e1fico y habilita un formulario tipo en la web del Ayuntamiento<\/title>\n<meta name=\"description\" content=\"Aunque no es obligatorio llevar este certificado de necesidades de desplazamiento, \u00e9ste facilita las gestiones en este periodo de confinamiento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Polic\u00eda Municipal recomienda llevar un certificado de trabajo para agilizar controles de tr\u00e1fico y habilita un formulario tipo en la web del Ayuntamiento\" \/>\n<meta property=\"og:description\" content=\"Aunque no es obligatorio llevar este certificado de necesidades de desplazamiento, \u00e9ste facilita las gestiones en este periodo de confinamiento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-26T11:16:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/03\/certificado-desplazamiento-personal-laboral.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1896\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"Polic\u00eda Municipal recomienda llevar un certificado de trabajo para agilizar controles de tr\u00e1fico y habilita un formulario tipo en la web del Ayuntamiento\",\"datePublished\":\"2020-03-26T11:16:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\\\/\"},\"wordCount\":333,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/certificado-desplazamiento-personal-laboral.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\\\/\",\"name\":\"Polic\u00eda Municipal recomienda llevar un certificado de trabajo para agilizar controles de tr\u00e1fico y habilita un formulario tipo en la web del Ayuntamiento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/certificado-desplazamiento-personal-laboral.jpg\",\"datePublished\":\"2020-03-26T11:16:27+00:00\",\"description\":\"Aunque no es obligatorio llevar este certificado de necesidades de desplazamiento, \u00e9ste facilita las gestiones en este periodo de confinamiento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/certificado-desplazamiento-personal-laboral.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/certificado-desplazamiento-personal-laboral.jpg\",\"width\":1896,\"height\":933},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Polic\u00eda Municipal recomienda llevar un certificado de trabajo para agilizar controles de tr\u00e1fico y habilita un formulario tipo en la web del Ayuntamiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Polic\u00eda Municipal recomienda llevar un certificado de trabajo para agilizar controles de tr\u00e1fico y habilita un formulario tipo en la web del Ayuntamiento","description":"Aunque no es obligatorio llevar este certificado de necesidades de desplazamiento, \u00e9ste facilita las gestiones en este periodo de confinamiento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/","og_locale":"es_ES","og_type":"article","og_title":"Polic\u00eda Municipal recomienda llevar un certificado de trabajo para agilizar controles de tr\u00e1fico y habilita un formulario tipo en la web del Ayuntamiento","og_description":"Aunque no es obligatorio llevar este certificado de necesidades de desplazamiento, \u00e9ste facilita las gestiones en este periodo de confinamiento.","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-03-26T11:16:27+00:00","og_image":[{"width":1896,"height":933,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/03\/certificado-desplazamiento-personal-laboral.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"Polic\u00eda Municipal recomienda llevar un certificado de trabajo para agilizar controles de tr\u00e1fico y habilita un formulario tipo en la web del Ayuntamiento","datePublished":"2020-03-26T11:16:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/"},"wordCount":333,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/03\/certificado-desplazamiento-personal-laboral.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/","name":"Polic\u00eda Municipal recomienda llevar un certificado de trabajo para agilizar controles de tr\u00e1fico y habilita un formulario tipo en la web del Ayuntamiento","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/03\/certificado-desplazamiento-personal-laboral.jpg","datePublished":"2020-03-26T11:16:27+00:00","description":"Aunque no es obligatorio llevar este certificado de necesidades de desplazamiento, \u00e9ste facilita las gestiones en este periodo de confinamiento.","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/03\/certificado-desplazamiento-personal-laboral.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/03\/certificado-desplazamiento-personal-laboral.jpg","width":1896,"height":933},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/policia-municipal-recomienda-llevar-un-certificado-de-trabajo-para-agilizar-controles-de-trafico-y-habilita-un-formulario-tipo-en-la-web-del-ayuntamiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Polic\u00eda Municipal recomienda llevar un certificado de trabajo para agilizar controles de tr\u00e1fico y habilita un formulario tipo en la web del Ayuntamiento"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/29066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=29066"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/29066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/29068"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=29066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=29066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=29066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}