{"id":28910,"date":"2020-03-11T12:23:21","date_gmt":"2020-03-11T10:23:21","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=28910"},"modified":"2020-03-11T12:23:21","modified_gmt":"2020-03-11T10:23:21","slug":"hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/","title":{"rendered":"Hasta el 30 de abril se pueden presentar obras en el XIV Premio Internacional de Poes\u00eda \u2018Ciudad de Pamplona\u2019 que cuenta con modalidades en castellano y en euskera"},"content":{"rendered":"<h5>El premio est\u00e1 impulsado por Ayuntamiento de Pamplona y Ateneo Navarro y otorga premios de 3.000 euros en cada una de las modalidades<\/h5>\n<p><!--more--><\/p>\n<p>El 30 de abril, a las 14 horas, finaliza el plazo de presentaci\u00f3n de obras en el XIV Premio Internacional de Poes\u00eda \u2018Ciudad de Pamplona\u2019 impulsado por Ayuntamiento de Pamplona y Ateneo Navarro\/Nafar Ateneoa. Cuenta con modalidades en castellano y en euskera. Se repartir\u00e1n dos premios de 3.000 euros, uno en cada modalidad ling\u00fc\u00edstica. Pueden concursar todas las personas, cualquiera que sea su nacionalidad, siempre que las obras presentadas est\u00e9n escritas en castellano o en euskera.<\/p>\n<p>Para la puesta en marcha del certamen el Consistorio pamplon\u00e9s firma un convenio con el Ateneo navarro por el que asume un gasto de 6.000 euros destinado a los dos premios en met\u00e1lico. El objetivo es fomentar y difundir de la creaci\u00f3n literaria y promover a sus autores. En la edici\u00f3n del a\u00f1o pasado, Aitor Francos en castellano y Mikel Arruabarrena en euskera fueron los ganadores. El fallo del premio se har\u00e1 p\u00fablico durante el mes de junio, momento en el que tambi\u00e9n se dar\u00e1 a conocer la composici\u00f3n del jurado.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Trabajos in\u00e9ditos y no presentados en otros cert\u00e1menes<\/strong><\/p>\n<p>Los trabajos presentados a este certamen deber\u00e1n ser in\u00e9ditos en su totalidad, no haber obtenido ning\u00fan premio en otros concursos de poes\u00eda previamente fallados y no estar concursando en este momento en otro certamen po\u00e9tico. El tema y la forma ser\u00e1n libres, con una extensi\u00f3n de entre 400 y 800 versos. Las obras se presentar\u00e1n por cuadruplicado, en ejemplares separados, en tama\u00f1o DIN A-4, debidamente numeradas sus p\u00e1ginas y cosidas, grapadas o encuadernadas. Los poemas estar\u00e1n escritos a doble espacios y mecanografiadas por una sola cara. Las personas galardonadas en a\u00f1os precedentes no podr\u00e1n presentarse.<\/p>\n<p>Los originales podr\u00e1n presentarse por el sistema de lema y plica. En la portada han de llevar t\u00edtulo y lema. En un sobre cerrado adjunto constar\u00e1 la autor\u00eda, su nacionalidad, domicilio y una copia del documento de identificaci\u00f3n o de pasaporte, tel\u00e9fono de contacto y\/o correo electr\u00f3nico. Todo esto debe acompa\u00f1arse de una breve bibliograf\u00eda del autor o autora y de un documento certificando que dicha obra no se ha presentado a ning\u00fan otro certamen literario vigente. La obra enviada no podr\u00e1 retirarse en el transcurso del certamen.<\/p>\n<p>Las obras que se presenten deber\u00e1n enviarse por correo certificado al Ateneo Navarro (avda. Bara\u00f1\u00e1in 10 \u2013 1\u00aaA. 31008 Pamplona. Navarra), indicando en el sobre \u201cPara el XIII Premio Internacional de Poes\u00eda Ciudad de Pamplona\u201d. Tambi\u00e9n podr\u00e1n enviarse por correo electr\u00f3nico a la direcci\u00f3n <a href=\"mailto:ateneo@ateneonavarro.es\">ateneo@ateneonavarro.es<\/a>, en dos archivos adjuntos, uno con los datos relativos a la autor\u00eda y otro con la obra.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>366 poemarios presentados el a\u00f1o pasado<\/strong><\/p>\n<p>Al concurso se presentaron, en 2019, 366 poemarios, 357 en castellano y 9 en euskera, y como en a\u00f1os anteriores, sigui\u00f3 aumentando la participaci\u00f3n por internet. El 65% de las obras presentadas en castellano (230 de las 357) ten\u00edan una procedencia nacional y el 35% eran extranjeras. La autonom\u00eda con m\u00e1s obras presentadas fue Andaluc\u00eda con 39, seguida de Madrid con 3 y, Navarra con 23.<\/p>\n<p>Entre los poemarios recibidos desde el extranjero destacaron los 25 de Cuba y los 24 de Argentina. De las 9 obras recibidas en euskera, 5 proced\u00edan de Navarra, 3 de Gipuzkoa y una de Vizcaya. La duod\u00e9cima edici\u00f3n del certamen tuvo r\u00e9cord de presentaci\u00f3n de trabajos, tanto en la modalidad de castellano como en la euskera. En castellano se recibieron 405 poemarios y en euskera 22 obras.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El premio est\u00e1 impulsado por Ayuntamiento de Pamplona y Ateneo Navarro y otorga premios de 3.000 euros en cada una de las modalidades<\/p>\n","protected":false},"author":1,"featured_media":20915,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-28910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hasta el 30 de abril se pueden presentar obras en el XIV Premio Internacional de Poes\u00eda \u2018Ciudad de Pamplona\u2019 que cuenta con modalidades en castellano y en euskera<\/title>\n<meta name=\"description\" content=\"El premio est\u00e1 impulsado por Ayuntamiento de Pamplona y Ateneo Navarro y otorga premios de 3.000 euros en cada una de las modalidades.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hasta el 30 de abril se pueden presentar obras en el XIV Premio Internacional de Poes\u00eda \u2018Ciudad de Pamplona\u2019 que cuenta con modalidades en castellano y en euskera\" \/>\n<meta property=\"og:description\" content=\"El premio est\u00e1 impulsado por Ayuntamiento de Pamplona y Ateneo Navarro y otorga premios de 3.000 euros en cada una de las modalidades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-11T10:23:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/03\/19.03.21_bases_certamen_poesia_ciudad_pamplona-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1075\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"Hasta el 30 de abril se pueden presentar obras en el XIV Premio Internacional de Poes\u00eda \u2018Ciudad de Pamplona\u2019 que cuenta con modalidades en castellano y en euskera\",\"datePublished\":\"2020-03-11T10:23:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\\\/\"},\"wordCount\":643,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/19.03.21_bases_certamen_poesia_ciudad_pamplona-1.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\\\/\",\"name\":\"Hasta el 30 de abril se pueden presentar obras en el XIV Premio Internacional de Poes\u00eda \u2018Ciudad de Pamplona\u2019 que cuenta con modalidades en castellano y en euskera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/19.03.21_bases_certamen_poesia_ciudad_pamplona-1.jpg\",\"datePublished\":\"2020-03-11T10:23:21+00:00\",\"description\":\"El premio est\u00e1 impulsado por Ayuntamiento de Pamplona y Ateneo Navarro y otorga premios de 3.000 euros en cada una de las modalidades.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/19.03.21_bases_certamen_poesia_ciudad_pamplona-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/19.03.21_bases_certamen_poesia_ciudad_pamplona-1.jpg\",\"width\":1920,\"height\":1075},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hasta el 30 de abril se pueden presentar obras en el XIV Premio Internacional de Poes\u00eda \u2018Ciudad de Pamplona\u2019 que cuenta con modalidades en castellano y en euskera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hasta el 30 de abril se pueden presentar obras en el XIV Premio Internacional de Poes\u00eda \u2018Ciudad de Pamplona\u2019 que cuenta con modalidades en castellano y en euskera","description":"El premio est\u00e1 impulsado por Ayuntamiento de Pamplona y Ateneo Navarro y otorga premios de 3.000 euros en cada una de las modalidades.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/","og_locale":"es_ES","og_type":"article","og_title":"Hasta el 30 de abril se pueden presentar obras en el XIV Premio Internacional de Poes\u00eda \u2018Ciudad de Pamplona\u2019 que cuenta con modalidades en castellano y en euskera","og_description":"El premio est\u00e1 impulsado por Ayuntamiento de Pamplona y Ateneo Navarro y otorga premios de 3.000 euros en cada una de las modalidades.","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-03-11T10:23:21+00:00","og_image":[{"width":1920,"height":1075,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/03\/19.03.21_bases_certamen_poesia_ciudad_pamplona-1.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"Hasta el 30 de abril se pueden presentar obras en el XIV Premio Internacional de Poes\u00eda \u2018Ciudad de Pamplona\u2019 que cuenta con modalidades en castellano y en euskera","datePublished":"2020-03-11T10:23:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/"},"wordCount":643,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/03\/19.03.21_bases_certamen_poesia_ciudad_pamplona-1.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/","name":"Hasta el 30 de abril se pueden presentar obras en el XIV Premio Internacional de Poes\u00eda \u2018Ciudad de Pamplona\u2019 que cuenta con modalidades en castellano y en euskera","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/03\/19.03.21_bases_certamen_poesia_ciudad_pamplona-1.jpg","datePublished":"2020-03-11T10:23:21+00:00","description":"El premio est\u00e1 impulsado por Ayuntamiento de Pamplona y Ateneo Navarro y otorga premios de 3.000 euros en cada una de las modalidades.","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/03\/19.03.21_bases_certamen_poesia_ciudad_pamplona-1.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/03\/19.03.21_bases_certamen_poesia_ciudad_pamplona-1.jpg","width":1920,"height":1075},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/hasta-el-30-de-abril-se-pueden-presentar-obras-en-el-xiv-premio-internacional-de-poesia-ciudad-de-pamplona-que-cuenta-con-modalidades-en-castellano-y-en-euskera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Hasta el 30 de abril se pueden presentar obras en el XIV Premio Internacional de Poes\u00eda \u2018Ciudad de Pamplona\u2019 que cuenta con modalidades en castellano y en euskera"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/28910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=28910"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/28910\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/20915"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=28910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=28910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=28910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}