{"id":28577,"date":"2020-02-28T13:50:17","date_gmt":"2020-02-28T11:50:17","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=28577"},"modified":"2020-02-28T13:51:10","modified_gmt":"2020-02-28T11:51:10","slug":"la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/","title":{"rendered":"La Escuela Catalina de Osc\u00e1riz oferta dos talleres de pintura y dibujo para el \u00faltimo trimestre del curso"},"content":{"rendered":"<h5>Las actividades, dirigidas a mayores de 16 a\u00f1os, dar\u00e1n comienzo la \u00faltima semana de marzo y se prolongar\u00e1n hasta mediados de junio<\/h5>\n<p><!--more--><\/p>\n<p>La Escuela Municipal de Artes y Oficios Catalina de Osc\u00e1riz ha programado dos talleres de pintura y dibujo para el \u00faltimo trimestre del curso 2019\/2020. Las actividades, enmarcadas en las propuestas educativas del Ayuntamiento de Pamplona, est\u00e1n dirigidas a mayores de 16 a\u00f1os y se desarrollar\u00e1n desde finales de marzo hasta mediados de junio. Las personas interesadas deber\u00e1n formalizar la inscripci\u00f3n entre el 2 y el 23 de marzo. Los talleres tendr\u00e1n un coste de 48,55 euros.<\/p>\n<p>En concreto, la escuela impartir\u00e1 el taller \u2018Dibujo y pintura r\u00e1pidos\u2019, centrado en la realizaci\u00f3n de apuntes y esbozos r\u00e1pidos, como garabateo, dibujo autom\u00e1tico, dibujo precipitado, pintura directa o pintura \u2018alla prima\u2019. El curso se desarrollar\u00e1 durante dos horas diarias los martes y los jueves, desde el 31 de marzo hasta el 18 de junio. Se ha previsto la constituci\u00f3n de dos grupos, uno de 17 a 19 horas y otro de 19 a 21 horas.<\/p>\n<p>En esos mismos horarios, tambi\u00e9n en dos grupos, pero los lunes y los mi\u00e9rcoles, se ofertar\u00e1 un taller de pintura centrado en el \u2018Paisaje urbano y paisaje rural\u2019. En esta ocasi\u00f3n, se trabajar\u00e1 sobre edificios y detalles arquitect\u00f3nicos como paisaje, profundizando en distintos recursos y estilos pl\u00e1sticos. El alumnado de este taller recibir\u00e1 formaci\u00f3n sobre perspectiva a\u00e9rea y lineal, sobre composici\u00f3n y sobre color. Este taller dar\u00e1 comienzo el 30 de marzo y concluir\u00e1 el 17 de junio.<\/p>\n<p>La inscripci\u00f3n a los talleres podr\u00e1 realizarse llamando al tel\u00e9fono de informaci\u00f3n municipal 010 (\u00f3 948 420 100 si llama desde fuera de Pamplona). Para poder optar a ambos cursos, es imprescindible contar con conocimientos b\u00e1sicos de dibujo y pintura.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>M\u00e1ximo 20 alumnos por grupo<\/strong><\/p>\n<p>Para el correcto desarrollo de las actividades, se ha previsto un n\u00famero m\u00e1ximo de alumnado de 20 personas por cada grupo, en total 40 plazas por taller. En caso de que se agoten las plazas, se elaborar\u00e1 una lista de espera con quienes no hayan podido acceder al curso, por si se generaran vacantes. Igualmente, quedar\u00e1n en lista de espera en uno de los talleres las personas que se inscriban a los dos a la vez.<\/p>\n<p>Una vez confirmada la plaza, ser\u00e1 necesario entregar los justificantes de pago en el \u00c1rea de Educaci\u00f3n y Cultura del Ayuntamiento (ubicada en la calle Descalzos, 72, 3\u00aa planta). Aunque el precio del taller es de 48,55 euros, existen reducciones en la matr\u00edcula en distintos supuestos, tal y como se recoge en las Ordenanzas Fiscales del Consistorio. En concreto, se prev\u00e9n reducciones del 50% y del 100% en funci\u00f3n de si se trata de familias numerosas de categor\u00eda general o especial, familias monoparentales, personas con discapacidad reconocida igual o superior al 33%, v\u00edctimas de violencia de g\u00e9nero, v\u00edctimas de terrorismo, por acogimiento familiar, y por tener unos ingresos familiares iguales o inferiores al 200% de la Renta de Inclusi\u00f3n Social o prestaci\u00f3n equivalente.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #ff0000;\">Talleres de Dibujo y Pintura<\/span><\/h3>\n<ul>\n<li><strong>Talleres:<\/strong>\n<ul>\n<li>\u201cDibujo y Pintura r\u00e1pidos\u201d: Del 31 de marzo al 18 de junio, los martes y jueves. De 17 a 19 horas o de 19 a 21 horas.<\/li>\n<li>\u201cPaisaje urbano y paisaje rural\u201d: Del 30 de marzo al 17 de junio, los lunes y mi\u00e9rcoles. De 17 a 19 horas o de 19 a 21 horas.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Requisitos:<\/strong> Ser mayor de 16 a\u00f1os y tener conocimientos previos de dibujo y pintura.<\/li>\n<li><strong>Inscripci\u00f3n:<\/strong> Desde el 2 hasta el 23 de marzo, en el tel\u00e9fono 010 de informaci\u00f3n municipal (\u00f3 948 420 100 si llama desde fuera de Pamplona).<\/li>\n<li><strong>Precio:<\/strong> 48,55 euros, si bien existen diferentes reducciones.<\/li>\n<li><strong>D\u00f3nde:<\/strong> Las clases se impartir\u00e1n en la Escuela Municipal de Artes y Oficios Catalina de Osc\u00e1riz, ubicada en los locales del antiguo Colegio P\u00fablico Jos\u00e9 Vila, en la calle Tajonar, n\u00famero 14.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las actividades, dirigidas a mayores de 16 a\u00f1os, dar\u00e1n comienzo la \u00faltima semana de marzo y se prolongar\u00e1n hasta mediados de junio<\/p>\n","protected":false},"author":1,"featured_media":25006,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-28577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Escuela Catalina de Osc\u00e1riz oferta dos talleres de pintura y dibujo para el \u00faltimo trimestre del curso<\/title>\n<meta name=\"description\" content=\"Las actividades, dirigidas a mayores de 16 a\u00f1os, dar\u00e1n comienzo la \u00faltima semana de marzo y se prolongar\u00e1n hasta mediados de junio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Escuela Catalina de Osc\u00e1riz oferta dos talleres de pintura y dibujo para el \u00faltimo trimestre del curso\" \/>\n<meta property=\"og:description\" content=\"Las actividades, dirigidas a mayores de 16 a\u00f1os, dar\u00e1n comienzo la \u00faltima semana de marzo y se prolongar\u00e1n hasta mediados de junio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-28T11:50:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-28T11:51:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.08_visita_unidad_barrio_milagrosa_escuela_arte_catalina_oscariz1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"La Escuela Catalina de Osc\u00e1riz oferta dos talleres de pintura y dibujo para el \u00faltimo trimestre del curso\",\"datePublished\":\"2020-02-28T11:50:17+00:00\",\"dateModified\":\"2020-02-28T11:51:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\\\/\"},\"wordCount\":660,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/19.10.08_visita_unidad_barrio_milagrosa_escuela_arte_catalina_oscariz1.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\\\/\",\"name\":\"La Escuela Catalina de Osc\u00e1riz oferta dos talleres de pintura y dibujo para el \u00faltimo trimestre del curso\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/19.10.08_visita_unidad_barrio_milagrosa_escuela_arte_catalina_oscariz1.jpg\",\"datePublished\":\"2020-02-28T11:50:17+00:00\",\"dateModified\":\"2020-02-28T11:51:10+00:00\",\"description\":\"Las actividades, dirigidas a mayores de 16 a\u00f1os, dar\u00e1n comienzo la \u00faltima semana de marzo y se prolongar\u00e1n hasta mediados de junio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/19.10.08_visita_unidad_barrio_milagrosa_escuela_arte_catalina_oscariz1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/19.10.08_visita_unidad_barrio_milagrosa_escuela_arte_catalina_oscariz1.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"A* Jes\u00fas M Garzaron\\\/Ayuntamiento de Pamplona F* 2019_10_08 T* Visita de la comisi\u00f3n a la Unidad de Barrio de la Milagrosa L* Unidad de Barrio de la Milagrosa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Escuela Catalina de Osc\u00e1riz oferta dos talleres de pintura y dibujo para el \u00faltimo trimestre del curso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Escuela Catalina de Osc\u00e1riz oferta dos talleres de pintura y dibujo para el \u00faltimo trimestre del curso","description":"Las actividades, dirigidas a mayores de 16 a\u00f1os, dar\u00e1n comienzo la \u00faltima semana de marzo y se prolongar\u00e1n hasta mediados de junio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/","og_locale":"es_ES","og_type":"article","og_title":"La Escuela Catalina de Osc\u00e1riz oferta dos talleres de pintura y dibujo para el \u00faltimo trimestre del curso","og_description":"Las actividades, dirigidas a mayores de 16 a\u00f1os, dar\u00e1n comienzo la \u00faltima semana de marzo y se prolongar\u00e1n hasta mediados de junio.","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-02-28T11:50:17+00:00","article_modified_time":"2020-02-28T11:51:10+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.08_visita_unidad_barrio_milagrosa_escuela_arte_catalina_oscariz1.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"La Escuela Catalina de Osc\u00e1riz oferta dos talleres de pintura y dibujo para el \u00faltimo trimestre del curso","datePublished":"2020-02-28T11:50:17+00:00","dateModified":"2020-02-28T11:51:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/"},"wordCount":660,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.08_visita_unidad_barrio_milagrosa_escuela_arte_catalina_oscariz1.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/","name":"La Escuela Catalina de Osc\u00e1riz oferta dos talleres de pintura y dibujo para el \u00faltimo trimestre del curso","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.08_visita_unidad_barrio_milagrosa_escuela_arte_catalina_oscariz1.jpg","datePublished":"2020-02-28T11:50:17+00:00","dateModified":"2020-02-28T11:51:10+00:00","description":"Las actividades, dirigidas a mayores de 16 a\u00f1os, dar\u00e1n comienzo la \u00faltima semana de marzo y se prolongar\u00e1n hasta mediados de junio.","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.08_visita_unidad_barrio_milagrosa_escuela_arte_catalina_oscariz1.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.08_visita_unidad_barrio_milagrosa_escuela_arte_catalina_oscariz1.jpg","width":1920,"height":1280,"caption":"A* Jes\u00fas M Garzaron\/Ayuntamiento de Pamplona F* 2019_10_08 T* Visita de la comisi\u00f3n a la Unidad de Barrio de la Milagrosa L* Unidad de Barrio de la Milagrosa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-escuela-catalina-de-oscariz-oferta-dos-talleres-de-pintura-y-dibujo-para-el-ultimo-trimestre-del-curso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"La Escuela Catalina de Osc\u00e1riz oferta dos talleres de pintura y dibujo para el \u00faltimo trimestre del curso"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/28577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=28577"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/28577\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/25006"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=28577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=28577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=28577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}