{"id":28281,"date":"2020-02-18T17:57:47","date_gmt":"2020-02-18T15:57:47","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=28281"},"modified":"2020-02-18T17:57:47","modified_gmt":"2020-02-18T15:57:47","slug":"la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/","title":{"rendered":"La renovada Unidad de Barrio de San Juan de la calle Monasterio de Tulebras volver\u00e1 a atender a los usuarios el pr\u00f3ximo lunes, d\u00eda 24"},"content":{"rendered":"<h5>Durante los casi nueve meses que han durado las obras de ampliaci\u00f3n, la Unidad de Barrio se hab\u00eda trasladado a un local en la avenida de Bayona<\/h5>\n<p><!--more--><\/p>\n<p>La Unidad de Barrio de San Juan volver\u00e1 a su ubicaci\u00f3n original en la calle Monasterio de Tulebras n\u00famero 3 el pr\u00f3ximo lunes, d\u00eda 24, despu\u00e9s de las obras de mejora y ampliaci\u00f3n que se han llevado a cabo en el local. Ma\u00f1ana ser\u00e1 el \u00faltimo d\u00eda que atienda en el local provisional de la avenida Bayona. Las atenciones los d\u00edas 20 y 21 se har\u00e1n v\u00eda telef\u00f3nica, en el 948 420 782. La Comisi\u00f3n de Asuntos Ciudadanos del Ayuntamiento de Pamplona han visitado hoy las reformadas instalaciones, que ocupan m\u00e1s de 230 metros cuadrados en la planta baja del edificio municipal de apartamentos tutelados de San Juan, conocido como Txoko Berri.<\/p>\n<p>Las obras de reforma supusieron el traslado provisi\u00f3n de la Unidad de Barrio a un local en la avenida de Bayona, donde ha atendido a los usuarios desde comienzos del mes de junio hasta ma\u00f1ana mi\u00e9rcoles. En este tiempo, las dependencias de la calle Monasterio de Tulebras han sufrido una importante transformaci\u00f3n. Sin duda el cambio m\u00e1s importante es la ampliaci\u00f3n de espacios, ya que este servicio municipal ha pasado de contar con 132,90 m\u00b2 \u00fatiles a 231,40 m\u00b2. Esto ha sido posible gracias a la incorporaci\u00f3n del porche abierto de acceso como zona de trabajo, con un total de 113,50 metros cuadrados. Esta ampliaci\u00f3n ha supuesto modificar el acceso a los apartamentos.<\/p>\n<p>Con un presupuesto total de 224.000 euros, las obras han permitido mejorar la zona de acceso y administraci\u00f3n, as\u00ed como crear siete despachos de trabajadores sociales, una sala de reuniones, aseos y un cuarto de limpieza. Todos los espacios generados cuenten con ventilaci\u00f3n e iluminaci\u00f3n natural. La Unidad de Barrio ha sido remodelada al completo, tras proceder al vaciado de las instalaciones, la retirada de los pavimentos tanto interiores como del porche, las carpinter\u00edas exteriores e interiores, tabiques, falsos techos y los revestimientos. As\u00ed, la nueva Unidad cuenta con una rampa de acceso para salvar el desnivel existente entre la calle peatonal y el interior del edificio. Adem\u00e1s, se ha instalado una cancela con doble puerta autom\u00e1tica que da acceso a la zona de recepci\u00f3n. El interior se articula en torno a un espacio central de espera y comunicaci\u00f3n.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Contratos de Empleo Social<\/strong><\/p>\n<p>Las obras han sido realizadas con cargo a la convocatoria de Obras de Inter\u00e9s General y Social del Servicio Navarro de Empleo. Para ello, se ha contratado a siete personas en situaci\u00f3n de vulnerabilidad, bien por ser mayores de 45 a\u00f1os, perceptores de renta garantizada o mujer. En concreto, se ha contratado a una arquitecta t\u00e9cnica a media jornada, a un encargado de obras mayores de 45 a\u00f1os, a tres oficiales y dos peones de alba\u00f1iler\u00eda, todos ellos perceptores de renta garantizada. La contrataci\u00f3n de estas personas ha supuesto para el Ayuntamiento de Pamplona un coste de 101.039 euros, si bien el SNE ha subvencionado alrededor de un 40% de este importe.<\/p>\n<p>Las Unidades de Barrio del Ayuntamiento de Pamplona son la\u00a0<strong>puerta de entrada<\/strong><strong>\u00a0<\/strong>al sistema de Servicios Sociales. Ubicadas en los distintos barrios de la ciudad, cuentan con cuatro programas de atenci\u00f3n primaria: acogida y orientaci\u00f3n social; autonom\u00eda personas y atenci\u00f3n a personas en situaci\u00f3n de dependencia; incorporaci\u00f3n social, y atenci\u00f3n a la infancia y la familia. La Unidad de San Juan ofrecer\u00e1 estos servicios a trav\u00e9s de una plantilla de ocho personas, entre las que est\u00e1n una administrativa, dos personas tituladas superiores en Integraci\u00f3n Social y cinco trabajadoras sociales. Dos de estos profesionales (una trabajadora social y un titulado en Integraci\u00f3n Social) se incorporaron en 2019 en una apuesta por reforzar el servicio de la Unidad.<\/p>\n<p>En total, del a\u00f1o pasado 938 personas fueron beneficiarias de Renta Garantizada, de las que 311 eran menores de edad. \u00a0Se tramitaron 329 PIAS o valoraciones a personas mayores para garantizar el acceso a las prestaciones reguladas por la ley de Promoci\u00f3n de la Autonom\u00eda Personal y Atenci\u00f3n a las personas en situaci\u00f3n de dependencia de 2006. Adem\u00e1s, se concedieron 85 ayudas de emergencia. El n\u00famero de usuarios de Servicio de Atenci\u00f3n Domiciliaria ascendi\u00f3 a 62 personas y del servicio Provivienda, a 17. \u00a0De media, la Unidad de Barrio de San Juan atiende a 48 personas al d\u00eda.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Un barrio envejecido<\/strong><\/p>\n<p>El barrio de San Juan impuls\u00f3 en marzo de 2018 el Pacto por la Persona Mayor, una iniciativa social para promover mejoras en la calidad de vida del barrio, donde m\u00e1s del 30% de sus habitantes tiene m\u00e1s de 65 a\u00f1os. De hecho, de las 20.323 personas censadas en el barrio, 6.468 son mayores de 65 a\u00f1os (31,8%). De todas ellas, 3.994 son mujeres y 2.474 hombres.<\/p>\n<p>Promovido por el centro de salud del barrio, a esta propuesta se sum\u00f3 tambi\u00e9n el Ayuntamiento de Pamplona, as\u00ed como diversas entidades y organizaciones de la zona, unidas en el compromiso de trabajar conjuntamente en la promoci\u00f3n del envejecimiento activo y saludable. El objetivo es trabajar conjuntamente para abordar tres pilares claves del envejecimiento: la salud, la participaci\u00f3n y la seguridad de las personas mayores.<\/p>\n<p>El Consistorio participa activamente en distintas actividades y propuestas, a trav\u00e9s de diferentes \u00e1reas. La Unidad de Barrio, a trav\u00e9s de la trabajadora social del programa de Autonom\u00eda, juega un papel importante en el desarrollo de este Pacto por la Persona Mayor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante los casi nueve meses que han durado las obras de ampliaci\u00f3n, la Unidad de Barrio se hab\u00eda trasladado a un local en la avenida de Bayona<\/p>\n","protected":false},"author":1,"featured_media":28283,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-28281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La renovada Unidad de Barrio de San Juan de la calle Monasterio de Tulebras volver\u00e1 a atender a los usuarios el pr\u00f3ximo lunes, d\u00eda 24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La renovada Unidad de Barrio de San Juan de la calle Monasterio de Tulebras volver\u00e1 a atender a los usuarios el pr\u00f3ximo lunes, d\u00eda 24\" \/>\n<meta property=\"og:description\" content=\"Durante los casi nueve meses que han durado las obras de ampliaci\u00f3n, la Unidad de Barrio se hab\u00eda trasladado a un local en la avenida de Bayona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-18T15:57:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/02\/20.02.18_CMC_visita_unidad_barrio_sanjuan1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"La renovada Unidad de Barrio de San Juan de la calle Monasterio de Tulebras volver\u00e1 a atender a los usuarios el pr\u00f3ximo lunes, d\u00eda 24\",\"datePublished\":\"2020-02-18T15:57:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\\\/\"},\"wordCount\":961,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/20.02.18_CMC_visita_unidad_barrio_sanjuan1.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\\\/\",\"name\":\"La renovada Unidad de Barrio de San Juan de la calle Monasterio de Tulebras volver\u00e1 a atender a los usuarios el pr\u00f3ximo lunes, d\u00eda 24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/20.02.18_CMC_visita_unidad_barrio_sanjuan1.jpg\",\"datePublished\":\"2020-02-18T15:57:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/20.02.18_CMC_visita_unidad_barrio_sanjuan1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/20.02.18_CMC_visita_unidad_barrio_sanjuan1.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"A* Jes\u00fas Garzaron\\\/Ayuntamiento de Pamplona F* 2020_02_18 T* Visita de la comisi\u00f3n a la Unidad de Barrio de San Juan L* Calle M\u00ba Tulebras 3, bajo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La renovada Unidad de Barrio de San Juan de la calle Monasterio de Tulebras volver\u00e1 a atender a los usuarios el pr\u00f3ximo lunes, d\u00eda 24\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La renovada Unidad de Barrio de San Juan de la calle Monasterio de Tulebras volver\u00e1 a atender a los usuarios el pr\u00f3ximo lunes, d\u00eda 24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/","og_locale":"es_ES","og_type":"article","og_title":"La renovada Unidad de Barrio de San Juan de la calle Monasterio de Tulebras volver\u00e1 a atender a los usuarios el pr\u00f3ximo lunes, d\u00eda 24","og_description":"Durante los casi nueve meses que han durado las obras de ampliaci\u00f3n, la Unidad de Barrio se hab\u00eda trasladado a un local en la avenida de Bayona","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-02-18T15:57:47+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/02\/20.02.18_CMC_visita_unidad_barrio_sanjuan1.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"La renovada Unidad de Barrio de San Juan de la calle Monasterio de Tulebras volver\u00e1 a atender a los usuarios el pr\u00f3ximo lunes, d\u00eda 24","datePublished":"2020-02-18T15:57:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/"},"wordCount":961,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/02\/20.02.18_CMC_visita_unidad_barrio_sanjuan1.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/","name":"La renovada Unidad de Barrio de San Juan de la calle Monasterio de Tulebras volver\u00e1 a atender a los usuarios el pr\u00f3ximo lunes, d\u00eda 24","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/02\/20.02.18_CMC_visita_unidad_barrio_sanjuan1.jpg","datePublished":"2020-02-18T15:57:47+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/02\/20.02.18_CMC_visita_unidad_barrio_sanjuan1.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/02\/20.02.18_CMC_visita_unidad_barrio_sanjuan1.jpg","width":1920,"height":1280,"caption":"A* Jes\u00fas Garzaron\/Ayuntamiento de Pamplona F* 2020_02_18 T* Visita de la comisi\u00f3n a la Unidad de Barrio de San Juan L* Calle M\u00ba Tulebras 3, bajo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/la-renovada-unidad-de-barrio-de-san-juan-de-la-calle-monasterio-de-tulebras-volvera-a-atender-a-los-usuarios-el-proximo-lunes-dia-24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"La renovada Unidad de Barrio de San Juan de la calle Monasterio de Tulebras volver\u00e1 a atender a los usuarios el pr\u00f3ximo lunes, d\u00eda 24"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/28281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=28281"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/28281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/28283"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=28281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=28281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=28281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}