{"id":28197,"date":"2020-02-14T19:21:17","date_gmt":"2020-02-14T17:21:17","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=28197"},"modified":"2020-02-14T19:21:17","modified_gmt":"2020-02-14T17:21:17","slug":"el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/","title":{"rendered":"El alcalde recibe a la Fundaci\u00f3n Remonte Euskal Jai Berri de la que el Ayuntamiento de Pamplona es patrono"},"content":{"rendered":"<p><!--more--><\/p>\n<p>El alcalde de Pamplona, Enrique Maya, se ha reunido hoy por la ma\u00f1ana con la Fundaci\u00f3n Remonte Euskal Jai Berri de la que el Ayuntamiento de Pamplona es patrono como forma de apoyo a esta modalidad deportiva de origen pamplon\u00e9s. En el encuentro han participado el director gerente de la fundaci\u00f3n, Jaime Aguirre, y la concejala delegada de Servicios Sociales, Acci\u00f3n Comunitaria y Deporte, Mar\u00eda Caballero.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>El Consistorio pamplon\u00e9s viene firmando los \u00faltimos a\u00f1os un contrato de patrocinio publicitario con la fundaci\u00f3n para la organizaci\u00f3n de determinados eventos de remonte cada a\u00f1o. Por ejemplo, durante 2019, se encarg\u00f3 de poner en marcha el VI Torneo de remonte Casco Viejo de Pamplona. El importe del contrato ascendi\u00f3 a 5.000 euros (IVA incluido). Adem\u00e1s, tambi\u00e9n es apoyada por otras v\u00edas, como el uso preferente que tiene del Front\u00f3n Labrit para determinados festivales de esta modalidad de pelota.<\/p>\n<p>La Fundaci\u00f3n Remonte Euskal Jai Berri fue constituida en 2004 para reimpulsar el remonte, una modalidad de pelota inventada en Pamplona a principios del siglo XX y que se extendi\u00f3 a otras comunidades antes de comenzar con su retroceso posterior. Su origen se atribuye a Juanito Moya, un aficionado nacido en la calle Tejer\u00eda que ide\u00f3 una nueva cesta que enviaba con m\u00e1s fuerza la pelota que los viejos guantes de cuero, sin detenerla en la cesta. As\u00ed, en 1904 empez\u00f3 a jugarse en frontones de grandes dimensiones, en el caso de Pamplona, en la cancha del Juego Nuevo.<\/p>\n<p>Adem\u00e1s de impulsar torneos y campeonatos y de divulgar este deporte, pone en marcha escuelas deportivas y mantiene relaciones con otras entidades, como, por ejemplo, con el Gobierno de Navarra para trasladar la oferta tur\u00edstica y gastron\u00f3mica de Navarrra en sus actividades o con la Asociaci\u00f3n de ayuda a Ni\u00f1os con C\u00e1ncer de Navarra (ADANO), que recibe la recaudaci\u00f3n obtenida en rifas y sorteos de las finales de los torneos.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":28199,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-28197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El alcalde recibe a la Fundaci\u00f3n Remonte Euskal Jai Berri de la que el Ayuntamiento de Pamplona es patrono<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El alcalde recibe a la Fundaci\u00f3n Remonte Euskal Jai Berri de la que el Ayuntamiento de Pamplona es patrono\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-14T17:21:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/02\/20.02.14_reunion_fundacion_remonte_eukal_jai_berri_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El alcalde recibe a la Fundaci\u00f3n Remonte Euskal Jai Berri de la que el Ayuntamiento de Pamplona es patrono\",\"datePublished\":\"2020-02-14T17:21:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\\\/\"},\"wordCount\":355,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/20.02.14_reunion_fundacion_remonte_eukal_jai_berri_1.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\\\/\",\"name\":\"El alcalde recibe a la Fundaci\u00f3n Remonte Euskal Jai Berri de la que el Ayuntamiento de Pamplona es patrono\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/20.02.14_reunion_fundacion_remonte_eukal_jai_berri_1.jpg\",\"datePublished\":\"2020-02-14T17:21:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/20.02.14_reunion_fundacion_remonte_eukal_jai_berri_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/20.02.14_reunion_fundacion_remonte_eukal_jai_berri_1.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"A* Jes\u00fas Garzaron\\\/Ayuntamiento Pamplona F* 2020_02_14 T* Reuni\u00f3n con la Fundaci\u00f3n de Remonte Euskal Jai Berri L* Despacho alcalde\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El alcalde recibe a la Fundaci\u00f3n Remonte Euskal Jai Berri de la que el Ayuntamiento de Pamplona es patrono\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El alcalde recibe a la Fundaci\u00f3n Remonte Euskal Jai Berri de la que el Ayuntamiento de Pamplona es patrono","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/","og_locale":"es_ES","og_type":"article","og_title":"El alcalde recibe a la Fundaci\u00f3n Remonte Euskal Jai Berri de la que el Ayuntamiento de Pamplona es patrono","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-02-14T17:21:17+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/02\/20.02.14_reunion_fundacion_remonte_eukal_jai_berri_1.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El alcalde recibe a la Fundaci\u00f3n Remonte Euskal Jai Berri de la que el Ayuntamiento de Pamplona es patrono","datePublished":"2020-02-14T17:21:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/"},"wordCount":355,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/02\/20.02.14_reunion_fundacion_remonte_eukal_jai_berri_1.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/","name":"El alcalde recibe a la Fundaci\u00f3n Remonte Euskal Jai Berri de la que el Ayuntamiento de Pamplona es patrono","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/02\/20.02.14_reunion_fundacion_remonte_eukal_jai_berri_1.jpg","datePublished":"2020-02-14T17:21:17+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/02\/20.02.14_reunion_fundacion_remonte_eukal_jai_berri_1.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2020\/02\/20.02.14_reunion_fundacion_remonte_eukal_jai_berri_1.jpg","width":1920,"height":1280,"caption":"A* Jes\u00fas Garzaron\/Ayuntamiento Pamplona F* 2020_02_14 T* Reuni\u00f3n con la Fundaci\u00f3n de Remonte Euskal Jai Berri L* Despacho alcalde"},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-alcalde-recibe-a-la-fundacion-remonte-euskal-jai-berri-de-la-que-el-ayuntamiento-de-pamplona-es-patrono\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El alcalde recibe a la Fundaci\u00f3n Remonte Euskal Jai Berri de la que el Ayuntamiento de Pamplona es patrono"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/28197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=28197"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/28197\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/28199"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=28197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=28197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=28197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}