{"id":27795,"date":"2020-01-29T14:03:15","date_gmt":"2020-01-29T12:03:15","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=27795"},"modified":"2020-01-29T14:03:15","modified_gmt":"2020-01-29T12:03:15","slug":"el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/","title":{"rendered":"El Ayuntamiento se compromete a eliminar las plazas de aparcamiento frente a los comercios de la calle San Francisco y a redactar un proyecto para su peatonalizaci\u00f3n"},"content":{"rendered":"<p><!--more--><\/p>\n<p>La Comisi\u00f3n de Urbanismo del Ayuntamiento de Pamplona ha aprobado por unanimidad una declaraci\u00f3n, presentada por el grupo municipal de EH Bildu, para la peatonalizaci\u00f3n de la calle San Francisco. En un primer punto, la declaraci\u00f3n acuerda \u201cinstar al equipo de gobierno a que, con la mayor brevedad, evite el estacionamiento frente a los comercios existentes en la calle San Francisco, mediante la se\u00f1al\u00e9tica que el \u00e1rea de Seguridad Ciudadana vea m\u00e1s conveniente\u201d.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>En un segundo punto, el texto insta tambi\u00e9n al equipo de gobierno a que, \u201cen los pr\u00f3ximos meses, se encargue mediante licitaci\u00f3n o mediante el equipo t\u00e9cnico municipal correspondiente, la redacci\u00f3n de un proyecto de reurbanizaci\u00f3n y peatonalizaci\u00f3n de la calle San Francisco\u201d.<\/p>\n<p>&nbsp;<br \/>\n[qodef_button size=\u00bblarge\u00bb type=\u00bb\u00bb text=\u00bbDeclaraci\u00f3n peatonalizaci\u00f3n San Francisco.pdf\u00bb custom_class=\u00bb\u00bb icon_pack=\u00bbfont_elegant\u00bb fa_icon=\u00bbicon_download\u00bb link=\u00bbhttps:\/\/www.laguiadepamplona.es\/actualidad\/wp-content\/uploads\/2020\/01\/20.01.29_CMU_declaracion_peatonalizacion_sanfrancisco.pdf\u00bb target=\u00bb_blank\u00bb color=\u00bbffffff\u00bb hover_color=\u00bb\u00bb background_color=\u00bb\u00bb hover_background_color=\u00bb\u00bb border_color=\u00bb\u00bb hover_border_color=\u00bb\u00bb font_size=\u00bb\u00bb font_weight=\u00bb\u00bb margin=\u00bb\u00bb]\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":21939,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Ayuntamiento se compromete a eliminar las plazas de aparcamiento frente a los comercios de la calle San Francisco y a redactar un proyecto para su peatonalizaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Ayuntamiento se compromete a eliminar las plazas de aparcamiento frente a los comercios de la calle San Francisco y a redactar un proyecto para su peatonalizaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-29T12:03:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El Ayuntamiento se compromete a eliminar las plazas de aparcamiento frente a los comercios de la calle San Francisco y a redactar un proyecto para su peatonalizaci\u00f3n\",\"datePublished\":\"2020-01-29T12:03:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\\\/\"},\"wordCount\":217,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\\\/\",\"name\":\"El Ayuntamiento se compromete a eliminar las plazas de aparcamiento frente a los comercios de la calle San Francisco y a redactar un proyecto para su peatonalizaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"datePublished\":\"2020-01-29T12:03:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"width\":1920,\"height\":1100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Ayuntamiento se compromete a eliminar las plazas de aparcamiento frente a los comercios de la calle San Francisco y a redactar un proyecto para su peatonalizaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Ayuntamiento se compromete a eliminar las plazas de aparcamiento frente a los comercios de la calle San Francisco y a redactar un proyecto para su peatonalizaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/","og_locale":"es_ES","og_type":"article","og_title":"El Ayuntamiento se compromete a eliminar las plazas de aparcamiento frente a los comercios de la calle San Francisco y a redactar un proyecto para su peatonalizaci\u00f3n","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-01-29T12:03:15+00:00","og_image":[{"width":1920,"height":1100,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El Ayuntamiento se compromete a eliminar las plazas de aparcamiento frente a los comercios de la calle San Francisco y a redactar un proyecto para su peatonalizaci\u00f3n","datePublished":"2020-01-29T12:03:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/"},"wordCount":217,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/","name":"El Ayuntamiento se compromete a eliminar las plazas de aparcamiento frente a los comercios de la calle San Francisco y a redactar un proyecto para su peatonalizaci\u00f3n","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","datePublished":"2020-01-29T12:03:15+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","width":1920,"height":1100},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-se-compromete-a-eliminar-las-plazas-de-aparcamiento-frente-a-los-comercios-de-la-calle-san-francisco-y-a-redactar-un-proyecto-para-su-peatonalizacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El Ayuntamiento se compromete a eliminar las plazas de aparcamiento frente a los comercios de la calle San Francisco y a redactar un proyecto para su peatonalizaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/27795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=27795"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/27795\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/21939"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=27795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=27795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=27795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}