{"id":27749,"date":"2020-01-28T17:01:00","date_gmt":"2020-01-28T15:01:00","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=27749"},"modified":"2020-01-28T17:01:00","modified_gmt":"2020-01-28T15:01:00","slug":"aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/","title":{"rendered":"Aprobada una declaraci\u00f3n de rechazo a la decisi\u00f3n del gobierno municipal de suspender una charla en la Casa de las Mujeres"},"content":{"rendered":"<p><!--more--><\/p>\n<p>La Comisi\u00f3n de Asuntos Ciudadanos ha aprobado una declaraci\u00f3n, presentada por los grupos municipales de EH Bildu, PSN y Geroa Bai, en la que el Ayuntamiento expresa \u201csu m\u00e1s rotundo rechazo a la decisi\u00f3n del gobierno municipal de suspender la charla \u2018brecha org\u00e1smica: de c\u00f3mo el patriarcado nos persigue hasta en la cama\u2019, dentro del programa de claras sobre igualdad y empoderamiento de la Casa de las Mujeres de Pamplona\u201d.<\/p>\n<p>La declaraci\u00f3n considera este hecho \u201cun acto de censura profundamente antidemocr\u00e1tico, que vulnera la libertad de expresi\u00f3n y de pensamiento y ataca el objetivo de la igualdad que ordena toda la legislaci\u00f3n estatal y foral en materia de igualdad, as\u00ed como la propia Ordenanza municipal\u201d. Se exige, adem\u00e1s, \u201cque se celebre la charla en los mismos t\u00e9rminos, con el mismo t\u00edtulo y la misma promoci\u00f3n previa que la anterior y se pidan disculpas a la ponente\u201d. Asimismo, denuncia \u201cla deriva sectaria y autoritaria del gobierno municipal de UPN, PP y Ciudadanos y su af\u00e1n de vetar charlas o actos p\u00fablicos que coinciden con su ideolog\u00eda\u201d.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>El texto de la declaraci\u00f3n aprobada critica \u201cel uso partidario de la instituci\u00f3n municipal por parte del gobierno municipal inmiscuy\u00e9ndose en la libertad de los colectivos e imponiendo un criterio pol\u00edtico reaccionario sobre el criterio t\u00e9cnico de las personas profesionales de Igualdad, y en contra de los objetivos estrat\u00e9gicos recogidos por las propias leyes, la Ordenanza y el Plan de Igualdad\u201d.<\/p>\n<p>Por \u00faltimo, se ha acordado \u201cexpresar el total apoyo a los colectivos de la Casa de las Mujeres, as\u00ed como al conjunto del movimiento feminista de la ciudad, verdadero protagonista de los importantes avances de los \u00faltimos a\u00f1os, e instarles a que sigan desarrollando su labor inestimable con el respaldo de la mayor\u00eda pol\u00edtica y social de la ciudad\u201d. La declaraci\u00f3n ha contado con los 6 votos a favor de los grupos municipales de EH Bildu, PSN y Geroa Bai y con los 5 votos en contra de Navarra Suma.<\/p>\n<p>&nbsp;<br \/>\n[qodef_button size=\u00bblarge\u00bb type=\u00bb\u00bb text=\u00bbDeclaraci\u00f3n charla casa mujeres.pdf\u00bb custom_class=\u00bb\u00bb icon_pack=\u00bbfont_elegant\u00bb fa_icon=\u00bbicon_download\u00bb link=\u00bbhttps:\/\/www.laguiadepamplona.es\/actualidad\/wp-content\/uploads\/2020\/01\/20.01.28_CMC_declaracion_charla_casa_mujeres.pdf\u00bb target=\u00bb_blank\u00bb color=\u00bbffffff\u00bb hover_color=\u00bb\u00bb background_color=\u00bb\u00bb hover_background_color=\u00bb\u00bb border_color=\u00bb\u00bb hover_border_color=\u00bb\u00bb font_size=\u00bb\u00bb font_weight=\u00bb\u00bb margin=\u00bb\u00bb]\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":21939,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aprobada una declaraci\u00f3n de rechazo a la decisi\u00f3n del gobierno municipal de suspender una charla en la Casa de las Mujeres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aprobada una declaraci\u00f3n de rechazo a la decisi\u00f3n del gobierno municipal de suspender una charla en la Casa de las Mujeres\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-28T15:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"Aprobada una declaraci\u00f3n de rechazo a la decisi\u00f3n del gobierno municipal de suspender una charla en la Casa de las Mujeres\",\"datePublished\":\"2020-01-28T15:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\\\/\"},\"wordCount\":433,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\\\/\",\"name\":\"Aprobada una declaraci\u00f3n de rechazo a la decisi\u00f3n del gobierno municipal de suspender una charla en la Casa de las Mujeres\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"datePublished\":\"2020-01-28T15:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"width\":1920,\"height\":1100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aprobada una declaraci\u00f3n de rechazo a la decisi\u00f3n del gobierno municipal de suspender una charla en la Casa de las Mujeres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aprobada una declaraci\u00f3n de rechazo a la decisi\u00f3n del gobierno municipal de suspender una charla en la Casa de las Mujeres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/","og_locale":"es_ES","og_type":"article","og_title":"Aprobada una declaraci\u00f3n de rechazo a la decisi\u00f3n del gobierno municipal de suspender una charla en la Casa de las Mujeres","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2020-01-28T15:01:00+00:00","og_image":[{"width":1920,"height":1100,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"Aprobada una declaraci\u00f3n de rechazo a la decisi\u00f3n del gobierno municipal de suspender una charla en la Casa de las Mujeres","datePublished":"2020-01-28T15:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/"},"wordCount":433,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/","name":"Aprobada una declaraci\u00f3n de rechazo a la decisi\u00f3n del gobierno municipal de suspender una charla en la Casa de las Mujeres","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","datePublished":"2020-01-28T15:01:00+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","width":1920,"height":1100},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aprobada-una-declaracion-de-rechazo-a-la-decision-del-gobierno-municipal-de-suspender-una-charla-en-la-casa-de-las-mujeres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Aprobada una declaraci\u00f3n de rechazo a la decisi\u00f3n del gobierno municipal de suspender una charla en la Casa de las Mujeres"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/27749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=27749"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/27749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/21939"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=27749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=27749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=27749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}