{"id":26364,"date":"2019-11-20T11:43:06","date_gmt":"2019-11-20T09:43:06","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=26364"},"modified":"2019-11-20T11:43:32","modified_gmt":"2019-11-20T09:43:32","slug":"el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/","title":{"rendered":"El Ayuntamiento apoya con 180.000 euros un proyecto de cooperaci\u00f3n de nutrici\u00f3n en Bolivia, otro de agua potable en Per\u00fa y un tercero de desarrollo econ\u00f3mico en Colombia"},"content":{"rendered":"<h3>El Consistorio dedica al Programa Municipal de Cooperaci\u00f3n Internacional al Desarrollo 1.498.882 euros, el 0,76% del presupuesto municipal<\/h3>\n<p><!--more--><\/p>\n<p>El Ayuntamiento de Pamplona apoya este a\u00f1o tres proyectos dentro de la Convocatoria destinada a la realizaci\u00f3n de Proyectos de Cooperaci\u00f3n al Desarrollo Local con Entidades Locales del Sur dotada con 180.000 euros. Uno de ellos se iniciar\u00e1 pr\u00f3ximamente en Bolivia y se centra en reforzar la producci\u00f3n de un alimento complementario alternativo de producci\u00f3n local que mejorar\u00e1 la desnutrici\u00f3n en menores. Un segundo apoya el desarrollo econ\u00f3mico de municipios de Per\u00fa. El tercero impulsa el acceso al agua potable en dos municipalidades de Colombia. Detr\u00e1s de ellos se encuentran miles de personas beneficiarias que se unen a todas aquellas que participan en las iniciativas llevadas a cabo con subvenciones del Programa Municipal de Cooperaci\u00f3n Internacional al Desarrollo. Este programa, que apoya a las comunidades de los pa\u00edses m\u00e1s empobrecidos, est\u00e1 dotado en 2019 con 1.498.882 euros, lo que representa el 0,76% del presupuesto municipal. As\u00ed se alcanza el porcentaje que Naciones Unidas recomienda que sea destinado, como m\u00ednimo, a la Cooperaci\u00f3n Internacional al Desarrollo (CID).<\/p>\n<p>Esta es una de las seis convocatorias del programa. En pa\u00edses en v\u00edas de desarrollo tambi\u00e9n se centra la destinada a Proyectos de Cooperaci\u00f3n Internacional al Desarrollo dotada inicialmente con 840.000 euros y la de Proyectos de Ayuda Humanitaria y de Emergencia que cuenta con 105.000 euros. Para la sensibilidad y educaci\u00f3n para el desarrollo en Pamplona, el Ayuntamiento cuenta una convocatoria para Proyectos de Educaci\u00f3n para el Desarrollo y la Ciudadan\u00eda Global (30.000 euros), otra para Proyectos de Sensibilizaci\u00f3n (107.500 euros) y una tercera para Acciones Puntuales de Sensibilizaci\u00f3n (9.600 euros).<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Convocatoria que financia proyectos a medio plazo a trav\u00e9s de ayudas de hasta 3 a\u00f1os<\/strong><\/p>\n<p>Las bases de la convocatoria de Proyectos de Cooperaci\u00f3n al Desarrollo Local con Entidades Locales del Sur recog\u00edan que se apoyar\u00edan tres proyectos, con 60.000 euros cada uno, de los que uno ser\u00eda nuevo y otros dos continuar\u00edan tras ser financiados en la convocatoria de 2017 en un caso y de dos en 2018. As\u00ed se pueden sostener programas que tienen m\u00e1s de un a\u00f1o de duraci\u00f3n y que permiten obtener resultados a medio y largo plazo. De forma paralela, se apuesta por la descentralizaci\u00f3n y el fortalecimiento de las administraciones locales de los pa\u00edses del Sur. A la convocatoria se presentaron nueve solicitudes con siete propuestas nuevas y dos que ya hab\u00edan obtenido ayuda.<\/p>\n<p>En 2019, por primera vez ha obtenido ayuda el proyecto \u2018Desnutrici\u00f3n cero y alimentaci\u00f3n saludable a trav\u00e9s del desarrollo econ\u00f3mico local en el municipio de Caripuyo\u2019 (Bolivia) de Medicus Mundi NAM. En su segundo a\u00f1o de financiaci\u00f3n ha entrado el de \u2018Promoci\u00f3n del desarrollo econ\u00f3mico local a partir de la mejora de las capacidades y competencias de la Municipalidad provincial de Caylloma\u2019 (Per\u00fa) de la Fundaci\u00f3n Paz y Solidaridad. Por tercer y \u00faltimo a\u00f1o ha recibido ayuda la iniciativa \u2018Agua para la paz: aporte al acceso a agua potable en zonas rurales del Valle del Cauca (Colombia)\u2019 de Alboan.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Desnutrici\u00f3n cero con un producto alimenticio local que se produce en la zona<\/strong><\/p>\n<p>El proyecto \u201cDesnutrici\u00f3n cero y alimentaci\u00f3n saludable, a trav\u00e9s del desarrollo econ\u00f3mico local en el municipio de Caripuyo\u201d, impulsado por M\u00e9dicos Mundi Nam, se desarrollar\u00e1 en el departamento de Potosi de Bolivia. El objetivo de la iniciativa, impulsada junto al personal de salud del gobierno municipal de Caripuyo, es lograr desnutrici\u00f3n cero en menores de dos a\u00f1os. El municipio cuenta con 8.687 habitantes y con 2.227 familias, distribuidas en 84 comunidades con un 98% de poblaci\u00f3n rural y un 88,8% en situaci\u00f3n de pobreza. El socio local es Medicus Mundi Delegaci\u00f3n Bolivia. El presupuesto para el primer a\u00f1o es de 90.802 euros; la entidad local de Caripuyo contribuye con el 34% (30.802 euros) y el Consistorio pamplon\u00e9s con el 66% (60.000 euros). El coste total del proyecto a tres a\u00f1os es de 262.069 euros.<\/p>\n<p>La iniciativa busca consolidar la apuesta del municipio de Caripuyo por la desnutrici\u00f3n cero y el fomento de una alimentaci\u00f3n saludable aprovechando los recursos existentes y la cooperaci\u00f3n p\u00fablico-privada. As\u00ed se contin\u00faa la l\u00ednea emprendida por Bolivia que presta especial atenci\u00f3n a la lactancia materna y al refuerzo con alimentos complementarios. En este caso, en lugar de basarse el proyecto en productos farmac\u00e9uticos se ha apostado por la producci\u00f3n de su propio complemento alimenticio, el Kallpawawa, en Quechua, \u201cs\u00faper alimento para beb\u00e9s\u201d. Los favorables datos aportados entre 2007 y 2018, en los que el proyecto fue apoyado por la cooperaci\u00f3n belga, se\u00f1alan que con la implantaci\u00f3n de este alimento la desnutrici\u00f3n ha ido reduci\u00e9ndose.<\/p>\n<p>Para llevar a cabo el proyecto se ha consolidado la producci\u00f3n de Kallpawawa fortaleciendo la capacidad t\u00e9cnica y organizativa de la planta industrial y de las asociaciones de suministradores. De forma paralela se impartir\u00e1 formaci\u00f3n a las familias con menores de tres a\u00f1os sobre conductas adecuadas en cuidado y desarrollo infantil. Por \u00faltimo, el programa de M\u00e9dicos Mundi servir\u00e1 para que el gobierno municipal local desarrollar\u00e1 capacidades para transcender de ser una entidad prestadora de servicios p\u00fablicos a la promoci\u00f3n del desarrollo integral de la econom\u00eda local. El gobierno municipal actualmente se encarga de pagar al personal de la planta industrial y de la compra de materias primas. Est\u00e1 previsto que esta planta pueda generar ingresos para el municipio a medio plazo. Por \u00faltimo, el proyecto contempla una fase de sensibilizaci\u00f3n que se realizar\u00e1 entre la poblaci\u00f3n de Pamplona con la edici\u00f3n de material informativo y la promoci\u00f3n del voluntariado.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Mejorar la capacidad empresarial de j\u00f3venes y mujeres y la producci\u00f3n de sectores clave<\/strong><\/p>\n<p>En su segundo a\u00f1o se encuentra el proyecto para la \u201cPromoci\u00f3n del Desarrollo Econ\u00f3mico Local a partir de la mejora de las capacidades y competencias en la municipalidad provincial y los principales actores econ\u00f3micos sociales de la provincia de Caylloma\u201d. Se desarrolla en el departamento de Arequipa, en 6 distritos de Caylloma que tienen una poblaci\u00f3n de 14.957 habitantes. El programa, impulsado por la Fundaci\u00f3n Paz y Solidaridad, cuenta como socio local con el Centro de Estudios y Promoci\u00f3n del Desarrollo (DESCO) que tiene m\u00e1s de 50 a\u00f1os de experiencia. El coste total es de 232.752 euros, con un gasto este a\u00f1o de 80.375 euros. El Ayuntamiento de Pamplona financia con 60.000 euros y el resto corre a cargo de las personas beneficias, socia local, municipalidad destinataria y entidad solicitante.<\/p>\n<p>El proyecto busca contribuir a la reducci\u00f3n de la pobreza y al crecimiento econ\u00f3mico sostenido con el incremento de ingresos y la generaci\u00f3n de autoempleo. Se mejorar\u00e1 la econom\u00eda a partir del fomento del desarrollo econ\u00f3mico local (con especial incidencia en las capacidades empresariales de j\u00f3venes y mujeres), del fortalecimiento de las principales cadenas productivas (l\u00e1cteos obtenidos del ganado, producci\u00f3n de quinoa y turismo rural) y de conglomerados econ\u00f3micos del gobierno local. La poblaci\u00f3n beneficiaria directa asciende a 1.928 personas (482 familias).<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Acceso al agua potable a trav\u00e9s de acueductos y de equipamientos para las familias<\/strong><\/p>\n<p>El tercer proyecto finaliza este a\u00f1o y ha impulsado el acceso a agua potable en zonas rurales de Colombia, en concreto en los municipios de Trujillo (18.142 habitantes) y Tulu\u00e1 (216.604), en la zona centro del departamento del Valle del Cauca. En el tercer a\u00f1o de desarrollo, se centra en Venecia (Trujillo) y San Lorenzo (Tulu\u00e1), cuyos acueductos rurales abastecen a una poblaci\u00f3n aproximada de 1.378 personas (708 mujeres y 670 hombres). Ambos municipios cuentan con una importante brecha urbano-rural, tanto en servicios b\u00e1sicos como en dotaci\u00f3n de equipamientos. En el proceso para contribuir al fortalecimiento de la gesti\u00f3n sostenible del agua se van a mejorar las infraestructuras de los acueductos comunitarios y se van a proveer sistemas familiares de potabilizaci\u00f3n de agua, Por otro lado, se ha trabajado en el fortalecimiento de la presencia de alcald\u00edas y organizaciones sociales.<\/p>\n<p>Alboan desarrolla este proyecto teniendo de social local a la Fundaci\u00f3n Instituto Mayor Campesino, organizaci\u00f3n no gubernamental fundada por la Compa\u00f1\u00eda de Jes\u00fas en 1962. El proyecto ha tenido un presupuesto total de 247.705 euros de los que 80.785 euros corresponden a este a\u00f1o. La ayuda municipal asciende al 74%, 60.000 euros, mientras que el 26% ser\u00e1 financiado, como en el resto de proyectos, por las personas beneficiarias, socia local, municipalidad destinataria y entidad solicitante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consistorio dedica al Programa Municipal de Cooperaci\u00f3n Internacional al Desarrollo 1.498.882 euros, el 0,76% del presupuesto municipal<\/p>\n","protected":false},"author":1,"featured_media":26366,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-26364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Ayuntamiento apoya con 180.000 euros un proyecto de cooperaci\u00f3n de nutrici\u00f3n en Bolivia, otro de agua potable en Per\u00fa y un tercero de desarrollo econ\u00f3mico en Colombia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Ayuntamiento apoya con 180.000 euros un proyecto de cooperaci\u00f3n de nutrici\u00f3n en Bolivia, otro de agua potable en Per\u00fa y un tercero de desarrollo econ\u00f3mico en Colombia\" \/>\n<meta property=\"og:description\" content=\"El Consistorio dedica al Programa Municipal de Cooperaci\u00f3n Internacional al Desarrollo 1.498.882 euros, el 0,76% del presupuesto municipal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-20T09:43:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-20T09:43:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/11\/19.11.20_cooperacion_sur_desarrollo_economico_caylloma.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1417\" \/>\n\t<meta property=\"og:image:height\" content=\"797\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El Ayuntamiento apoya con 180.000 euros un proyecto de cooperaci\u00f3n de nutrici\u00f3n en Bolivia, otro de agua potable en Per\u00fa y un tercero de desarrollo econ\u00f3mico en Colombia\",\"datePublished\":\"2019-11-20T09:43:06+00:00\",\"dateModified\":\"2019-11-20T09:43:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\\\/\"},\"wordCount\":1478,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/19.11.20_cooperacion_sur_desarrollo_economico_caylloma.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\\\/\",\"name\":\"El Ayuntamiento apoya con 180.000 euros un proyecto de cooperaci\u00f3n de nutrici\u00f3n en Bolivia, otro de agua potable en Per\u00fa y un tercero de desarrollo econ\u00f3mico en Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/19.11.20_cooperacion_sur_desarrollo_economico_caylloma.jpg\",\"datePublished\":\"2019-11-20T09:43:06+00:00\",\"dateModified\":\"2019-11-20T09:43:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/19.11.20_cooperacion_sur_desarrollo_economico_caylloma.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/19.11.20_cooperacion_sur_desarrollo_economico_caylloma.jpg\",\"width\":1417,\"height\":797},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Ayuntamiento apoya con 180.000 euros un proyecto de cooperaci\u00f3n de nutrici\u00f3n en Bolivia, otro de agua potable en Per\u00fa y un tercero de desarrollo econ\u00f3mico en Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Ayuntamiento apoya con 180.000 euros un proyecto de cooperaci\u00f3n de nutrici\u00f3n en Bolivia, otro de agua potable en Per\u00fa y un tercero de desarrollo econ\u00f3mico en Colombia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/","og_locale":"es_ES","og_type":"article","og_title":"El Ayuntamiento apoya con 180.000 euros un proyecto de cooperaci\u00f3n de nutrici\u00f3n en Bolivia, otro de agua potable en Per\u00fa y un tercero de desarrollo econ\u00f3mico en Colombia","og_description":"El Consistorio dedica al Programa Municipal de Cooperaci\u00f3n Internacional al Desarrollo 1.498.882 euros, el 0,76% del presupuesto municipal","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2019-11-20T09:43:06+00:00","article_modified_time":"2019-11-20T09:43:32+00:00","og_image":[{"width":1417,"height":797,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/11\/19.11.20_cooperacion_sur_desarrollo_economico_caylloma.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El Ayuntamiento apoya con 180.000 euros un proyecto de cooperaci\u00f3n de nutrici\u00f3n en Bolivia, otro de agua potable en Per\u00fa y un tercero de desarrollo econ\u00f3mico en Colombia","datePublished":"2019-11-20T09:43:06+00:00","dateModified":"2019-11-20T09:43:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/"},"wordCount":1478,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/11\/19.11.20_cooperacion_sur_desarrollo_economico_caylloma.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/","name":"El Ayuntamiento apoya con 180.000 euros un proyecto de cooperaci\u00f3n de nutrici\u00f3n en Bolivia, otro de agua potable en Per\u00fa y un tercero de desarrollo econ\u00f3mico en Colombia","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/11\/19.11.20_cooperacion_sur_desarrollo_economico_caylloma.jpg","datePublished":"2019-11-20T09:43:06+00:00","dateModified":"2019-11-20T09:43:32+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/11\/19.11.20_cooperacion_sur_desarrollo_economico_caylloma.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/11\/19.11.20_cooperacion_sur_desarrollo_economico_caylloma.jpg","width":1417,"height":797},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-apoya-con-180-000-euros-un-proyecto-de-cooperacion-de-nutricion-en-bolivia-otro-de-agua-potable-en-peru-y-un-tercero-de-desarrollo-economico-en-colombia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El Ayuntamiento apoya con 180.000 euros un proyecto de cooperaci\u00f3n de nutrici\u00f3n en Bolivia, otro de agua potable en Per\u00fa y un tercero de desarrollo econ\u00f3mico en Colombia"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/26364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=26364"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/26364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/26366"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=26364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=26364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=26364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}