{"id":26123,"date":"2019-11-12T17:22:51","date_gmt":"2019-11-12T15:22:51","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=26123"},"modified":"2019-11-12T17:23:15","modified_gmt":"2019-11-12T15:23:15","slug":"el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/","title":{"rendered":"El Ayuntamiento ampliar\u00e1 la red de atenci\u00f3n primaria de los servicios sociales en 2020 con la creaci\u00f3n de la Unidad de Barrio de Lezkairu"},"content":{"rendered":"<h3>Casi el 20% de las atenciones en las seis unidades de barrio con el nuevo modelo de atenci\u00f3n primaria se llevan a cabo en el plazo de una semana<\/h3>\n<p><!--more--><\/p>\n<p>El Ayuntamiento de Pamplona abrir\u00e1 en 2020 la Unidad de Barrio de Lezkairu para dar una respuesta descentralizada y pr\u00f3xima la ciudadan\u00eda de esa zona de la ciudad. Esa unidad de barrio podr\u00eda asumir, adem\u00e1s, casi el 25% de las citas que en la actualidad atiende la UB Milagrosa. La concejala delegada de Servicios Sociales, Acci\u00f3n Comunitaria y Deporte, Mar\u00eda Caballero, y la directora de Servicios Sociales, Olivia Elizari, han presentado en Comisi\u00f3n de Asuntos Ciudadanos las medidas adoptadas para la correcta implementaci\u00f3n del modelo de atenci\u00f3n primaria en las unidades de barrio con el objetivo de agilizar la atenci\u00f3n y ganar eficiencia.<\/p>\n<p>El nuevo modelo de atenci\u00f3n, implementado en siete unidades de barrio desde el pasado verano, se basa en el prop\u00f3sito de mejorar y agilizar la atenci\u00f3n a la ciudadan\u00eda, favorecer espacios de intervenci\u00f3n grupal y reservar espacios para el trabajo comunitario, favoreciendo la coordinaci\u00f3n p\u00fablico-privada, con entidades del tercer sector y con la administraci\u00f3n educativa y de salud. Se persigue un modelo centrado en la persona, basado en la atenci\u00f3n integral y hol\u00edstica, evitando modelos de naturaleza asistencial que fragmentan la demanda. A principios de verano, se implementaba un nuevo modelo de atenci\u00f3n primaria en la mitad de las unidades de barrio que conforman Pamplona, que en la actualidad ascienden a siete unidades de barrio. Este modelo se ha puesto ya en marcha en las unidades de barrio de Txantrea, Rochapea, San Juan, Iturrama, San Jorge y Buztintxuri desde principios de verano, y en Milagrosa desde octubre<\/p>\n<p>En estos meses de implementaci\u00f3n, el modelo ha sido evaluado semanalmente por personal t\u00e9cnico del \u00e1rea de Servicios Sociales para as\u00ed poder ir ajust\u00e1ndolo al m\u00e1ximo a la realidad social de cada barrio. Como principal novedad, el modelo incluye una fase de cribado, que permite a las personas ser atendidas en una semana, pudiendo resolverse atenciones derivadas de acreditaci\u00f3n de necesidad econ\u00f3mica para acceso a diferentes prestaciones, as\u00ed como informaci\u00f3n de car\u00e1cter general de programas. En caso de precisar una atenci\u00f3n m\u00e1s espec\u00edfica, la persona es derivada al programa de atenci\u00f3n primaria correspondiente.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Primeros datos del mes de septiembre<\/strong><\/p>\n<p>Seg\u00fan datos del mes de septiembre, en las seis unidades de barrio en las que estaba implementado el modelo entonces (en la UB Milagrosa se puso en marcha en octubre), se realizaron 2.140 atenciones. De ellas han pasado a la fase de cribado 427, mientras que el resto, 1.621 fueron citas programadas de car\u00e1cter individual relacionadas con alguno de los programas de atenci\u00f3n primaria. Casi el 20% de las atenciones totales, por tanto, se atienden en el plazo de semana y, de ellas, m\u00e1s del 80% se resuelven en esa fase de cribado, por lo que finalizan en ese momento sin tener que llevar a cabo m\u00e1s esperas de atenci\u00f3n.<\/p>\n<p>Adem\u00e1s de esta novedad el Ayuntamiento ha puesto en marcha otras medidas tanto para la mejora de la atenci\u00f3n a la ciudadan\u00eda como para el desarrollo de la labor profesional del personal t\u00e9cnico. Entre otras medidas, se han estandarizado procesos, se ha definido el contenido de programas, se han mantenido reuniones con terceros para eliminar y\/o simplificar el tr\u00e1mite de acreditaci\u00f3n a terceros, se ha contratado temporalmente a una trabajadora social para dar apoyo los barrios, se van a definir las funciones por perfil profesional, o se ha cambiado la zonificaci\u00f3n de calles por profesional.<\/p>\n<p>En coordinaci\u00f3n con la Oficina Estrat\u00e9gica, se ha definido un sistema de evaluaci\u00f3n del modelo, que permite establecer unos indicadores de medici\u00f3n que aportan informaci\u00f3n objetiva relacionada con par\u00e1metros de satisfacci\u00f3n ciudadana, de satisfacci\u00f3n de profesionales, de eficiencia, de reducci\u00f3n de esperas, de impacto social\u2026 Para ello, se pretenden constituir 10 grupos focales, 4 talleres DAFO, 5 entrevistas con responsables del \u00e1rea, encuestas a personas usuarias, seguimiento a una muestra representativa de expedientes y encuesta dirigida a profesionales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Casi el 20% de las atenciones en las seis unidades de barrio con el nuevo modelo de atenci\u00f3n primaria se llevan a cabo en el plazo de una semana<\/p>\n","protected":false},"author":1,"featured_media":21939,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-26123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Ayuntamiento ampliar\u00e1 la red de atenci\u00f3n primaria de los servicios sociales en 2020 con la creaci\u00f3n de la Unidad de Barrio de Lezkairu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Ayuntamiento ampliar\u00e1 la red de atenci\u00f3n primaria de los servicios sociales en 2020 con la creaci\u00f3n de la Unidad de Barrio de Lezkairu\" \/>\n<meta property=\"og:description\" content=\"Casi el 20% de las atenciones en las seis unidades de barrio con el nuevo modelo de atenci\u00f3n primaria se llevan a cabo en el plazo de una semana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-12T15:22:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-12T15:23:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El Ayuntamiento ampliar\u00e1 la red de atenci\u00f3n primaria de los servicios sociales en 2020 con la creaci\u00f3n de la Unidad de Barrio de Lezkairu\",\"datePublished\":\"2019-11-12T15:22:51+00:00\",\"dateModified\":\"2019-11-12T15:23:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\\\/\"},\"wordCount\":732,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\\\/\",\"name\":\"El Ayuntamiento ampliar\u00e1 la red de atenci\u00f3n primaria de los servicios sociales en 2020 con la creaci\u00f3n de la Unidad de Barrio de Lezkairu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"datePublished\":\"2019-11-12T15:22:51+00:00\",\"dateModified\":\"2019-11-12T15:23:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"width\":1920,\"height\":1100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Ayuntamiento ampliar\u00e1 la red de atenci\u00f3n primaria de los servicios sociales en 2020 con la creaci\u00f3n de la Unidad de Barrio de Lezkairu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Ayuntamiento ampliar\u00e1 la red de atenci\u00f3n primaria de los servicios sociales en 2020 con la creaci\u00f3n de la Unidad de Barrio de Lezkairu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/","og_locale":"es_ES","og_type":"article","og_title":"El Ayuntamiento ampliar\u00e1 la red de atenci\u00f3n primaria de los servicios sociales en 2020 con la creaci\u00f3n de la Unidad de Barrio de Lezkairu","og_description":"Casi el 20% de las atenciones en las seis unidades de barrio con el nuevo modelo de atenci\u00f3n primaria se llevan a cabo en el plazo de una semana","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2019-11-12T15:22:51+00:00","article_modified_time":"2019-11-12T15:23:15+00:00","og_image":[{"width":1920,"height":1100,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El Ayuntamiento ampliar\u00e1 la red de atenci\u00f3n primaria de los servicios sociales en 2020 con la creaci\u00f3n de la Unidad de Barrio de Lezkairu","datePublished":"2019-11-12T15:22:51+00:00","dateModified":"2019-11-12T15:23:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/"},"wordCount":732,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/","name":"El Ayuntamiento ampliar\u00e1 la red de atenci\u00f3n primaria de los servicios sociales en 2020 con la creaci\u00f3n de la Unidad de Barrio de Lezkairu","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","datePublished":"2019-11-12T15:22:51+00:00","dateModified":"2019-11-12T15:23:15+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","width":1920,"height":1100},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-ampliara-la-red-de-atencion-primaria-de-los-servicios-sociales-en-2020-con-la-creacion-de-la-unidad-de-barrio-de-lezkairu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El Ayuntamiento ampliar\u00e1 la red de atenci\u00f3n primaria de los servicios sociales en 2020 con la creaci\u00f3n de la Unidad de Barrio de Lezkairu"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/26123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=26123"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/26123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/21939"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=26123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=26123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=26123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}