{"id":25630,"date":"2019-10-24T19:55:22","date_gmt":"2019-10-24T17:55:22","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=25630"},"modified":"2019-10-24T19:56:44","modified_gmt":"2019-10-24T17:56:44","slug":"aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/","title":{"rendered":"Aitor Francos, en la modalidad de castellano, y Mikel Arruabarrena, en la de euskera, reciben el Premio Internacional de Poes\u00eda Ciudad de Pamplona"},"content":{"rendered":"<p><!--more--><\/p>\n<h3>La entrega de los galardones a los dos j\u00f3venes autores ha tenido lugar esta tarde en el Palacio del Condestable<\/h3>\n<figure id=\"attachment_25633\" aria-describedby=\"caption-attachment-25633\" style=\"width: 450px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.laguiadepamplona.es\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.24_Entrega_premio_poesia_ciudad_pamplona_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-25633\" src=\"https:\/\/www.laguiadepamplona.es\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.24_Entrega_premio_poesia_ciudad_pamplona_1-450x300.jpg\" alt=\"\" width=\"450\" height=\"300\" srcset=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.24_Entrega_premio_poesia_ciudad_pamplona_1-450x300.jpg 450w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.24_Entrega_premio_poesia_ciudad_pamplona_1-768x512.jpg 768w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.24_Entrega_premio_poesia_ciudad_pamplona_1-1024x682.jpg 1024w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.24_Entrega_premio_poesia_ciudad_pamplona_1-640x427.jpg 640w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.24_Entrega_premio_poesia_ciudad_pamplona_1.jpg 1920w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><figcaption id=\"caption-attachment-25633\" class=\"wp-caption-text\">A* Jes\u00fas M Garzaron\/Ayuntamiento de Pamplona<br \/>F* 2019_10_24<br \/>T* Premios poes\u00eda \u00abCiudad de Pamplona<br \/>L* Condestable<\/figcaption><\/figure>\n<p>Aitor Francos Ajona, en la modalidad de castellano, y Mikel Arruabarrena, en la de euskera, han sido los galardonados con el Premio Internacional de Poes\u00eda Ciudad de Pamplona. El concurso, organizado por el Ateneo Navarro\/Nafar Ateneoa con el patrocinio del Ayuntamiento de Pamplona, alcanza la XIII edici\u00f3n en castellano y la IV en euskera. Los galardones han sido entregados esta tarde en el Palacio del Condestable por el alcalde de Pamplona, Enrique Maya, y por el vicepresidente del Ateneo Navarro\/Nafar Ateneoa, Pedro Salaberri.<\/p>\n<p>Los galardones consisten en sendos premios econ\u00f3micos de 3.000 euros y la edici\u00f3n de los poemarios ganadores. En el acto tambi\u00e9n han participado la concejala delegada de Cultura e Igualdad, Mar\u00eda Garc\u00eda-Barberena; el vocal de Literatura y Ling\u00fc\u00edstica, Javier Asi\u00e1in; y el vocal de Euskera y Cultura Popular, Josu Jim\u00e9nez Maia.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Aitor Franco galardonado por un poemario de haikus<\/strong><\/p>\n<p>Aitor Francos Ajona (Bilbao, 1986) ha ganado el premio de esta edici\u00f3n por el poemario \u2018Los d\u00edas andan sueltos\u2019, un libro de haikus que comienza con versos libre y contin\u00faa con la m\u00e9trica tradicional. Este g\u00e9nero po\u00e9tico, en palabras de los miembros del jurado, permite recoger la instantaneidad, el momento, algo que ha hecho el autor. Lo mismo que colocar a la naturaleza en el centro de la obra. Sin embargo, ha destacado que no se ha atenido estrictamente al m\u00e9todo japon\u00e9s sino que lo ha enriquecido con la idiosincrasia occidental. As\u00ed, ha logrado una poes\u00eda muy t\u00e9cnica, bien construida, ingeniosa e inteligente; llegando desde lo m\u00ednimo a la m\u00e1xima expresi\u00f3n en una obra de la que se ha destacado la gran calidad de sus 400 versos. Cada poema puede leerse independientemente, lo que permite peque\u00f1as lecturas y que se acerquen al g\u00e9nero po\u00e9tico personas que habitualmente no lo hacen. Fue elegido por unanimidad del jurado.<\/p>\n<p>Aitor Francos ha publicado desde 2011 cuando vio la luz su primer trabajo, \u2018Igloo\u2019, una decena de obras y ha sido incluido en varias antolog\u00edas. Ha recibido los premios Surcos, Hermanos Machado y Jos\u00e9 Bergam\u00edn. Asimismo, ha preparado la antolog\u00eda de poes\u00eda vasca \u2018Las aguas tranquilas\u2019 con traducciones al euskera de ocho poetas vascos actuales. Escribe cr\u00edtica y art\u00edculos para suplementos como P\u00e9rgola y en revistas como Quimera.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Mikel Arruabarrena, un joven f\u00edsico y poeta<\/strong><\/p>\n<p>Mikel Arruabarrena Larrarte (Hondarribia, 1994) present\u00f3 al certamen \u2018Ahanzturaren bezperan\u2019. Arruabarrena realiza en estos momentos el doctorado en F\u00edsica en el Centro de F\u00edsica de Materiales de San Sebasti\u00e1n de la Universidad del Pa\u00eds Vasco. Comenz\u00f3 en el mundo literario a trav\u00e9s del concurso de poes\u00eda en euskera que se organiza en Hondarribia y al que se presentaba, ganando en algunas ocasiones, cuando estudiaba en el instituto de la localidad. Este trabajo, seg\u00fan el jurado, ha destacado por la fuerza, el buen ritmo, la construcci\u00f3n de los versos muy t\u00e9cnica y bien elaborada y la tem\u00e1tica, que hac\u00eda intuir que pod\u00eda tratarse de una persona joven. Tambi\u00e9n ha sido elegido por unanimidad del jurado.<\/p>\n<p>En la modalidad de castellano el jurado ha estado compuesto por Mercedes Serna, profesora titular de Literatura Hispanoamericana en la Universidad de Barcelona; Jes\u00fas Mun\u00e1rriz, director gerente de la Editorial Hiperi\u00f3n; y Javier Asi\u00e1in, vocal de Literatura y Ling\u00fc\u00edstica del Ateneo Navarro y secretario del jurado. En euskera han tomado parte Aintzane Galardi, ganadora de la edici\u00f3n anterior del Premio de Poes\u00eda Ciudad de Pamplona en esa modalidad; Unai Pascual, editor de la editorial Denonartean; y Josu Jim\u00e9nez Maia, vocal de Euskera y Cultura Popular del Ateneo Navarro y secretario del jurado de euskera.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>366 poemarios en el concurso, 357 en castellano y 9 en euskera<\/strong><\/p>\n<p>Al concurso se presentaron 366 poemarios, de los que 357 son en castellano y 9 en euskera. Como en ediciones anteriores, sigue aumentando la cifra de participantes por internet. Este a\u00f1o en castellano el 94% de las obras llegaron por este medio y en euskera fueron el 89%. En 2018, en castellano se recibieron 405 poemarios, un 27% m\u00e1s que en 2017 cuando se presentaron 319. En euskera llegaron ese a\u00f1o 22 obras, m\u00e1s del doble que el anterior cuando se registraron 9, la misma cifra que este a\u00f1o.<\/p>\n<p>El 65% de las obras presentadas en castellano (230 de las 357) tienen una procedencia nacional y el 35% son extranjeras. En esta edici\u00f3n la autonom\u00eda con m\u00e1s obras presentadas ha sido Andaluc\u00eda con 39, seguida de Madrid con 35, Navarra con 23, Castilla La Mancha con 20 y Catalu\u00f1a con 18. A continuaci\u00f3n se sit\u00faan Castilla y Le\u00f3n con 13, Comunidad Valenciana y Euskadi con 12, Murcia con 11, Arag\u00f3n con 9, Extremadura, Galicia y las Islas Canarias con 7, Asturias con 6, Islas Baleares y la Rioja con 3 y Cantabria con 2.<\/p>\n<p>Entre los poemarios recibidos desde el extranjero destacan los 25 de Cuba y los 24 de Argentina, seguidos de 15 de Colombia y de M\u00e9xico, 8 de Venezuela y Per\u00fa, 5 de Ecuador y de Estados Unidos, 4 de Chile y de Alemania, 2 de Portugal, Rep\u00fablica Dominicana y Uruguay, y con un solo poemario, Brasil, Costa Rica, Dinamarca, Israel, Italia, Paraguay y Turqu\u00eda.<\/p>\n<p>De las 9 obras recibidas en euskera, 5 son de Navarra, 3 de Gipuzkoa y uno de Vizcaya.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #ff0000;\">Ganadores premio poes\u00eda ciudad de Pamplona<\/span><\/h3>\n<ul>\n<li>2007: Manuel Jurado<\/li>\n<li>2008: Manuel Laespada<\/li>\n<li>2009: Andr\u00e9s Garc\u00eda<\/li>\n<li>2010: Alfonso Pascal<\/li>\n<li>2011: Teresa N\u00fa\u00f1ez<\/li>\n<li>2012: Julio C\u00e9sar<\/li>\n<li>2013: Jos\u00e9 Antonio Ram\u00edrez Lozano<\/li>\n<li>2014: Carlos Vaquerizo<\/li>\n<li>2015: Mar\u00eda Sanz<\/li>\n<li>2016: Tom\u00e1s Hern\u00e1ndez y Jon Barberena<\/li>\n<li>2017: Joaqu\u00edn M\u00e1rquez y Juan Karlos Lopez-Mugartza<\/li>\n<li>2018: Juan Leyva y Aintzane Galardi<\/li>\n<li>2019: Aitor Francos y Mikel Arruabarrena<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":25632,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-25630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aitor Francos, en la modalidad de castellano, y Mikel Arruabarrena, en la de euskera, reciben el Premio Internacional de Poes\u00eda Ciudad de Pamplona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aitor Francos, en la modalidad de castellano, y Mikel Arruabarrena, en la de euskera, reciben el Premio Internacional de Poes\u00eda Ciudad de Pamplona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-24T17:55:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-24T17:56:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.24_Entrega_premio_poesia_ciudad_pamplona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"Aitor Francos, en la modalidad de castellano, y Mikel Arruabarrena, en la de euskera, reciben el Premio Internacional de Poes\u00eda Ciudad de Pamplona\",\"datePublished\":\"2019-10-24T17:55:22+00:00\",\"dateModified\":\"2019-10-24T17:56:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\\\/\"},\"wordCount\":1014,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/19.10.24_Entrega_premio_poesia_ciudad_pamplona.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\\\/\",\"name\":\"Aitor Francos, en la modalidad de castellano, y Mikel Arruabarrena, en la de euskera, reciben el Premio Internacional de Poes\u00eda Ciudad de Pamplona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/19.10.24_Entrega_premio_poesia_ciudad_pamplona.jpg\",\"datePublished\":\"2019-10-24T17:55:22+00:00\",\"dateModified\":\"2019-10-24T17:56:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/19.10.24_Entrega_premio_poesia_ciudad_pamplona.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/19.10.24_Entrega_premio_poesia_ciudad_pamplona.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"A* Jes\u00fas M Garzaron\\\/Ayuntamiento de Pamplona F* 2019_10_24 T* Premios poes\u00eda \\\"Ciudad de Pamplona L* Condestable\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aitor Francos, en la modalidad de castellano, y Mikel Arruabarrena, en la de euskera, reciben el Premio Internacional de Poes\u00eda Ciudad de Pamplona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aitor Francos, en la modalidad de castellano, y Mikel Arruabarrena, en la de euskera, reciben el Premio Internacional de Poes\u00eda Ciudad de Pamplona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/","og_locale":"es_ES","og_type":"article","og_title":"Aitor Francos, en la modalidad de castellano, y Mikel Arruabarrena, en la de euskera, reciben el Premio Internacional de Poes\u00eda Ciudad de Pamplona","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2019-10-24T17:55:22+00:00","article_modified_time":"2019-10-24T17:56:44+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.24_Entrega_premio_poesia_ciudad_pamplona.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"Aitor Francos, en la modalidad de castellano, y Mikel Arruabarrena, en la de euskera, reciben el Premio Internacional de Poes\u00eda Ciudad de Pamplona","datePublished":"2019-10-24T17:55:22+00:00","dateModified":"2019-10-24T17:56:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/"},"wordCount":1014,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.24_Entrega_premio_poesia_ciudad_pamplona.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/","name":"Aitor Francos, en la modalidad de castellano, y Mikel Arruabarrena, en la de euskera, reciben el Premio Internacional de Poes\u00eda Ciudad de Pamplona","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.24_Entrega_premio_poesia_ciudad_pamplona.jpg","datePublished":"2019-10-24T17:55:22+00:00","dateModified":"2019-10-24T17:56:44+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.24_Entrega_premio_poesia_ciudad_pamplona.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/10\/19.10.24_Entrega_premio_poesia_ciudad_pamplona.jpg","width":1920,"height":1280,"caption":"A* Jes\u00fas M Garzaron\/Ayuntamiento de Pamplona F* 2019_10_24 T* Premios poes\u00eda \"Ciudad de Pamplona L* Condestable"},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/aitor-francos-en-la-modalidad-de-castellano-y-mikel-arruabarrena-en-la-de-euskera-reciben-el-premio-internacional-de-poesia-ciudad-de-pamplona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Aitor Francos, en la modalidad de castellano, y Mikel Arruabarrena, en la de euskera, reciben el Premio Internacional de Poes\u00eda Ciudad de Pamplona"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/25630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=25630"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/25630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/25632"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=25630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=25630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=25630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}