{"id":25298,"date":"2019-10-16T12:24:00","date_gmt":"2019-10-16T10:24:00","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=25298"},"modified":"2019-10-16T12:24:36","modified_gmt":"2019-10-16T10:24:36","slug":"rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/","title":{"rendered":"Rubik Teatre abre este jueves una nueva edici\u00f3n del ciclo de Antzerki Aroa con una obra basada en el teatro visual, los nuevos lenguajes teatrales y la po\u00e9tica del movimiento"},"content":{"rendered":"<p><!--more--><\/p>\n<h3>La actuaci\u00f3n tendr\u00e1 lugar en la Escuela Navarra de Teatro a las 20 horas con entradas a 8 euros<\/h3>\n<p>La compa\u00f1\u00eda Rubik Teatre ser\u00e1 la encargada de abrir este jueves, 17 de octubre, una nueva edici\u00f3n del ciclo de teatro en euskera para p\u00fablico joven y adulto Antzerki Aroa. Pondr\u00e1 en escena la obra \u2018Babesleku arrotzak eta animalia bakartien hotsak\u2019, un espect\u00e1culo creado profundizando en la experimentaci\u00f3n y en la b\u00fasqueda de nuevos lenguajes teatrales y trabajando la po\u00e9tica del movimiento y el teatro visual. Las entradas cuestan 8 euros y pueden comprarse en la taquilla de la Escuela Navarra de Teatro y en su p\u00e1gina web <a href=\"http:\/\/www.laescueladeteatro.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.laescueladeteatro.com<\/a>.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>Las actuaciones de este a\u00f1o de Antzerki Aroa se extender\u00e1n hasta el 11 de diciembre en la Escuela Navarra de Teatro, Teatro Gayarre y Civivox Iturrama. Todas las representaciones ser\u00e1n a las ocho de la tarde. Adem\u00e1s de Rubik Theatre, pasar\u00e1n por los distintos escenarios Producciones Vaiv\u00e9n, Artedrama-Axut -Dejabu Panpin Laborategia, Hika Teatroa y Atx Teatroa. Las entradas cuestan cada d\u00eda 8 euros y pueden comprarse en los lugares de las actuaciones y en sus respectivas p\u00e1ginas web: <a href=\"http:\/\/www.laescueladeteatro.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.laescueladeteatro.com<\/a>, <a href=\"http:\/\/www.teatrogayarre.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.teatrogayarre.com<\/a> y <a href=\"http:\/\/www.pamplonaescultura.es\" target=\"_blank\" rel=\"noopener noreferrer\">www.pamplonaescultura.es<\/a> o <a href=\"http:\/\/www.pamplona.es\" target=\"_blank\" rel=\"noopener noreferrer\">www.pamplona.es<\/a> para la actividad que tendr\u00e1 lugar en Civivox Iturrama.<\/p>\n<p>El colectivo art\u00edstico RubiK Theater se cre\u00f3 en 2013 y hasta 2016 estuvo afincado entre Pa\u00eds Vasco y Catalu\u00f1a, fecha en la que fij\u00f3 su residencia en el Pa\u00eds Vasco. Su voluntad es experimentar en nuevos lenguajes donde el gesto y el movimiento sean las principales herramientas del actor\/performer, ofreciendo una dramaturgia escrita por los propios cuerpos. Naci\u00f3 con la uni\u00f3n art\u00edstica de Estitxu Zaldua y Juanjo Herrero, ambos licenciados en la especialidad de Teatro F\u00edsico y Visual en el Institut del Teatre (Barcelona). Su formaci\u00f3n se basa en la danza, el texto, la manipulaci\u00f3n de objetos y la biomec\u00e1nica aplicada. Trabajan en la b\u00fasqueda de una gestualidad definida y profundizan en el movimiento, la expresividad del cuerpo, la palabra, el espacio y toda su composici\u00f3n pl\u00e1stica para crear una arquitectura esc\u00e9nica con dramaturgia propia. En su trabajo habitual colabora con artistas de diversas disciplinas: core\u00f3grafos, dramaturgos, artistas audiovisuales, m\u00fasicos). Crean as\u00ed un punto de encuentro multidisciplinar con el que ofrecen al espectador una propuesta para intuir, interpretar y sentir.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #ff0000;\">\u2018Antzerki Aroa. 2019\u2019. Del 17 de octubre al 11 de diciembre. Entradas: 8 euros<\/span><\/h3>\n<ul>\n<li><span style=\"color: #ff0000;\"><strong>Jueves, 17 de octubre<\/strong>.<\/span> 20:00. Escuela Navarra de Teatro<\/li>\n<li>Babesleku arrotzak eta animalia bakartien hotsak<\/li>\n<li>Rubik Theatre<\/li>\n<li><span style=\"color: #ff0000;\"><strong>Mi\u00e9rcoles, 30 de octubre<\/strong>.<\/span> 20:00. Teatro Gayarre<\/li>\n<li>Erlauntza (con sobret\u00edtulos en castellano)<\/li>\n<li>Producciones Vaiv\u00e9n<\/li>\n<li><span style=\"color: #ff0000;\"><strong>Mi\u00e9rcoles, 13 de noviembre<\/strong>.<\/span> 20:00. Teatro Gayarre<\/li>\n<li>Zaldi urdina<\/li>\n<li>Artedrama &#8211; Axut &#8211; Dejabu Panpin Laborategia<\/li>\n<li><span style=\"color: #ff0000;\"><strong>Jueves, 14 de noviembre<\/strong>.<\/span> 20:00. Teatro Gayarre<\/li>\n<li>Zaldi urdina (con sobret\u00edtulos en castellano)<\/li>\n<li>Artedrama &#8211; Axut &#8211; Dejabu Panpin Laborategia<\/li>\n<li><span style=\"color: #ff0000;\"><strong>Viernes, 22 de noviembre<\/strong>.<\/span> 20:00. Civivox Iturrama<\/li>\n<li>Txarriboda<\/li>\n<li>Hika Teatroa<\/li>\n<li><span style=\"color: #ff0000;\"><strong>Mi\u00e9rcoles, 11 de diciembre<\/strong>.<\/span> 20:00. Escuela Navarra de Teatro<\/li>\n<li>7ak bat<\/li>\n<li>Atx teatroa<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":17572,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-25298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rubik Teatre abre este jueves una nueva edici\u00f3n del ciclo de Antzerki Aroa con una obra basada en el teatro visual, los nuevos lenguajes teatrales y la po\u00e9tica del movimiento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rubik Teatre abre este jueves una nueva edici\u00f3n del ciclo de Antzerki Aroa con una obra basada en el teatro visual, los nuevos lenguajes teatrales y la po\u00e9tica del movimiento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-16T10:24:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-16T10:24:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/05\/teatro-gayarre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"Rubik Teatre abre este jueves una nueva edici\u00f3n del ciclo de Antzerki Aroa con una obra basada en el teatro visual, los nuevos lenguajes teatrales y la po\u00e9tica del movimiento\",\"datePublished\":\"2019-10-16T10:24:00+00:00\",\"dateModified\":\"2019-10-16T10:24:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\\\/\"},\"wordCount\":534,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/teatro-gayarre.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\\\/\",\"name\":\"Rubik Teatre abre este jueves una nueva edici\u00f3n del ciclo de Antzerki Aroa con una obra basada en el teatro visual, los nuevos lenguajes teatrales y la po\u00e9tica del movimiento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/teatro-gayarre.jpg\",\"datePublished\":\"2019-10-16T10:24:00+00:00\",\"dateModified\":\"2019-10-16T10:24:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/teatro-gayarre.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/teatro-gayarre.jpg\",\"width\":1000,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rubik Teatre abre este jueves una nueva edici\u00f3n del ciclo de Antzerki Aroa con una obra basada en el teatro visual, los nuevos lenguajes teatrales y la po\u00e9tica del movimiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rubik Teatre abre este jueves una nueva edici\u00f3n del ciclo de Antzerki Aroa con una obra basada en el teatro visual, los nuevos lenguajes teatrales y la po\u00e9tica del movimiento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/","og_locale":"es_ES","og_type":"article","og_title":"Rubik Teatre abre este jueves una nueva edici\u00f3n del ciclo de Antzerki Aroa con una obra basada en el teatro visual, los nuevos lenguajes teatrales y la po\u00e9tica del movimiento","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2019-10-16T10:24:00+00:00","article_modified_time":"2019-10-16T10:24:36+00:00","og_image":[{"width":1000,"height":607,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/05\/teatro-gayarre.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"Rubik Teatre abre este jueves una nueva edici\u00f3n del ciclo de Antzerki Aroa con una obra basada en el teatro visual, los nuevos lenguajes teatrales y la po\u00e9tica del movimiento","datePublished":"2019-10-16T10:24:00+00:00","dateModified":"2019-10-16T10:24:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/"},"wordCount":534,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/05\/teatro-gayarre.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/","name":"Rubik Teatre abre este jueves una nueva edici\u00f3n del ciclo de Antzerki Aroa con una obra basada en el teatro visual, los nuevos lenguajes teatrales y la po\u00e9tica del movimiento","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/05\/teatro-gayarre.jpg","datePublished":"2019-10-16T10:24:00+00:00","dateModified":"2019-10-16T10:24:36+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/05\/teatro-gayarre.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/05\/teatro-gayarre.jpg","width":1000,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/rubik-teatre-abre-este-jueves-una-nueva-edicion-del-ciclo-de-antzerki-aroa-con-una-obra-basada-en-el-teatro-visual-los-nuevos-lenguajes-teatrales-y-la-poetica-del-movimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Rubik Teatre abre este jueves una nueva edici\u00f3n del ciclo de Antzerki Aroa con una obra basada en el teatro visual, los nuevos lenguajes teatrales y la po\u00e9tica del movimiento"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/25298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=25298"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/25298\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/17572"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=25298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=25298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=25298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}