{"id":25287,"date":"2019-10-16T12:18:41","date_gmt":"2019-10-16T10:18:41","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=25287"},"modified":"2019-10-16T12:18:53","modified_gmt":"2019-10-16T10:18:53","slug":"el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/","title":{"rendered":"El Ayuntamiento concede 218.000 euros a diez entidades sin \u00e1nimo de lucro para la realizaci\u00f3n de proyectos art\u00edsticos a lo largo de este a\u00f1o"},"content":{"rendered":"<p><!--more--><\/p>\n<h3>Las entidades beneficiarias recibir\u00e1n ayudas que oscilan entre los 9.800 y los 28.500 euros, para sufragar proyectos de m\u00e1s de 70.000 euros<\/h3>\n<p>Un total de diez entidades sin \u00e1nimo de lucro se repartir\u00e1n los 218.000 euros que el Ayuntamiento de Pamplona ha concedido dentro de la convocatoria de ayudas a la realizaci\u00f3n de proyectos art\u00edsticos en la capital navarra durante este a\u00f1o 2019. Se trata de la tercera edici\u00f3n de esta convocatoria, que busca apoyar la programaci\u00f3n y realizaci\u00f3n de actividades culturales y art\u00edsticas como complemento a las que surgen de la iniciativa municipal. La condici\u00f3n para poder optar a las subvenciones pasaba por contar con un proyecto cuyo presupuesto fuera superior a 70.000 euros. Las ayudas individuales concedidas oscilan entre los 9.800 y los 28.500 euros.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>Las entidades adjudicatarias han sido la Agrupaci\u00f3n Coral de C\u00e1mara de Pamplona (con 22.913 euros), la Asociaci\u00f3n Gayarre Amigos de la \u00d3pera-AGAO (con 24.549), la Asociaci\u00f3n \u00d3pera de C\u00e1mara de Navarra (28.412), la Asociaci\u00f3n Santas Pascuas (26.186), Ateneo Navarro-Nafar Ateneoa (18.380), Coral de C\u00e1mara de Navarra (26.186), la Escuela Navarra de Teatro \u2013El Colectivo (16.366), la Federaci\u00f3n de Coros de Navarra (20.188), la Fundaci\u00f3n Atenea (9.820) y la Universidad P\u00fablica de Navarra, que ha recibido 25.000 euros para su programaci\u00f3n de promoci\u00f3n y difusi\u00f3n cultural dentro de la cuant\u00eda reservada para entidades dependientes del Gobierno de Navarra dentro de la convocatoria.<\/p>\n<p>La subvenci\u00f3n ahora resuelta est\u00e1 pensada para apoyar la organizaci\u00f3n y ejecuci\u00f3n en Pamplona de festivales, recitales, ciclos, cert\u00e1menes de artes esc\u00e9nicas, de m\u00fasica y de literatura, talleres; conferencias, cinef\u00f3rums y cualquier otra actividad que pueda ser considerada de car\u00e1cter cultural y art\u00edstico. Las entidades impulsoras deb\u00edan estar legalmente constituidas e inscritas en el registro correspondiente, con domicilio fiscal y social en Pamplona.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #ff0000;\">Entidades y Proyectos Subvencionados<\/span><\/h3>\n<p>&nbsp;<\/p>\n<table width=\"619\">\n<tbody>\n<tr>\n<td width=\"264\"><strong>ENTIDAD<\/strong><\/td>\n<td width=\"251\"><strong>PROYECTO<\/strong><\/td>\n<td width=\"104\"><strong>SUBVENCI\u00d3N<br \/>\n(euros)<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"264\">Agrupaci\u00f3n Coral de C\u00e1mara de Pamplona<\/td>\n<td width=\"251\">Proyecto art\u00edstico 2019<\/td>\n<td width=\"104\">22.913<\/td>\n<\/tr>\n<tr>\n<td width=\"264\">Asociaci\u00f3n Gayarre Amigos de la \u00d3pera (AGAO)<\/td>\n<td width=\"251\">Temporada de \u00f3pera y l\u00edrica 2019. L\u00edrica para todos: AGAO social, difusi\u00f3n y formaci\u00f3n<\/td>\n<td width=\"104\">24.549<\/td>\n<\/tr>\n<tr>\n<td width=\"264\">Asociaci\u00f3n \u00d3pera de C\u00e1mara de Navarra<\/td>\n<td width=\"251\">VIII Temporada de \u00d3pera<\/td>\n<td width=\"104\">28.412<\/td>\n<\/tr>\n<tr>\n<td width=\"264\">Asociaci\u00f3n Santas Pascuas<\/td>\n<td width=\"251\">Festival Santaspascuas 2019<\/td>\n<td width=\"104\">26.186<\/td>\n<\/tr>\n<tr>\n<td width=\"264\">Ateneo Navarro-Nafar Ateneoa<\/td>\n<td width=\"251\">Proyecto cultural a\u00f1o 2019<\/td>\n<td width=\"104\">18.380<\/td>\n<\/tr>\n<tr>\n<td width=\"264\">Coral de C\u00e1mara de Navarra<\/td>\n<td width=\"251\">Temporada Encantando Denboraldia 2019<\/td>\n<td width=\"104\">26.186<\/td>\n<\/tr>\n<tr>\n<td width=\"264\">Escuela Navarra de Teatro \u2013El Colectivo-<\/td>\n<td width=\"251\">Epicentro. Plataforma integral para el impulso de las artes esc\u00e9nicas (Epicentro-creativo y epicentro-golfos)<\/td>\n<td width=\"104\">16.366<\/td>\n<\/tr>\n<tr>\n<td width=\"264\">Federaci\u00f3n de Coros de Navarra<\/td>\n<td width=\"251\">Pamplona con voz propia<\/td>\n<td width=\"104\">20.188<\/td>\n<\/tr>\n<tr>\n<td width=\"264\">Fundaci\u00f3n Atenea<\/td>\n<td width=\"251\">Compa\u00f1\u00eda art\u00edstica ATENEA<\/td>\n<td width=\"104\">9.820<\/td>\n<\/tr>\n<tr>\n<td width=\"264\">Universidad P\u00fablica de Navarra<\/td>\n<td width=\"251\">Programaci\u00f3n de promoci\u00f3n y difusi\u00f3n cultural de la UPNA 2019<\/td>\n<td width=\"104\">25.000<\/td>\n<\/tr>\n<tr>\n<td width=\"264\"><strong>TOTAL<\/strong><\/td>\n<td width=\"251\"><strong>\u00a0<\/strong><\/td>\n<td width=\"104\"><strong>218.000<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":16728,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-25287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Ayuntamiento concede 218.000 euros a diez entidades sin \u00e1nimo de lucro para la realizaci\u00f3n de proyectos art\u00edsticos a lo largo de este a\u00f1o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Ayuntamiento concede 218.000 euros a diez entidades sin \u00e1nimo de lucro para la realizaci\u00f3n de proyectos art\u00edsticos a lo largo de este a\u00f1o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-16T10:18:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-16T10:18:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/03\/18.03.23_coral_camara_pamplona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"604\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El Ayuntamiento concede 218.000 euros a diez entidades sin \u00e1nimo de lucro para la realizaci\u00f3n de proyectos art\u00edsticos a lo largo de este a\u00f1o\",\"datePublished\":\"2019-10-16T10:18:41+00:00\",\"dateModified\":\"2019-10-16T10:18:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\\\/\"},\"wordCount\":472,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/18.03.23_coral_camara_pamplona.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\\\/\",\"name\":\"El Ayuntamiento concede 218.000 euros a diez entidades sin \u00e1nimo de lucro para la realizaci\u00f3n de proyectos art\u00edsticos a lo largo de este a\u00f1o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/18.03.23_coral_camara_pamplona.jpg\",\"datePublished\":\"2019-10-16T10:18:41+00:00\",\"dateModified\":\"2019-10-16T10:18:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/18.03.23_coral_camara_pamplona.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/18.03.23_coral_camara_pamplona.jpg\",\"width\":1000,\"height\":604},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Ayuntamiento concede 218.000 euros a diez entidades sin \u00e1nimo de lucro para la realizaci\u00f3n de proyectos art\u00edsticos a lo largo de este a\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Ayuntamiento concede 218.000 euros a diez entidades sin \u00e1nimo de lucro para la realizaci\u00f3n de proyectos art\u00edsticos a lo largo de este a\u00f1o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/","og_locale":"es_ES","og_type":"article","og_title":"El Ayuntamiento concede 218.000 euros a diez entidades sin \u00e1nimo de lucro para la realizaci\u00f3n de proyectos art\u00edsticos a lo largo de este a\u00f1o","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2019-10-16T10:18:41+00:00","article_modified_time":"2019-10-16T10:18:53+00:00","og_image":[{"width":1000,"height":604,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/03\/18.03.23_coral_camara_pamplona.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El Ayuntamiento concede 218.000 euros a diez entidades sin \u00e1nimo de lucro para la realizaci\u00f3n de proyectos art\u00edsticos a lo largo de este a\u00f1o","datePublished":"2019-10-16T10:18:41+00:00","dateModified":"2019-10-16T10:18:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/"},"wordCount":472,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/03\/18.03.23_coral_camara_pamplona.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/","name":"El Ayuntamiento concede 218.000 euros a diez entidades sin \u00e1nimo de lucro para la realizaci\u00f3n de proyectos art\u00edsticos a lo largo de este a\u00f1o","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/03\/18.03.23_coral_camara_pamplona.jpg","datePublished":"2019-10-16T10:18:41+00:00","dateModified":"2019-10-16T10:18:53+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/03\/18.03.23_coral_camara_pamplona.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/03\/18.03.23_coral_camara_pamplona.jpg","width":1000,"height":604},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-concede-218-000-euros-a-diez-entidades-sin-animo-de-lucro-para-la-realizacion-de-proyectos-artisticos-a-lo-largo-de-este-ano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El Ayuntamiento concede 218.000 euros a diez entidades sin \u00e1nimo de lucro para la realizaci\u00f3n de proyectos art\u00edsticos a lo largo de este a\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/25287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=25287"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/25287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/16728"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=25287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=25287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=25287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}