{"id":24898,"date":"2019-10-04T12:16:26","date_gmt":"2019-10-04T10:16:26","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=24898"},"modified":"2019-10-04T12:16:41","modified_gmt":"2019-10-04T10:16:41","slug":"convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/","title":{"rendered":"Convocado el certamen para proyectos de aprendizaje \u2013 servicio en centros educativos p\u00fablicos y concertados, cuyas propuestas se pueden presentar hasta el 20 de noviembre"},"content":{"rendered":"<p><!--more--><\/p>\n<h3>Se establecen tres modalidades para centros de Infantil y Primaria, de ESO y Bachillerato y de Formaci\u00f3n Profesional<\/h3>\n<p>El 20 de noviembre finaliza el plazo para que centros educativos p\u00fablicos y concertados de Pamplona presenten sus proyectos de aprendizaje \u2013 servicio al certamen organizado por el Ayuntamiento de Pamplona. La tercera edici\u00f3n de este certamen busca una vez m\u00e1s propuestas educativas que combinen procesos de aprendizaje y de servicio a la comunidad en un solo proyecto, bien articulado y en el que quienes participen aprendan a trabajar con necesidades reales del entorno para poder mejorarlo.<\/p>\n<p>El certamen pretende promover la elaboraci\u00f3n e implementaci\u00f3n de proyectos educativos de aprendizaje-servicio en los centros docentes p\u00fablicos y concertados de Pamplona, como una metodolog\u00eda did\u00e1ctica que combina procesos de aprendizaje basados en el curr\u00edculo de cada etapa y de servicio a la comunidad local por parte del alumnado. De este modo, el Ayuntamiento de Pamplona pretende hacer visible el compromiso solidario y c\u00edvico de los centros educativos, fortaleciendo la cohesi\u00f3n social y la participaci\u00f3n de todos los agentes de la comunidad en la mejora de las condiciones de la vida local.<\/p>\n<p>Podr\u00e1n tomar parte en el concurso los centros educativos p\u00fablicos o concertados de Pamplona de Educaci\u00f3n Infantil y Primaria, ESO \u2013 Bachillerato y Formaci\u00f3n Profesional en los que, al menos uno de sus docentes haya participado en el curso de formaci\u00f3n sobre aprendizaje-servicio convocado al efecto por el Ayuntamiento de Pamplona, o acredite una formaci\u00f3n previa similar en la metodolog\u00eda de aprendizaje servicios, mediante la presentaci\u00f3n de certificaci\u00f3n oficial. Los proyectos deben ser originales y estar elaborados para su implementaci\u00f3n en el curso 2019 \u2013 2020. Podr\u00e1n ser presentados en castellano o euskera, dependiendo del modelo ling\u00fc\u00edstico que se imparta en el centro.<\/p>\n<p>Cada centro escolar participante presentar\u00e1 un \u00fanico proyecto de aprendizaje-servicio por etapa educativa (Infantil y Primaria, ESO, Bachillerato), excepto los centros de Formaci\u00f3n Profesional. Se describen tres modelos con los que deben identificarse los proyectos presentados. El modelo A consiste en un proyecto de un grupo clase en el que se pretendan aprendizajes en una o m\u00e1s materias del curr\u00edculo, en el que colabore al menos una entidad social o instituci\u00f3n p\u00fablica de Pamplona. El modelo B recoge proyectos de m\u00e1s de un grupo clase en el que se pretendan aprendizajes en una o m\u00e1s materias del curr\u00edculo y en el que colabore al menos una entidad social o instituci\u00f3n p\u00fablica de Pamplona. El modelo C plasma proyectos de todo el centro educativo en el que colabore al menos una entidad social o instituci\u00f3n p\u00fablica de Pamplona.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><strong>Modalidades, premios y criterios del jurado<\/strong><\/p>\n<p>Las bases establecen tres modalidades de premios: modalidad 1 para proyectos de centros de Educaci\u00f3n Infantil y Primaria; modalidad 2 para centros de ESO y Bachillerato; y modalidad 3 para proyectos de centros de Formaci\u00f3n Profesional. Cada modalidad cuenta con un primer y un segundo premio dotados con 1.500 y 1.100 euros, respectivamente, que deber\u00e1n ser invertidos en el desarrollo del proyecto que lo ha recibido. Las propuestas de los centros educativos se deben presentar mediante instancia oficial al \u00e1rea de Educaci\u00f3n, Participaci\u00f3n Ciudadana y Juventud del Ayuntamiento de Pamplona (c\/ Descalzos, 72. 31001 Pamplona) o en cualquiera de los registros y medios recogidos en la ley.<\/p>\n<p>El jurado que determinar\u00e1 los premios estar\u00e1 presidido por el concejal delegado de Educaci\u00f3n, Participaci\u00f3n Ciudadana y Juventud y contar\u00e1 como vocales con personal t\u00e9cnico municipal del \u00e1rea de Educaci\u00f3n, una persona en representaci\u00f3n de la Red Navarra de Aprendizaje y Servicios Solidario y una persona ponente del curso de formaci\u00f3n sobre proyectos de aprendizaje-servicio organizado por el Ayuntamiento.<\/p>\n<p>Se valorar\u00e1n aspectos como la vinculaci\u00f3n entre los aprendizajes curriculares y el servicio que se pretende realizar; la envergadura de la pr\u00e1ctica, atendiendo al volumen del alumnado del centro; la autenticidad, relevancia e impacto en la ciudad del proyecto de servicio; el trabajo en red entre centros educativos y entidades sociales; la participaci\u00f3n activa del alumnado a lo largo de todo el proceso; que promuevan acciones de reflexi\u00f3n y pensamiento cr\u00edtico en el aprendizaje del alumnado participante; y que sean proyectos dirigidos a poblaci\u00f3n de Pamplona en riesgo de exclusi\u00f3n social o de difusi\u00f3n y apoyo a los derechos humanos y derechos de la infancia.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":21939,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-24898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocado el certamen para proyectos de aprendizaje \u2013 servicio en centros educativos p\u00fablicos y concertados, cuyas propuestas se pueden presentar hasta el 20 de noviembre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocado el certamen para proyectos de aprendizaje \u2013 servicio en centros educativos p\u00fablicos y concertados, cuyas propuestas se pueden presentar hasta el 20 de noviembre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-04T10:16:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-04T10:16:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"Convocado el certamen para proyectos de aprendizaje \u2013 servicio en centros educativos p\u00fablicos y concertados, cuyas propuestas se pueden presentar hasta el 20 de noviembre\",\"datePublished\":\"2019-10-04T10:16:26+00:00\",\"dateModified\":\"2019-10-04T10:16:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\\\/\"},\"wordCount\":772,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\\\/\",\"name\":\"Convocado el certamen para proyectos de aprendizaje \u2013 servicio en centros educativos p\u00fablicos y concertados, cuyas propuestas se pueden presentar hasta el 20 de noviembre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"datePublished\":\"2019-10-04T10:16:26+00:00\",\"dateModified\":\"2019-10-04T10:16:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/ayuntamiento-pamplona-laguiadepamplona.jpg\",\"width\":1920,\"height\":1100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocado el certamen para proyectos de aprendizaje \u2013 servicio en centros educativos p\u00fablicos y concertados, cuyas propuestas se pueden presentar hasta el 20 de noviembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocado el certamen para proyectos de aprendizaje \u2013 servicio en centros educativos p\u00fablicos y concertados, cuyas propuestas se pueden presentar hasta el 20 de noviembre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/","og_locale":"es_ES","og_type":"article","og_title":"Convocado el certamen para proyectos de aprendizaje \u2013 servicio en centros educativos p\u00fablicos y concertados, cuyas propuestas se pueden presentar hasta el 20 de noviembre","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2019-10-04T10:16:26+00:00","article_modified_time":"2019-10-04T10:16:41+00:00","og_image":[{"width":1920,"height":1100,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"Convocado el certamen para proyectos de aprendizaje \u2013 servicio en centros educativos p\u00fablicos y concertados, cuyas propuestas se pueden presentar hasta el 20 de noviembre","datePublished":"2019-10-04T10:16:26+00:00","dateModified":"2019-10-04T10:16:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/"},"wordCount":772,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/","name":"Convocado el certamen para proyectos de aprendizaje \u2013 servicio en centros educativos p\u00fablicos y concertados, cuyas propuestas se pueden presentar hasta el 20 de noviembre","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","datePublished":"2019-10-04T10:16:26+00:00","dateModified":"2019-10-04T10:16:41+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2019\/05\/ayuntamiento-pamplona-laguiadepamplona.jpg","width":1920,"height":1100},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/convocado-el-certamen-para-proyectos-de-aprendizaje-servicio-en-centros-educativos-publicos-y-concertados-cuyas-propuestas-se-pueden-presentar-hasta-el-20-de-noviembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Convocado el certamen para proyectos de aprendizaje \u2013 servicio en centros educativos p\u00fablicos y concertados, cuyas propuestas se pueden presentar hasta el 20 de noviembre"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/24898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=24898"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/24898\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/21939"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=24898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=24898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=24898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}