{"id":19384,"date":"2018-11-14T13:36:45","date_gmt":"2018-11-14T11:36:45","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=19384"},"modified":"2018-11-14T13:36:45","modified_gmt":"2018-11-14T11:36:45","slug":"el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/","title":{"rendered":"El Festival de jardiner\u00eda urbana acoger\u00e1 en esta edici\u00f3n hasta a 20 centros escolares, al ampliar las modalidades de participaci\u00f3n de \u2018Naturart II\u2019"},"content":{"rendered":"<h3>Aunque sin ejecutar jard\u00edn, otros diez centros podr\u00e1n presentar sus maquetas sobre cambio clim\u00e1tico y desarrollar ese debate en sus aulas<\/h3>\n<p><!--more--><\/p>\n<p>14 centros escolares han presentado su candidatura para construir jardines ef\u00edmeros en los fosos de la Ciudadela para la segunda edici\u00f3n de Naturart, el festival de jardiner\u00eda urbana de Pamplona, este a\u00f1o en torno al \u2018Cambio clim\u00e1tico\u2019. Como el acceso al programa se ha realizado en riguroso orden de inscripci\u00f3n y s\u00f3lo pueden realizarse los jardines de los 10 primeros inscritos, dado el espacio limitado en los fosos, el Consistorio ha previsto una nueva modalidad para poder tomar parte.<\/p>\n<p>Este a\u00f1o a los diez centros interesados que no hayan llegado a tiempo se les permitir\u00e1 participar en la fase de presentaci\u00f3n de maquetas de \u2018Naturart II\u2019, aunque no podr\u00e1n ejecutar el resultado final. Ya hay cuatro solicitudes en esta modalidad y quedan seis posibles plazas libres que de nuevo se cubrir\u00e1n en orden de inscripci\u00f3n hasta el 30 de noviembre. El programa y su actual ampliaci\u00f3n est\u00e1 dirigido a los centros de Secundaria, Bachiller y FP. Quienes deseen apuntarse a la fase de realizaci\u00f3n de las maquetas podr\u00e1n hacerlo contactando directamente con el equipo coordinador (en el tel\u00e9fono 948 210131 de lunes a viernes de 9 a 14 horas). Adem\u00e1s, este a\u00f1o se invitar\u00e1 a paisajistas a que realicen dise\u00f1os propios en una zona contigua de los fosos, como el pasado a\u00f1o hizo el propio Consistorio pamplon\u00e9s.<\/p>\n<p>Todas las maquetas de jardines creadas por los centros podr\u00e1n ser expuestas en los ayuntamientos o centros culturales de los municipios participantes, asi como en el espacio cultural que determine el Ayuntamiento de Pamplona. Y es que uno de los fines del programa es llevar la reflexi\u00f3n sobre la jardiner\u00eda, la sostenibilidad y la creatividad art\u00edstica al mayor n\u00famero de aulas posibles de forma que, a partir de ahora, y hasta el mes de junio, el alumnado trabajar\u00e1 sus maquetas en los centros escolares con la ayuda de jardineros profesionales de Pamplona y la Comarca de Pamplona.<\/p>\n<p><strong>Ocho de los 10 centros ya tienen experiencia en Naturart<\/strong><\/p>\n<p>Como el pasado junio, en esta edici\u00f3n los jardines ocupar\u00e1n unos 1.500 m<sup>2<\/sup> en los fosos del entorno del Revell\u00edn de Santa Isabel, a la altura de la Puerta del Socorro de la Ciudadela. Ahora se acordar\u00e1 con los centros educativos los detalles y el cronograma de cada propuesta, tras lo que seguidamente se llevar\u00e1 a cabo una sesi\u00f3n formativa para el alumnado. Los centros que ha presentado solicitud en los 10 primeros puestos han sido: CI Agroforestal; CI Cuatrovientos; Nuestra Se\u00f1ora del Huerto; IES Ochoa de Olza; Iturrama BHI; Jaso ikastola; La Compasi\u00f3n Escolapios; IES Mendillorri BHI; Sagrado Coraz\u00f3n y San C\u00e9rnin. Ocho de los centros de esta edici\u00f3n han decidido repetir, porque ya participaron en Naturart I.<\/p>\n<p>A partir de ahora los centros deber\u00e1n trabajar en una maqueta f\u00edsica o electr\u00f3nica y un plano de ejecuci\u00f3n de su proyecto que deber\u00e1n presentar en febrero. Luego vendr\u00e1 la parte t\u00e9cnica de encaje de la idea con los materiales y plantas m\u00e1s adecuadas, una elecci\u00f3n que se har\u00e1 en coordinaci\u00f3n con los servicios de jardines mentores. Los equipos mixtos de alumnado y personal de jardiner\u00eda usar\u00e1n \u00fanicamente materiales reciclados y reciclables, plantas y la conjugaci\u00f3n de diversas alturas en el corte de la hierba, sobre un espacio acotado de 120 m<sup>2<\/sup>. Como en la pasada edici\u00f3n los jardines quedar\u00e1n expuestos al p\u00fablico hasta la siega previa a San Ferm\u00edn.<\/p>\n<p>Ahora el Ayuntamiento de Pamplona buscar\u00e1 la colaboraci\u00f3n de diferentes Servicios Municipales de Jardines. En la pasada edici\u00f3n del Festival de jardiner\u00eda urbana en junio de 2018 se realizaron 10 jardines a cargo de 487 escolares y se implicaron en sus proyectos como mentores los servicios, no solo de Pamplona, sino tambi\u00e9n de siete Ayuntamiento de la Comarca: Burlada, No\u00e1in-Valle de Elorz, Aranguren, Eg\u00fc\u00e9s, Berriozar, Orkoien y Ansoain que se embarcar\u00e1n en trasponer los proyectos esbozados por los estudiantes a los fosos de la fortificaci\u00f3n.<\/p>\n<p>Una idea a escala ciudad<\/p>\n<p>El protagonismo de los escolares en este proyecto busca dar voz a la ciudadan\u00eda, tambi\u00e9n a la m\u00e1s joven, en el dise\u00f1o del espacio com\u00fan. Pero, en su concepto de desarrollo, \u2018Naturart\u2019 tiene la virtualidad de ser una forma de actuar sobre el paisaje urbano de la mano de profesionales del mundo de la jardiner\u00eda y el paisajismo, modific\u00e1ndolo de forma no radical, para reenfocar la atenci\u00f3n del paseante en las zonas verdes de la ciudad que ya conoce. Los jardines de \u2018Naturart\u2019 se realizan en primavera y sus dise\u00f1os fugaces desaparecer\u00e1n mediante la siega a las puertas de San Ferm\u00edn.<\/p>\n<p>Adem\u00e1s de implicar a una importante parte de la ciudadan\u00eda, desde el punto de vista de la Administraci\u00f3n Local este programa pone en funcionamiento coordinado a las \u00e1reas municipales de Ciudad Habitable y Vivienda, Cultura y Educaci\u00f3n y Ecolog\u00eda Urbana y Movilidad, adem\u00e1s de entidades colaboradoras como la Mancomunidad de la Comarca de Pamplona o Traperos de Ema\u00fas.<\/p>\n<p>Finalmente \u2018Naturart\u2019 pretende ser el resultado del sincretismo entre dos conceptos: el movimiento de arte ef\u00edmero contempor\u00e1neo que encaja en la l\u00ednea de trabajo de Hiriartea y el esfuerzo de concienciaci\u00f3n ambiental, tanto del Servicio de Parques Jardines y Zonas Verdes, como del de educaci\u00f3n ambiental del Ayuntamiento de Pamplona.<\/p>\n<p>Los centros que ejecutar\u00e1n jardines ef\u00edmeros en Naturart II<\/p>\n<ul>\n<li>CI agroforestal<\/li>\n<li>CI Cuatrovientos<\/li>\n<li>Nuestra Se\u00f1ora del Huerto<\/li>\n<li>IES Ochoa de Olza<\/li>\n<li>Iturrama BHI<\/li>\n<li>Jaso ikastola<\/li>\n<li>La Compasi\u00f3n Escolapios<\/li>\n<li>IES Mendillorri BHI<\/li>\n<li>Sagrado Coraz\u00f3n<\/li>\n<li>San C\u00e9rnin<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque sin ejecutar jard\u00edn, otros diez centros podr\u00e1n presentar sus maquetas sobre cambio clim\u00e1tico y desarrollar ese debate en sus aulas<\/p>\n","protected":false},"author":1,"featured_media":18869,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-19384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Festival de jardiner\u00eda urbana acoger\u00e1 en esta edici\u00f3n hasta a 20 centros escolares, al ampliar las modalidades de participaci\u00f3n de \u2018Naturart II\u2019<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Festival de jardiner\u00eda urbana acoger\u00e1 en esta edici\u00f3n hasta a 20 centros escolares, al ampliar las modalidades de participaci\u00f3n de \u2018Naturart II\u2019\" \/>\n<meta property=\"og:description\" content=\"Aunque sin ejecutar jard\u00edn, otros diez centros podr\u00e1n presentar sus maquetas sobre cambio clim\u00e1tico y desarrollar ese debate en sus aulas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona Noticias y actualidad\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-14T11:36:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/10\/18.10.03_Naturart_primera_edicion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El Festival de jardiner\u00eda urbana acoger\u00e1 en esta edici\u00f3n hasta a 20 centros escolares, al ampliar las modalidades de participaci\u00f3n de \u2018Naturart II\u2019\",\"datePublished\":\"2018-11-14T11:36:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\\\/\"},\"wordCount\":1011,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/18.10.03_Naturart_primera_edicion.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\\\/\",\"name\":\"El Festival de jardiner\u00eda urbana acoger\u00e1 en esta edici\u00f3n hasta a 20 centros escolares, al ampliar las modalidades de participaci\u00f3n de \u2018Naturart II\u2019\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/18.10.03_Naturart_primera_edicion.jpg\",\"datePublished\":\"2018-11-14T11:36:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/18.10.03_Naturart_primera_edicion.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/18.10.03_Naturart_primera_edicion.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Festival de jardiner\u00eda urbana acoger\u00e1 en esta edici\u00f3n hasta a 20 centros escolares, al ampliar las modalidades de participaci\u00f3n de \u2018Naturart II\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Festival de jardiner\u00eda urbana acoger\u00e1 en esta edici\u00f3n hasta a 20 centros escolares, al ampliar las modalidades de participaci\u00f3n de \u2018Naturart II\u2019","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/","og_locale":"es_ES","og_type":"article","og_title":"El Festival de jardiner\u00eda urbana acoger\u00e1 en esta edici\u00f3n hasta a 20 centros escolares, al ampliar las modalidades de participaci\u00f3n de \u2018Naturart II\u2019","og_description":"Aunque sin ejecutar jard\u00edn, otros diez centros podr\u00e1n presentar sus maquetas sobre cambio clim\u00e1tico y desarrollar ese debate en sus aulas","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/","og_site_name":"La Gu\u00eda de Pamplona Noticias y actualidad","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2018-11-14T11:36:45+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/10\/18.10.03_Naturart_primera_edicion.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El Festival de jardiner\u00eda urbana acoger\u00e1 en esta edici\u00f3n hasta a 20 centros escolares, al ampliar las modalidades de participaci\u00f3n de \u2018Naturart II\u2019","datePublished":"2018-11-14T11:36:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/"},"wordCount":1011,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/10\/18.10.03_Naturart_primera_edicion.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/","name":"El Festival de jardiner\u00eda urbana acoger\u00e1 en esta edici\u00f3n hasta a 20 centros escolares, al ampliar las modalidades de participaci\u00f3n de \u2018Naturart II\u2019","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/10\/18.10.03_Naturart_primera_edicion.jpg","datePublished":"2018-11-14T11:36:45+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/10\/18.10.03_Naturart_primera_edicion.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/10\/18.10.03_Naturart_primera_edicion.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-festival-de-jardineria-urbana-acogera-en-esta-edicion-hasta-a-20-centros-escolares-al-ampliar-las-modalidades-de-participacion-de-naturart-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El Festival de jardiner\u00eda urbana acoger\u00e1 en esta edici\u00f3n hasta a 20 centros escolares, al ampliar las modalidades de participaci\u00f3n de \u2018Naturart II\u2019"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/19384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=19384"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/19384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/18869"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=19384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=19384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=19384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}