{"id":18570,"date":"2018-08-30T11:47:15","date_gmt":"2018-08-30T09:47:15","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=18570"},"modified":"2018-08-30T11:47:15","modified_gmt":"2018-08-30T09:47:15","slug":"el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/","title":{"rendered":"El tel\u00e9fono 010, la red Civivox y la Casa de la Juventud retoman su horario habitual en septiembre, una vez concluidos los meses de verano"},"content":{"rendered":"<p><!--more--><\/p>\n<p>Con la llegada del mes de septiembre, servicios municipales como la atenci\u00f3n telef\u00f3nica del 010, la red Civivox o la Casa de la Juventud retoman su horario habitual, que mantendr\u00e1n durante todo el curso. Durante los meses de julio y agosto, estos servicios e instalaciones han adoptado un horario de verano, sin atenci\u00f3n los fines de semana como principal caracter\u00edstica (excepto Civivox Condestable).<\/p>\n<p>El tel\u00e9fono 010 \u2013 948 420 100 atender\u00e1 desde el 1 de septiembre de lunes a viernes, en horario ininterrumpido, de 8 a 19 horas y los s\u00e1bados el servicio estar\u00e1 operativo solo por las ma\u00f1anas, de 9.30 a 13.30 horas. Durante el verano la atenci\u00f3n telef\u00f3nica se est\u00e1 llevando a cabo de lunes a viernes, de 8 a 15 horas.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Noticias La Guia de Pamplona --><br \/>\n<ins class=\"adsbygoogle\"\nstyle=\"display:block\"\ndata-ad-client=\"ca-pub-6943679897239327\"\ndata-ad-slot=\"7048180777\"\ndata-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>La red Civivox retoma tambi\u00e9n los habituales horarios de apertura y cierre de sus centros tras el par\u00e9ntesis estival. Durante el verano la atenci\u00f3n se centralizaba de lunes a viernes, de 9 a 14 horas por la ma\u00f1ana, con la excepci\u00f3n de Condestable que abr\u00eda tambi\u00e9n por las tardes de 17 a 22 horas y los s\u00e1bados de 9 a 14 horas. Desde este s\u00e1bado 1 de septiembre entre en vigor en horario habitual del curso. Los siete centros Civivox (Condestable, Jus la Rocha, Iturrama, Mendillorri, Ensanche, Milagrosa y San Jorge) abren de lunes a s\u00e1bado, de 9 a 14 horas y de 17 a 22 horas. A partir del 15 de septiembre, Condestable estar\u00e1 abierto los domingos, de 9 a 14 y de 17 a 22 horas. Iturrama, Mendillorri y San Jorge abrir\u00e1n tambi\u00e9n los domingos, seg\u00fan la programaci\u00f3n que acojan.<\/p>\n<p>La Casa de la Juventud abre a partir de septiembre de lunes a viernes, de 9 a 14 horas por la ma\u00f1ana y de 17 a 22 horas por la tarde. Los s\u00e1bados las instalaciones permanecen abiertas de 10 a 14 horas y de 17 a 21 horas. La Casa de la Juventud est\u00e1n tambi\u00e9n abierta los domingos en horario de ma\u00f1ana, de 10 a 14 horas. Durante el verano, del 16 de julio al 31 de agosto, la Casa ha tenido un horario de lunes a viernes, de 9 a 12 horas y de 17 a 22 horas.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":13864,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-18570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El tel\u00e9fono 010, la red Civivox y la Casa de la Juventud retoman su horario habitual en septiembre, una vez concluidos los meses de verano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El tel\u00e9fono 010, la red Civivox y la Casa de la Juventud retoman su horario habitual en septiembre, una vez concluidos los meses de verano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona Noticias y actualidad\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-30T09:47:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/08\/cada_dia_plan_juventud.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"527\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El tel\u00e9fono 010, la red Civivox y la Casa de la Juventud retoman su horario habitual en septiembre, una vez concluidos los meses de verano\",\"datePublished\":\"2018-08-30T09:47:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\\\/\"},\"wordCount\":375,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/cada_dia_plan_juventud.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\\\/\",\"name\":\"El tel\u00e9fono 010, la red Civivox y la Casa de la Juventud retoman su horario habitual en septiembre, una vez concluidos los meses de verano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/cada_dia_plan_juventud.jpg\",\"datePublished\":\"2018-08-30T09:47:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/cada_dia_plan_juventud.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/cada_dia_plan_juventud.jpg\",\"width\":1000,\"height\":527},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El tel\u00e9fono 010, la red Civivox y la Casa de la Juventud retoman su horario habitual en septiembre, una vez concluidos los meses de verano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El tel\u00e9fono 010, la red Civivox y la Casa de la Juventud retoman su horario habitual en septiembre, una vez concluidos los meses de verano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/","og_locale":"es_ES","og_type":"article","og_title":"El tel\u00e9fono 010, la red Civivox y la Casa de la Juventud retoman su horario habitual en septiembre, una vez concluidos los meses de verano","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/","og_site_name":"La Gu\u00eda de Pamplona Noticias y actualidad","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2018-08-30T09:47:15+00:00","og_image":[{"width":1000,"height":527,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/08\/cada_dia_plan_juventud.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El tel\u00e9fono 010, la red Civivox y la Casa de la Juventud retoman su horario habitual en septiembre, una vez concluidos los meses de verano","datePublished":"2018-08-30T09:47:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/"},"wordCount":375,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/08\/cada_dia_plan_juventud.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/","name":"El tel\u00e9fono 010, la red Civivox y la Casa de la Juventud retoman su horario habitual en septiembre, una vez concluidos los meses de verano","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/08\/cada_dia_plan_juventud.jpg","datePublished":"2018-08-30T09:47:15+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/08\/cada_dia_plan_juventud.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/08\/cada_dia_plan_juventud.jpg","width":1000,"height":527},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-telefono-010-la-red-civivox-y-la-casa-de-la-juventud-retoman-su-horario-habitual-en-septiembre-una-vez-concluidos-los-meses-de-verano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El tel\u00e9fono 010, la red Civivox y la Casa de la Juventud retoman su horario habitual en septiembre, una vez concluidos los meses de verano"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/18570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=18570"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/18570\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/13864"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=18570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=18570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=18570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}