{"id":18554,"date":"2018-08-29T15:41:42","date_gmt":"2018-08-29T13:41:42","guid":{"rendered":"https:\/\/www.laguiadepamplona.es\/actualidad\/?p=18554"},"modified":"2018-08-29T15:41:42","modified_gmt":"2018-08-29T13:41:42","slug":"grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/","title":{"rendered":"Grandes \u00e9xitos y canciones de siempre, propuesta musical del grupo Tocar Madera este jueves en el paseo peatonal de Carlos III"},"content":{"rendered":"<h3>El concierto al aire libre comenzar\u00e1 a las 20 horas, con entrada libre, en la confluencia de Carlos III con la calle San Ferm\u00edn<!--more--><\/h3>\n<p>Nueva cita con el ciclo Auzokale de actuaciones y espect\u00e1culos en los diferentes barrio de la ciudad durante este periodo veraniego. Ma\u00f1ana jueves ser\u00e1 el turno del grupo Tocar Madera, que acercar\u00e1n a Carlos III canciones de siempre y grandes \u00e9xitos del pop \u2013 rock. La actuaci\u00f3n al aire libre empezar\u00e1 a las 20 horas, en entrada libre, en la confluencia de la peatonal de Carlos III con la calle San Ferm\u00edn.<\/p>\n<p>Tocar Madera mantienen su sello caracter\u00edstico de empaste y armonizaci\u00f3n de voces e instrumentos, pero dan un paso m\u00e1s, ya que a su habitual repertorio de ya no se centra exclusivamente en canciones cl\u00e1sicas y de siempre, de son cubano, de vals peruano o de canci\u00f3n popular argentina suman otros g\u00e9neros y ritmos. El grupo surge de la uni\u00f3n del cantautor Carlos L\u00e1zaro y dos de los integrantes de Los Compadres, To\u00f1o Sastre y Miguel \u00c1ngel Ugarte. A mediados de 2016 ambas formaciones deciden hacer un alto el camino de sus respectivas bandas, para disfrutar de la m\u00fasica desde otro punto de vista y que es de la versi\u00f3n musical.<\/p>\n<p>Para ello toman algunos de los principales \u00e9xitos del pop y del rock de todos los tiempos, para llevarlos a un terreno latino y ac\u00fastico, brind\u00e1ndonos temas de Queen, U2 o Coldplay, desde la rumba, el bolero o el cha cha cha. Todo ello sin olvidarse de los principales \u00e9xitos y artistas latinos m\u00e1s recientes como pueden ser Juanes o Joaqu\u00edn Sabina. Este cocktail musical desemboca en un espect\u00e1culo ameno y muy participativo, al tratarse de un repertorio m\u00e1s que reconocible por el p\u00fablico. En el concierto de este jueves versionar\u00e1n temas como \u2018Hotel California\u2019, \u2018I want to break free\u2019, \u2018Every breath you take\u2019, \u2018Camisa negra\u2019, \u2018Despacito\u2019 o \u201919 d\u00edas y 500 noches\u2019.<\/p>\n<p>Esta actuaci\u00f3n forma parte del programa Auzokale, dentro de las actividades programadas por el Ayuntamiento y la red Civivox en estos meses de verano. Las siguientes citas tendr\u00e1n lugar los d\u00edas 1 y 4 de septiembre. El s\u00e1bado los payasos Txispi y Popi presentar\u00e1n su espect\u00e1culo \u2018de travesuras\u2019 en el patio de Civivox Milagrosa en doble sesi\u00f3n, a las 12 y a las 18.30 horas. El martes 4 de septiembre el parque de la Runa de la Rochapea acoger\u00e1 el concierto \u2018Ta tante et toi\u2019 del grupo Gancho Drom, a partir de las 20 horas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Auzokale. Otros espect\u00e1culos en barrios<\/strong><\/p>\n<ul>\n<li>Paseo Peatonal Carlos III. Tocar madera. 30 de agosto. 20 horas<\/li>\n<li>Patio de Civivox Milagrosa. \u2018Travesuras de payasos\u2019. Txispi y Popi. 1 de septiembre. 12 y 18.30 horas<\/li>\n<li>Teatro Parque de la Runa. \u2018Ta tante et toi\u2019. Gancho Drome. 4 de septiembre. 22 horas<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El concierto al aire libre comenzar\u00e1 a las 20 horas, con entrada libre, en la confluencia de Carlos III con la calle San Ferm\u00edn<\/p>\n","protected":false},"author":1,"featured_media":17600,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-18554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grandes \u00e9xitos y canciones de siempre, propuesta musical del grupo Tocar Madera este jueves en el paseo peatonal de Carlos III<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grandes \u00e9xitos y canciones de siempre, propuesta musical del grupo Tocar Madera este jueves en el paseo peatonal de Carlos III\" \/>\n<meta property=\"og:description\" content=\"El concierto al aire libre comenzar\u00e1 a las 20 horas, con entrada libre, en la confluencia de Carlos III con la calle San Ferm\u00edn\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona Noticias y actualidad\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-29T13:41:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/05\/ayto-pamplona-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"555\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"Grandes \u00e9xitos y canciones de siempre, propuesta musical del grupo Tocar Madera este jueves en el paseo peatonal de Carlos III\",\"datePublished\":\"2018-08-29T13:41:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\\\/\"},\"wordCount\":501,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/ayto-pamplona-3.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\\\/\",\"name\":\"Grandes \u00e9xitos y canciones de siempre, propuesta musical del grupo Tocar Madera este jueves en el paseo peatonal de Carlos III\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/ayto-pamplona-3.jpg\",\"datePublished\":\"2018-08-29T13:41:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/ayto-pamplona-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/ayto-pamplona-3.jpg\",\"width\":1000,\"height\":555},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grandes \u00e9xitos y canciones de siempre, propuesta musical del grupo Tocar Madera este jueves en el paseo peatonal de Carlos III\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grandes \u00e9xitos y canciones de siempre, propuesta musical del grupo Tocar Madera este jueves en el paseo peatonal de Carlos III","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/","og_locale":"es_ES","og_type":"article","og_title":"Grandes \u00e9xitos y canciones de siempre, propuesta musical del grupo Tocar Madera este jueves en el paseo peatonal de Carlos III","og_description":"El concierto al aire libre comenzar\u00e1 a las 20 horas, con entrada libre, en la confluencia de Carlos III con la calle San Ferm\u00edn","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/","og_site_name":"La Gu\u00eda de Pamplona Noticias y actualidad","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2018-08-29T13:41:42+00:00","og_image":[{"width":1000,"height":555,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/05\/ayto-pamplona-3.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"Grandes \u00e9xitos y canciones de siempre, propuesta musical del grupo Tocar Madera este jueves en el paseo peatonal de Carlos III","datePublished":"2018-08-29T13:41:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/"},"wordCount":501,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/05\/ayto-pamplona-3.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/","name":"Grandes \u00e9xitos y canciones de siempre, propuesta musical del grupo Tocar Madera este jueves en el paseo peatonal de Carlos III","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/05\/ayto-pamplona-3.jpg","datePublished":"2018-08-29T13:41:42+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/05\/ayto-pamplona-3.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/05\/ayto-pamplona-3.jpg","width":1000,"height":555},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/grandes-exitos-y-canciones-de-siempre-propuesta-musical-del-grupo-tocar-madera-este-jueves-en-el-paseo-peatonal-de-carlos-iii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Grandes \u00e9xitos y canciones de siempre, propuesta musical del grupo Tocar Madera este jueves en el paseo peatonal de Carlos III"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/18554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=18554"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/18554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/17600"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=18554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=18554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=18554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}