{"id":14505,"date":"2017-10-02T14:18:01","date_gmt":"2017-10-02T13:18:01","guid":{"rendered":"http:\/\/laguiadepamplona.es\/actualidad\/?p=14505"},"modified":"2017-10-02T14:18:01","modified_gmt":"2017-10-02T13:18:01","slug":"cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/","title":{"rendered":"Cuatro personas detenidas la semana pasada por conducir bajo los efectos del alcohol o negarse a realizar la prueba de etilometr\u00eda"},"content":{"rendered":"<h3>Polic\u00eda Municipal denunci\u00f3 adem\u00e1s a otras 17 personas por v\u00eda administrativa<\/h3>\n<p><!--more--><\/p>\n<p>Polic\u00eda Municipal de Pamplona detuvo la semana pasada a cuatro personas por conducir bajo los efectos del alcohol o negarse a realizar la prueba de etilometr\u00eda. Una de las detenciones se realiz\u00f3 el lunes, otra el jueves y dos el viernes. En tres casos, los conductores dieron positivo en alcoholemia y en otro, la persona que conduc\u00eda se neg\u00f3 a realizar la prueba de etilometr\u00eda por lo que se le acusa tambi\u00e9n de un presundo delito de conducci\u00f3n bajo los efectos del alcohol. Este hecho se produjo el viernes.<\/p>\n<p>Adem\u00e1s, entre el lunes 25 de septiembre y el domingo 1 de octubre, Polic\u00eda Municipal denunci\u00f3 por v\u00eda administrativa a 17 personas. 13 fueron por dar positivos en controles de alcoholemia, aunque sin alcanzar tasas constitutivas de delito. Dos m\u00e1s fueron sancionadas por circular bajo los efectos de las drogas y otras dos por conducir con los permisos de circulaci\u00f3n sin vigencia. Las denuncias se interpusieron una el lunes (una denuncia por drogas), dos el mi\u00e9rcoles (por etilometr\u00eda por p\u00e9rdida de vigencia del permiso de circulaci\u00f3n), otra el jueves (la segunda denuncia por drogas), 10 el viernes (9 por positivo en alcoholemia y otra por no tener el carn\u00e9 de conducir en vigencia) y otras 3 el s\u00e1bado, todas ellas por positivo en alcoholemia.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Polic\u00eda Municipal denunci\u00f3 adem\u00e1s a otras 17 personas por v\u00eda administrativa<\/p>\n","protected":false},"author":1,"featured_media":14501,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-14505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuatro personas detenidas la semana pasada por conducir bajo los efectos del alcohol o negarse a realizar la prueba de etilometr\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuatro personas detenidas la semana pasada por conducir bajo los efectos del alcohol o negarse a realizar la prueba de etilometr\u00eda\" \/>\n<meta property=\"og:description\" content=\"Polic\u00eda Municipal denunci\u00f3 adem\u00e1s a otras 17 personas por v\u00eda administrativa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-02T13:18:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/09\/POLIC\u00cdA-MUNICIPAL_Nueva-imagen_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"Cuatro personas detenidas la semana pasada por conducir bajo los efectos del alcohol o negarse a realizar la prueba de etilometr\u00eda\",\"datePublished\":\"2017-10-02T13:18:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\\\/\"},\"wordCount\":258,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/POLIC\u00cdA-MUNICIPAL_Nueva-imagen_2.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\\\/\",\"name\":\"Cuatro personas detenidas la semana pasada por conducir bajo los efectos del alcohol o negarse a realizar la prueba de etilometr\u00eda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/POLIC\u00cdA-MUNICIPAL_Nueva-imagen_2.jpg\",\"datePublished\":\"2017-10-02T13:18:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/POLIC\u00cdA-MUNICIPAL_Nueva-imagen_2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/POLIC\u00cdA-MUNICIPAL_Nueva-imagen_2.jpg\",\"width\":1000,\"height\":666},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuatro personas detenidas la semana pasada por conducir bajo los efectos del alcohol o negarse a realizar la prueba de etilometr\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuatro personas detenidas la semana pasada por conducir bajo los efectos del alcohol o negarse a realizar la prueba de etilometr\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/","og_locale":"es_ES","og_type":"article","og_title":"Cuatro personas detenidas la semana pasada por conducir bajo los efectos del alcohol o negarse a realizar la prueba de etilometr\u00eda","og_description":"Polic\u00eda Municipal denunci\u00f3 adem\u00e1s a otras 17 personas por v\u00eda administrativa","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2017-10-02T13:18:01+00:00","og_image":[{"width":1000,"height":666,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/09\/POLIC\u00cdA-MUNICIPAL_Nueva-imagen_2.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"Cuatro personas detenidas la semana pasada por conducir bajo los efectos del alcohol o negarse a realizar la prueba de etilometr\u00eda","datePublished":"2017-10-02T13:18:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/"},"wordCount":258,"commentCount":0,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/09\/POLIC\u00cdA-MUNICIPAL_Nueva-imagen_2.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/","name":"Cuatro personas detenidas la semana pasada por conducir bajo los efectos del alcohol o negarse a realizar la prueba de etilometr\u00eda","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/09\/POLIC\u00cdA-MUNICIPAL_Nueva-imagen_2.jpg","datePublished":"2017-10-02T13:18:01+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/09\/POLIC\u00cdA-MUNICIPAL_Nueva-imagen_2.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/09\/POLIC\u00cdA-MUNICIPAL_Nueva-imagen_2.jpg","width":1000,"height":666},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/cuatro-personas-detenidas-la-semana-pasada-por-conducir-bajo-los-efectos-del-alcohol-o-negarse-a-realizar-la-prueba-de-etilometria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Cuatro personas detenidas la semana pasada por conducir bajo los efectos del alcohol o negarse a realizar la prueba de etilometr\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/14505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=14505"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/14505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/14501"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=14505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=14505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=14505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}