{"id":13603,"date":"2017-06-22T12:20:13","date_gmt":"2017-06-22T11:20:13","guid":{"rendered":"http:\/\/laguiadepamplona.es\/actualidad\/?p=13603"},"modified":"2017-06-22T12:20:13","modified_gmt":"2017-06-22T11:20:13","slug":"condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/","title":{"rendered":"Condestable presenta ma\u00f1ana viernes \u2018Euskofoniak\u2019, un espect\u00e1culo de reflexi\u00f3n musical y danza tradicional desde un lenguaje contempor\u00e1neo"},"content":{"rendered":"<h3 class=\"western\">La actuaci\u00f3n, que comienza a las 19.30 horas, est\u00e1 protagonizada por \u2018Txiplin\u2019 a la guitarra, I\u00f1aki Lero con la percusi\u00f3n y el dantzari Iker Larumbe<\/h3>\n<p lang=\"es-ES\"><!--more--><br \/>\n<span style=\"font-family: Arial,sans-serif;\">El Palacio del Condestable presenta ma\u00f1ana viernes, 23 de junio, <span lang=\"eu\">\u2018<\/span>Euskofoniak\u2019, un espect\u00e1culo de reflexi\u00f3n musical y danza tradicional desde un lenguaje contempor\u00e1neo. Estar\u00e1 protagonizado por \u2018Txiplin\u2019 a la guitarra, I\u00f1aki Lero con la percusi\u00f3n y el dantzari Iker Larumbe. Comenzar\u00e1 a las 19.30 horas y la entrada es libre.<\/span><\/p>\n<p lang=\"es-ES\"><span style=\"font-family: Arial,sans-serif;\">Los creadores a la hora de hablar de \u2018Euskofoniak\u2019 se\u00f1alan que \u201ctomando como base las danzas tradicionales vascas, interpretamos creativamente esta herencia cultural en un proceso de reflexi\u00f3n musical que entabla un di\u00e1logo entre la guitarra y el resto de instrumentos\u201d. Asimismo, se\u00f1alan que este proyecto musical desarrolla un recorrido en el tiempo desde un lenguaje contempor\u00e1neo \u201ccomo una exploraci\u00f3n en lo m\u00e1s hondo de la sensibilidad imaginativa de nuestro pueblo y teniendo como precedente la experimentaci\u00f3n; una nueva mirada al lenguaje popular, un ejercicio de recuperaci\u00f3n de nuestro sentimiento y legado m\u00e1s profundo donde poder experimentar desde distintos lenguajes musicales\u201d.<\/span><\/p>\n<p lang=\"es-ES\"><span style=\"font-family: Arial,sans-serif;\">Esta actividad se enmarca en un programa de reflexi\u00f3n en torno a los Sanfermines abierto a toda la ciudadan\u00eda organizado por primera vez por el Ayuntamiento de Pamplona que est\u00e1 ofreciendo a lo largo de este mes de junio exposiciones, conferencias, cine, talleres, visitas guiadas, mesas redondas, actuaciones musicales y espect\u00e1culo de danza. Bajo el t\u00edtulo \u2018Nondik eta norantz. De d\u00f3nde y hacia d\u00f3nde\u2019, esta iniciativa llega tras el marco <span style=\"color: #000000;\">de participaci\u00f3n y reflexi\u00f3n abierto desde el pasado a\u00f1o en varias mesas tem\u00e1ticas en la que est\u00e1n participando asociaciones y agentes de la fiesta en la organizaci\u00f3n de los Sanfermines aportando ideas concretas y se\u00f1alando aspectos que hay que cambiar, mejorar o reforzar. El <\/span>Consistorio pamplon\u00e9s propone estos <span style=\"color: #000000;\">espacios de deliberaci\u00f3n en los que se trabaja el libro <\/span>blanco de los Sanfermines ya que quiere que <span style=\"color: #000000;\">la fiesta sea, tambi\u00e9n, un tema sobre el que hacer una reflexi\u00f3n en la que participe toda la ciudadan\u00eda de Pamplona.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actuaci\u00f3n, que comienza a las 19.30 horas, est\u00e1 protagonizada por \u2018Txiplin\u2019 a la guitarra, I\u00f1aki Lero con la percusi\u00f3n y el dantzari Iker Larumbe<\/p>\n","protected":false},"author":1,"featured_media":11008,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-13603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Condestable presenta ma\u00f1ana viernes \u2018Euskofoniak\u2019, un espect\u00e1culo de reflexi\u00f3n musical y danza tradicional desde un lenguaje contempor\u00e1neo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Condestable presenta ma\u00f1ana viernes \u2018Euskofoniak\u2019, un espect\u00e1culo de reflexi\u00f3n musical y danza tradicional desde un lenguaje contempor\u00e1neo\" \/>\n<meta property=\"og:description\" content=\"La actuaci\u00f3n, que comienza a las 19.30 horas, est\u00e1 protagonizada por \u2018Txiplin\u2019 a la guitarra, I\u00f1aki Lero con la percusi\u00f3n y el dantzari Iker Larumbe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-22T11:20:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/palacio-condestable-civivox.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"Condestable presenta ma\u00f1ana viernes \u2018Euskofoniak\u2019, un espect\u00e1culo de reflexi\u00f3n musical y danza tradicional desde un lenguaje contempor\u00e1neo\",\"datePublished\":\"2017-06-22T11:20:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\\\/\"},\"wordCount\":388,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/palacio-condestable-civivox.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\\\/\",\"name\":\"Condestable presenta ma\u00f1ana viernes \u2018Euskofoniak\u2019, un espect\u00e1culo de reflexi\u00f3n musical y danza tradicional desde un lenguaje contempor\u00e1neo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/palacio-condestable-civivox.jpg\",\"datePublished\":\"2017-06-22T11:20:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/palacio-condestable-civivox.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/palacio-condestable-civivox.jpg\",\"width\":900,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Condestable presenta ma\u00f1ana viernes \u2018Euskofoniak\u2019, un espect\u00e1culo de reflexi\u00f3n musical y danza tradicional desde un lenguaje contempor\u00e1neo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Condestable presenta ma\u00f1ana viernes \u2018Euskofoniak\u2019, un espect\u00e1culo de reflexi\u00f3n musical y danza tradicional desde un lenguaje contempor\u00e1neo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/","og_locale":"es_ES","og_type":"article","og_title":"Condestable presenta ma\u00f1ana viernes \u2018Euskofoniak\u2019, un espect\u00e1culo de reflexi\u00f3n musical y danza tradicional desde un lenguaje contempor\u00e1neo","og_description":"La actuaci\u00f3n, que comienza a las 19.30 horas, est\u00e1 protagonizada por \u2018Txiplin\u2019 a la guitarra, I\u00f1aki Lero con la percusi\u00f3n y el dantzari Iker Larumbe","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2017-06-22T11:20:13+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/palacio-condestable-civivox.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"Condestable presenta ma\u00f1ana viernes \u2018Euskofoniak\u2019, un espect\u00e1culo de reflexi\u00f3n musical y danza tradicional desde un lenguaje contempor\u00e1neo","datePublished":"2017-06-22T11:20:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/"},"wordCount":388,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/palacio-condestable-civivox.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/","name":"Condestable presenta ma\u00f1ana viernes \u2018Euskofoniak\u2019, un espect\u00e1culo de reflexi\u00f3n musical y danza tradicional desde un lenguaje contempor\u00e1neo","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/palacio-condestable-civivox.jpg","datePublished":"2017-06-22T11:20:13+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/palacio-condestable-civivox.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/12\/palacio-condestable-civivox.jpg","width":900,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/condestable-presenta-manana-viernes-euskofoniak-un-espectaculo-de-reflexion-musical-y-danza-tradicional-desde-un-lenguaje-contemporaneo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Condestable presenta ma\u00f1ana viernes \u2018Euskofoniak\u2019, un espect\u00e1culo de reflexi\u00f3n musical y danza tradicional desde un lenguaje contempor\u00e1neo"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/13603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=13603"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/13603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/11008"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=13603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=13603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=13603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}