{"id":13366,"date":"2017-06-07T13:55:39","date_gmt":"2017-06-07T12:55:39","guid":{"rendered":"http:\/\/laguiadepamplona.es\/actualidad\/?p=13366"},"modified":"2017-06-07T13:55:39","modified_gmt":"2017-06-07T12:55:39","slug":"una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/","title":{"rendered":"Una sesi\u00f3n de emprendimiento \u2018en vivo\u2019 y un concurso: la oferta municipal para que unos j\u00f3venes ense\u00f1en a otros mediante networking a poner en marcha ideas de negocio"},"content":{"rendered":"<h3>Contin\u00faa abierto el plazo para apuntarse al panel de emprendedores \u2018Pitch &amp; Beer\u2019 que tendr\u00e1 lugar ma\u00f1ana en la Casa de la Juventud<\/h3>\n<p><!--more--><\/p>\n<p><a href=\"http:\/\/laguiadepamplona.es\/actualidad\/wp-content\/uploads\/2017\/06\/pitch_beer_cartel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-13368\" src=\"http:\/\/laguiadepamplona.es\/actualidad\/wp-content\/uploads\/2017\/06\/pitch_beer_cartel-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/06\/pitch_beer_cartel-212x300.jpg 212w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/06\/pitch_beer_cartel-768x1086.jpg 768w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/06\/pitch_beer_cartel-724x1024.jpg 724w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/06\/pitch_beer_cartel-300x424.jpg 300w, https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/06\/pitch_beer_cartel.jpg 1000w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a>Hacer bicicletas usando bamb\u00fa, realizar zumos naturales y sanos usando partes de la fruta de las que usualmente la industria descarta su manejo, repensar las energ\u00edas renovables o trasladar trucks vinculados a eventos gastron\u00f3micos por distintas localidades, son algunas de las ideas que se dar\u00e1n cita ma\u00f1ana en \u2018Pitch &amp; Beer\u2019 un concurso de ideas entre j\u00f3venes emprendedores que tendr\u00e1 lugar en la Casa de la Juventud.<\/p>\n<p>Son proyectos de negocio con nombres como \u2018Feelback Eventos\u2019, \u2018Urdinnova\u2019, \u2018Bambookoa\u2019, \u2018Juicycommunity\u2019 o \u2018Kalefood\u2019 que tienen detr\u00e1s a emprendedores, bien individuales, bien estructurados por equipos, con una edad media de 25 a\u00f1os. Algunos de estos proyectos son incluso, resultado de trabajos de fin de grado en la Universidad. A\u00fan hay tiempo para que quien tenga una idea de negocio se apunte a este panel, contactando con \u2018Pitch &amp; Beer Pamplona Iru\u00f1a\u2019 en su p\u00e1gina de Facebook.<\/p>\n<p>Todos ellos competir\u00e1n para ser elegidos mejor proyecto, pero, sobre todo, deber\u00e1n presentar p\u00fablicamente su idea y sus planes de negocio y podr\u00e1n recibir las precisiones de un jurado especializado en proyectos de emprendimiento y el <em>feedback<\/em> del p\u00fablico asistente.<\/p>\n<p>La sesi\u00f3n de <strong><u>\u2018Pitch &amp; Beer\u2019 tendr\u00e1 lugar ma\u00f1ana, de 19 a 20.30 horas, en la Casa de la Juventud<\/u><\/strong>. Comenzar\u00e1 con la presentaci\u00f3n de los equipos participantes y de los tres jueces. Quienes se encargar\u00e1n de evaluar los proyectos presentados ser\u00e1n: Johan Gustafsson, el cofundador y gerente de Bolsabooks; Beatriz Blasco, t\u00e9cnica en el \u00e1rea de creaci\u00f3n de empresas de CEIN (Centro Europeo de Empresas e Innovaci\u00f3n de Navarra) y Koldo Aiestar\u00e1n, cofundador de Kukuxumuxu.<\/p>\n<p>A partir de ah\u00ed, cada equipo participante tendr\u00e1 3 minutos para presentar su trabajo a los asistentes. Detr\u00e1s de cada presentaci\u00f3n el proyecto recibir\u00e1 p\u00fablicamente las valoraciones de los jurados. Finalizada esta fase que, adem\u00e1s de ser una competici\u00f3n es una buena forma de depurar los proyectos, comenzar\u00e1 el encuentro de networking.<\/p>\n<p>En un ambiente m\u00e1s informal, con aperitivos y bebidas de por medio, todos los presentes podr\u00e1n tener un rato de intercambio de ideas, planes de negocios, experiencias o buenas pr\u00e1cticas. Es una manera de establecer un sistema de comunicaci\u00f3n y puede permitir en el futuro la realizaci\u00f3n de trabajo en com\u00fan. Tras el networking se anunciar\u00e1 el proyecto ganador, que se llevar\u00e1 el diploma que le avalar\u00e1 como vencedor de la II Edici\u00f3n de Pitch &amp; Beer<\/p>\n<p>Pitch &amp; Beer es una propuesta de emprendedores pensada para emprendedores, ya que la idea de crear este foro de trabajo est\u00e1 dentro de una iniciativa de origen empresarial. Koenna, la asociaci\u00f3n que la impulsa, est\u00e1 formada por 17 j\u00f3venes estudiantes de la Universidad de Mondrag\u00f3n, y la creaci\u00f3n de esta \u2018empresa de eventos\u2019 es parte de su formaci\u00f3n acad\u00e9mica.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contin\u00faa abierto el plazo para apuntarse al panel de emprendedores \u2018Pitch &amp; Beer\u2019 que tendr\u00e1 lugar ma\u00f1ana en la Casa de la Juventud<\/p>\n","protected":false},"author":1,"featured_media":13367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-13366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una sesi\u00f3n de emprendimiento \u2018en vivo\u2019 y un concurso: la oferta municipal para que unos j\u00f3venes ense\u00f1en a otros mediante networking a poner en marcha ideas de negocio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una sesi\u00f3n de emprendimiento \u2018en vivo\u2019 y un concurso: la oferta municipal para que unos j\u00f3venes ense\u00f1en a otros mediante networking a poner en marcha ideas de negocio\" \/>\n<meta property=\"og:description\" content=\"Contin\u00faa abierto el plazo para apuntarse al panel de emprendedores \u2018Pitch &amp; Beer\u2019 que tendr\u00e1 lugar ma\u00f1ana en la Casa de la Juventud\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-07T12:55:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/06\/banner_pitch_beer_cartel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"582\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"Una sesi\u00f3n de emprendimiento \u2018en vivo\u2019 y un concurso: la oferta municipal para que unos j\u00f3venes ense\u00f1en a otros mediante networking a poner en marcha ideas de negocio\",\"datePublished\":\"2017-06-07T12:55:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\\\/\"},\"wordCount\":542,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/banner_pitch_beer_cartel.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\\\/\",\"name\":\"Una sesi\u00f3n de emprendimiento \u2018en vivo\u2019 y un concurso: la oferta municipal para que unos j\u00f3venes ense\u00f1en a otros mediante networking a poner en marcha ideas de negocio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/banner_pitch_beer_cartel.jpg\",\"datePublished\":\"2017-06-07T12:55:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/banner_pitch_beer_cartel.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/banner_pitch_beer_cartel.jpg\",\"width\":1000,\"height\":582},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una sesi\u00f3n de emprendimiento \u2018en vivo\u2019 y un concurso: la oferta municipal para que unos j\u00f3venes ense\u00f1en a otros mediante networking a poner en marcha ideas de negocio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una sesi\u00f3n de emprendimiento \u2018en vivo\u2019 y un concurso: la oferta municipal para que unos j\u00f3venes ense\u00f1en a otros mediante networking a poner en marcha ideas de negocio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/","og_locale":"es_ES","og_type":"article","og_title":"Una sesi\u00f3n de emprendimiento \u2018en vivo\u2019 y un concurso: la oferta municipal para que unos j\u00f3venes ense\u00f1en a otros mediante networking a poner en marcha ideas de negocio","og_description":"Contin\u00faa abierto el plazo para apuntarse al panel de emprendedores \u2018Pitch &amp; Beer\u2019 que tendr\u00e1 lugar ma\u00f1ana en la Casa de la Juventud","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2017-06-07T12:55:39+00:00","og_image":[{"width":1000,"height":582,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/06\/banner_pitch_beer_cartel.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"Una sesi\u00f3n de emprendimiento \u2018en vivo\u2019 y un concurso: la oferta municipal para que unos j\u00f3venes ense\u00f1en a otros mediante networking a poner en marcha ideas de negocio","datePublished":"2017-06-07T12:55:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/"},"wordCount":542,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/06\/banner_pitch_beer_cartel.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/","name":"Una sesi\u00f3n de emprendimiento \u2018en vivo\u2019 y un concurso: la oferta municipal para que unos j\u00f3venes ense\u00f1en a otros mediante networking a poner en marcha ideas de negocio","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/06\/banner_pitch_beer_cartel.jpg","datePublished":"2017-06-07T12:55:39+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/06\/banner_pitch_beer_cartel.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/06\/banner_pitch_beer_cartel.jpg","width":1000,"height":582},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/una-sesion-de-emprendimiento-en-vivo-y-un-concurso-la-oferta-municipal-para-que-unos-jovenes-ensenen-a-otros-mediante-networking-a-poner-en-marcha-ideas-de-negocio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"Una sesi\u00f3n de emprendimiento \u2018en vivo\u2019 y un concurso: la oferta municipal para que unos j\u00f3venes ense\u00f1en a otros mediante networking a poner en marcha ideas de negocio"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/13366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=13366"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/13366\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/13367"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=13366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=13366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=13366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}