{"id":12843,"date":"2017-05-03T12:43:43","date_gmt":"2017-05-03T11:43:43","guid":{"rendered":"http:\/\/laguiadepamplona.es\/actualidad\/?p=12843"},"modified":"2017-05-03T12:43:43","modified_gmt":"2017-05-03T11:43:43","slug":"el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/","title":{"rendered":"El Ayuntamiento de Pamplona licita en diez lotes por gremios el acuerdo marco para la rehabilitaci\u00f3n de viviendas y bajeras municipales durante 2017"},"content":{"rendered":"<h3>Este jueves se presenta en Condestable para explicar y aclarar dudas del acuerdo, al que se prev\u00e9n destinar m\u00e1s de 300.000 euros este a\u00f1o<\/h3>\n<p><!--more--><\/p>\n<p>El Ayuntamiento de Pamplona ha convocado la licitaci\u00f3n del acuerdo marco para la rehabilitaci\u00f3n de viviendas y bajeras municipales. Se trata de un acuerdo dividido en diez lotes en funci\u00f3n de los gremios (alba\u00f1iler\u00eda, pintura, carpinter\u00eda, electricidad, etc.) para potenciar el acceso a los contratos p\u00fablicos de las empresas m\u00e1s peque\u00f1as, tal y como recoge el proyecto Trebatu. El pliego de cl\u00e1usulas administrativas puede consultarse en el Portal de Contrataci\u00f3n de Navarra. Los interesados deber\u00e1n presentar su oferta hasta las 14.30 horas del 22 de mayo.<\/p>\n<p>El Ayuntamiento ha preparado para este jueves 4 de mayo una sesi\u00f3n informativa para dar a conocer a las peque\u00f1as y medianas empresas locales el nuevo acuerdo marco, detallando tanto la documentaci\u00f3n a presentar para formar parte de la lista de proveedores como las relaciones administrativas con el Ayuntamiento dentro de dicho acuerdo marco. La presentaci\u00f3n ser\u00e1 a las 18.30 horas en la sala de conferencias del Palacio del Condestable (calle Mayor, 2) y en ella intervendr\u00e1n t\u00e9cnicos municipales del Ayuntamiento de Pamplona de diversas \u00e1reas.<\/p>\n<p>El Ayuntamiento prev\u00e9 destinar inicialmente en este a\u00f1o alrededor de 300.000 euros para reformas en viviendas y cerca de 50.000 para rehabilitaci\u00f3n en bajeras. Con estas cuant\u00edas, el Ayuntamiento quiere continuar con la rehabilitaci\u00f3n progresiva de viviendas municipales para cubrir situaciones de emergencia social y, adem\u00e1s, crear un parque de viviendas de alquiler social destinadas a las personas y familias con mayores necesidades. Asimismo, se pretende reformar y acondicionar locales y bajeras municipales para cubrir necesidades del propio Ayuntamiento o ponerlos a disposici\u00f3n de la ciudadan\u00eda.<\/p>\n<p>Con este acuerdo marco, se crear\u00e1 una selecci\u00f3n de proveedores para la realizaci\u00f3n de gran parte de estas obras durante este a\u00f1o 2017 (a partir del mes de junio), y contempl\u00e1ndose la posibilidad de pr\u00f3rroga durante 2018.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Los diez lotes<\/strong><\/p>\n<p>Las principales actuaciones a realizar dentro de la presente contrataci\u00f3n son las de alba\u00f1iler\u00eda, pintura, carpinter\u00eda interior, parqu\u00e9 y laminados, carpinter\u00eda exterior y cerrajer\u00eda, cristaler\u00eda, electricidad, fontaner\u00eda y calefacci\u00f3n, limpieza y suministro e instalaci\u00f3n de mobiliario de cocina. Cada una de ellas conforma un lote en la licitaci\u00f3n. El pliego del contrato recoge el presupuesto estimado para cada uno de los lotes durante 2017, as\u00ed como los requisitos de solvencia econ\u00f3mica, financiera, t\u00e9cnica\u00a0 profesional exigibles para cada uno de ellos.<\/p>\n<p>De los diez lotes existentes en el acuerdo marco, el lote de trabajos de alba\u00f1iler\u00eda y el lote de trabajos de limpieza son exclusivos para centros especiales de empleo y\/o centros de inserci\u00f3n sociolaboral.<\/p>\n<p>Cada licitador no podr\u00e1 presentar m\u00e1s de una oferta ni podr\u00e1 tampoco suscribir ninguna oferta en participaci\u00f3n conjunta con otros licitadores si lo ha hecho individualmente, ni figurar en m\u00e1s de una de esas agrupaciones.<\/p>\n<p>Para la selecci\u00f3n de adjudicatarios, el \u00fanico criterio que se tendr\u00e1 en cuenta es el precio: las ofertas ser\u00e1n clasificadas seg\u00fan el porcentaje de baja ofertado, resultando en primer lugar aqu\u00e9llas cuyo porcentaje de baja sea superior. S\u00f3lo resultar\u00e1n seleccionados un m\u00e1ximo de 6 empresarios o proveedores para cada lote. En caso de empate, se dirimir\u00e1 a favor de la empresa que tenga un mayor porcentaje de trabajadores con discapacidad, siempre que \u00e9ste no sea inferior al 3%.<\/p>\n<p>&nbsp;<\/p>\n<p>Los diez lotes<\/p>\n<ul>\n<li><strong>Alba\u00f1iler\u00eda<\/strong>. Los trabajos de alba\u00f1iler\u00eda contemplados incluyen demolici\u00f3n y levante de tabiques de ladrillo, enfoscados, alicatados y pavimentos cer\u00e1micos, as\u00ed como ayudas a las instalaciones (apertura y tapado de rozas, etc.).<\/li>\n<\/ul>\n<p><strong>El presupuesto estimado para 2017 es de 17.500 euros.<\/strong><\/p>\n<ul>\n<li><strong>Pintura y tratamientos espec\u00edficos<\/strong>. Pintado de paramentos tanto verticales (tabiques, muros de fachada&#8230;) como horizontales (techos) existentes, a base de dos o m\u00e1s manos de pintura pl\u00e1stica lisa color a decidir por la direcci\u00f3n facultativa en obra, sobre todo tipo de acabados (gotel\u00e9, liso, etc.), proyecci\u00f3n de gotel\u00e9, esmaltado de radiadores y otros elementos met\u00e1licos, y esmaltado de carpinter\u00edas.<\/li>\n<\/ul>\n<p>Presupuesto estimado en 2017: 52.500 euros.<\/p>\n<ul>\n<li><strong>Carpinter\u00eda interior<\/strong>. Retirada y sustituci\u00f3n de carpinter\u00eda interior en mal estado y\/o la reparaci\u00f3n de la carpinter\u00eda ya existente, incluidas manillas, jambas&#8230;<\/li>\n<\/ul>\n<p>Presupuesto estimado en 2017: 12.500 euros.<\/p>\n<ul>\n<li><strong>Parqu\u00e9 y laminados<\/strong>. Lijado y barnizado de pavimentos de madera en mal estado, incluso sustituci\u00f3n de tablillas y rodapi\u00e9s de madera, as\u00ed como la colocaci\u00f3n de pavimentos laminados.<\/li>\n<\/ul>\n<p>Presupuesto estimado en 2017: 12.500 euros.<\/p>\n<ul>\n<li><strong>Carpinter\u00eda exterior y cerrajer\u00eda<\/strong>. Reposici\u00f3n y\/o sustituci\u00f3n total o parcial de carpinter\u00eda exterior de madera, aluminio, PVC, etc., as\u00ed como su ajuste para su correcto funcionamiento, y de sus elementos (herrajes, persianas, cintas de persiana&#8230;).<\/li>\n<\/ul>\n<p>Presupuesto estimado en 2017: 12.500 euros.<\/p>\n<ul>\n<li><strong>Cristaler\u00eda<\/strong>. Reposici\u00f3n y\/o sustituci\u00f3n de cristales de ventanas y puertas vidrieras.<\/li>\n<\/ul>\n<p>Presupuesto estimado en 2017: 10.000 euros.<\/p>\n<ul>\n<li><strong>Electricidad<\/strong>. Revisi\u00f3n general de instalaciones el\u00e9ctricas as\u00ed como cuadros el\u00e9ctricos, y reposici\u00f3n y\/o sustituci\u00f3n de los elementos necesarios (interruptores, bases de enchufes, diferenciales, magnetot\u00e9rmicos, l\u00edneas, etc.), incorporaci\u00f3n de plafones en todas las estancias y redacci\u00f3n y tramitaci\u00f3n de boletines el\u00e9ctricos caducados.<\/li>\n<\/ul>\n<p>Presupuesto estimado en 2017: 20.000 euros.<\/p>\n<ul>\n<li><strong>Fontaner\u00eda y calefacci\u00f3n. <\/strong>Repaso exhaustivo de todos los aparatos sanitarios, as\u00ed como de la grifer\u00eda, y se realizar\u00e1n las reparaciones y\/o sustituciones pertinentes para garantizar su perfecto funcionamiento. Se contempla la ejecuci\u00f3n de una nueva instalaci\u00f3n de calefacci\u00f3n de gas (radiadores, v\u00e1lvulas, conductos de cobre&#8230;), incluso caldera y sus ventilaciones, as\u00ed como la redacci\u00f3n de los correspondientes certificados de instalaci\u00f3n.<\/li>\n<\/ul>\n<p>Presupuesto estimado en 2017: 62.500 euros.<\/p>\n<ul>\n<li><strong>Limpieza y tratamientos de higiene . <\/strong>Limpieza general de cada una de las viviendas (dej\u00e1ndolas listas para entrar a vivir), edificios y otros bienes inmuebles municipales y, a juicio de la direcci\u00f3n facultativa, de diferentes elementos comunes de los mismos.<\/li>\n<\/ul>\n<p>Presupuesto estimado en 2017: 12.500 euros.<\/p>\n<ul>\n<li><strong>Mobiliario de cocina. <\/strong>Amueblamiento de aquellas viviendas que no est\u00e9n dotadas de mobiliario de cocina. Dichos muebles ser\u00e1n de madera laminada de calidad est\u00e1ndar, formada por muebles bajos y altos en color blanco mate. Se incluir\u00e1 la encimera de estratificado, en la cual se deber\u00e1 integrar el fregadero y su correspondiente grifer\u00eda. As\u00ed mismo, se dotar\u00e1n de campana extractora, horno, vitrocer\u00e1mica, frigor\u00edfico y lavadora.<\/li>\n<\/ul>\n<p>Presupuesto estimado en 2017: 37.500 euros.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves se presenta en Condestable para explicar y aclarar dudas del acuerdo, al que se prev\u00e9n destinar m\u00e1s de 300.000 euros este a\u00f1o<\/p>\n","protected":false},"author":1,"featured_media":10979,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-12843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Ayuntamiento de Pamplona licita en diez lotes por gremios el acuerdo marco para la rehabilitaci\u00f3n de viviendas y bajeras municipales durante 2017<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Ayuntamiento de Pamplona licita en diez lotes por gremios el acuerdo marco para la rehabilitaci\u00f3n de viviendas y bajeras municipales durante 2017\" \/>\n<meta property=\"og:description\" content=\"Este jueves se presenta en Condestable para explicar y aclarar dudas del acuerdo, al que se prev\u00e9n destinar m\u00e1s de 300.000 euros este a\u00f1o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-03T11:43:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/11\/Ayto_Pamplona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El Ayuntamiento de Pamplona licita en diez lotes por gremios el acuerdo marco para la rehabilitaci\u00f3n de viviendas y bajeras municipales durante 2017\",\"datePublished\":\"2017-05-03T11:43:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\\\/\"},\"wordCount\":1122,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Ayto_Pamplona.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\\\/\",\"name\":\"El Ayuntamiento de Pamplona licita en diez lotes por gremios el acuerdo marco para la rehabilitaci\u00f3n de viviendas y bajeras municipales durante 2017\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Ayto_Pamplona.jpg\",\"datePublished\":\"2017-05-03T11:43:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Ayto_Pamplona.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Ayto_Pamplona.jpg\",\"width\":900,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Ayuntamiento de Pamplona licita en diez lotes por gremios el acuerdo marco para la rehabilitaci\u00f3n de viviendas y bajeras municipales durante 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Ayuntamiento de Pamplona licita en diez lotes por gremios el acuerdo marco para la rehabilitaci\u00f3n de viviendas y bajeras municipales durante 2017","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/","og_locale":"es_ES","og_type":"article","og_title":"El Ayuntamiento de Pamplona licita en diez lotes por gremios el acuerdo marco para la rehabilitaci\u00f3n de viviendas y bajeras municipales durante 2017","og_description":"Este jueves se presenta en Condestable para explicar y aclarar dudas del acuerdo, al que se prev\u00e9n destinar m\u00e1s de 300.000 euros este a\u00f1o","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2017-05-03T11:43:43+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/11\/Ayto_Pamplona.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El Ayuntamiento de Pamplona licita en diez lotes por gremios el acuerdo marco para la rehabilitaci\u00f3n de viviendas y bajeras municipales durante 2017","datePublished":"2017-05-03T11:43:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/"},"wordCount":1122,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/11\/Ayto_Pamplona.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/","name":"El Ayuntamiento de Pamplona licita en diez lotes por gremios el acuerdo marco para la rehabilitaci\u00f3n de viviendas y bajeras municipales durante 2017","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/11\/Ayto_Pamplona.jpg","datePublished":"2017-05-03T11:43:43+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/11\/Ayto_Pamplona.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2016\/11\/Ayto_Pamplona.jpg","width":900,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-ayuntamiento-de-pamplona-licita-en-diez-lotes-por-gremios-el-acuerdo-marco-para-la-rehabilitacion-de-viviendas-y-bajeras-municipales-durante-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El Ayuntamiento de Pamplona licita en diez lotes por gremios el acuerdo marco para la rehabilitaci\u00f3n de viviendas y bajeras municipales durante 2017"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/12843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=12843"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/12843\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/10979"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=12843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=12843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=12843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}