{"id":12559,"date":"2017-04-07T12:23:56","date_gmt":"2017-04-07T11:23:56","guid":{"rendered":"http:\/\/laguiadepamplona.es\/actualidad\/?p=12559"},"modified":"2017-04-07T12:23:56","modified_gmt":"2017-04-07T11:23:56","slug":"el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra","status":"publish","type":"post","link":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/","title":{"rendered":"El jazz espiritual de \u2018The Sacred Concert\u2019 de Duke Ellington y el estreno de la \u2018Misa R\u00e9quiem\u2019 de Eslava, s\u00e1bado y lunes en Baluarte en el Festival de M\u00fasica Sacra"},"content":{"rendered":"<h3>El domingo actuar\u00e1n la Sinfonietta Acad\u00e9mica y el Coro Juvenil del Orfe\u00f3n Pamplon\u00e9s en la iglesia de los Carmelitas Descalzos<\/h3>\n<p><!--more--><\/p>\n<p>El Festival de M\u00fasica Sacra contin\u00faa este fin de semana y el lunes con tres nuevas propuestas vocales. El s\u00e1bado Jazzy Leap de la Coral de C\u00e1mara de Navarra y Seda Jazz Big Band interpretar\u00e1n \u2018The Sacred Concerts\u2019 de Duke Ellington en Baluarte; el domingo la iglesia Carmelitas Descalzos acoger\u00e1 \u2018In Paradisum\u2019 con obras de Faur\u00e9 y Ravel a cargo de la Sinfonietta Acad\u00e9mica y el Coro Juvenil del Orfe\u00f3n Pamplon\u00e9s; y el lunes, tambi\u00e9n en Baluarte, el Coro Sinf\u00f3nico de la Federaci\u00f3n de Coros de Navarra y Orquesta Sinf\u00f3nica Goya estrenar\u00e1n la \u2018Misa R\u00e9quiem\u2019 de Hilari\u00f3n Eslava. Los conciertos de Baluarte tienen un precio de 10 euros y el de la iglesia de los Carmelitas es de entrada libre, previa retirada de invitaciones.<\/p>\n<p>Ma\u00f1ana s\u00e1bado, a partir de las 20 horas, Baluarte acoger\u00e1 la representaci\u00f3n de \u2018The Sacred\u00a0 Concert\u2019, uno de los programas menos frecuentes del repertorio cl\u00e1sico jazz\u00edstico dado su singular car\u00e1cter espiritual y el gran numero de artistas que requiere su ejecuci\u00f3n. Detr\u00e1s de este proyecto est\u00e1 el m\u00fasico Perico Sambeat, que hace a\u00f1os se puso a recuperar este proyecto. En el concierto se interpretar\u00e1n una selecci\u00f3n de temas de los tres conciertos sacros, con clara preferencia por el segundo y una menor presencia del tercero de ellos. Y es que se han perdido gran parte de las partituras, ya que en realidad muchas no exist\u00edan, pues Duke Ellington daba\u00a0 indicaciones directas a los m\u00fasicos.<\/p>\n<p>Los protagonistas de esta hist\u00f3rica producci\u00f3n ser\u00e1n tambi\u00e9n la Seda Jazz Big Band valenciana; los solistas y coro de Jazzy Leap, secci\u00f3n de jazz y m\u00fasica moderna de la Coral de C\u00e1mara de Navarra. Adem\u00e1s, participar\u00e1 Rafa Izaguirre como bailar\u00edn solista de claqu\u00e9 y el Coro de Ni\u00f1os de la escuela de \u00f3pera de la \u00d3pera de C\u00e1mara de Navarra.<\/p>\n<p><strong>Faur\u00e9, el domingo con la Sinfonietta Acad\u00e9mica y el Coro Juvenil del Orfe\u00f3n Pamplon\u00e9s<\/strong><\/p>\n<p>El domingo actuar\u00e1n en la iglesia de los Carmelitas Descalzos la Sinfonietta Acad\u00e9mica y el Coro Juvenil del Orfe\u00f3n Pamplon\u00e9s bajo el t\u00edtulo de \u2018In Paradisum\u2019. El concierto comenzar\u00e1 a las 20 horas, con entrada libre previa retirada de invitaciones, con un m\u00e1ximo de dos por persona, desde una hora antes de inicio en la propia puerta del templo.<\/p>\n<p>En la temporada en la que la Sinfonietta Acad\u00e9mica celebra su vig\u00e9simo quinto aniversario, interpretar\u00e1n dentro del Festival de M\u00fasica Sacra dos obras ic\u00f3nicas del compositor franc\u00e9s. El tema central del programa ser\u00e1 el \u2018R\u00e9quiem de Faur\u00e9\u2019, uniendo bajo la batuta de Caroline Collier la orquesta de la Sinfonietta con el Coro Juvenil del Orfe\u00f3n Pamplon\u00e9s y dos cantantes solistas.\u00a0 El \u2018R\u00e9quiem en Re menor. Op 48\u2019 de Faur\u00e9 es una de las m\u00e1s populares misas de r\u00e9quiem, considerada como una de las m\u00e1s hermosas y notables obras para coro y orquesta. Se completar\u00e1 el concierto con la \u2018Suite de Pelleas y Melisande. Op. 80\u2019, tambi\u00e9n de Faur\u00e9, y con la \u2018Pavane pour un Infante Defunte\u2019 de Maurice Ravel.<\/p>\n<p><strong>Estreno de la Misa R\u00e9quiem de Hilari\u00f3n Eslava el lunes en Baluarte<\/strong><\/p>\n<p>Baluarte acoge el lunes, a las 20 horas, el estreno mundial de la \u2018Misa de R\u00e9quiem\u2019 de Hilari\u00f3n Eslava, una partitura recuperada por la Federaci\u00f3n de Coros de Navarra, que interpretar\u00e1n el propio coro sinf\u00f3nico de la federaci\u00f3n y la Orquesta Sinf\u00f3nica Goya. Las entradas para el concierto se venden al precio de 10 euros.<\/p>\n<p>El trabajo para actualizar la partitura actual de 120 p\u00e1ginas, partichela del coro y orquesta ha sido laboriosa. Se trata de una partitura impresa en el siglo XIX con una graf\u00eda poco clara\u00a0 y con un org\u00e1nico en la orquesta diferente al actual. Por ello se ha tenido que realizar la transcripci\u00f3n a los instrumentos actuales de la orquesta. Tambi\u00e9n la se ha debido realizar la transcripci\u00f3n\u00a0 clave de sol y a fa de la escritura para el coro, pues al ser de esa \u00e9poca era muy dif\u00edcil de leer. El m\u00fasico burlad\u00e9s Hilari\u00f3n Eslava y su Misa R\u00e9quiem se convierten en el punto de referencia sobre el que pivota la actividad de la Federaci\u00f3n de Coros de Navarra en este 2017, en el que van a movilizar a cerca de 300 personas para los dos conciertos previstos en Pamplona y Zaragoza.<\/p>\n<p>El Coro de la Federaci\u00f3n Navarra de Coros se present\u00f3 de forma oficial en diciembre de 2008 y desde entonces ha participado en numerosos conciertos dentro y fuera de la geograf\u00eda foral. Se objetivo es seguir aportando, al igual que la federaci\u00f3n, una muestra representativa de la m\u00fasica coral no profesional de Navarra. Se concibe tambi\u00e9n como un lugar de encuentro, de disfrute y de intercambio de impresiones que sean trasladadas a los coros de origen, contribuyendo al enriquecimiento musical de todos ellos. En estos momentos est\u00e1 compuesto por 150 personas. La Orquesta Sinf\u00f3nica Goya, por su parte, se cre\u00f3 en el primer trimestre de 2013 con la intenci\u00f3n de aglutinar a algunos de los mejores m\u00fasicos de las generaciones m\u00e1s j\u00f3venes en el inicio de sus carreras profesionales. La mayor\u00eda de sus miembros han formado parte ya de importantes orquestas nacionales e internacionales.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Festival de M\u00fasica Sacra<\/strong><\/p>\n<p><strong>S\u00e1bado, 8 de abril, 20 horas. <\/strong><strong>Baluarte<\/strong><\/p>\n<ul>\n<li><em>The Sacred Concerts<\/em><\/li>\n<li>Jazzy Leap de la Coral de C\u00e1mara de Navarra y Seda Jazz Big Band<\/li>\n<li>Entrada: 10 euros<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Domingo, 9 de abril, 20 horas. <\/strong><strong>Iglesia Carmelitas Descalzos <\/strong><\/p>\n<ul>\n<li><em>In Paradisum<\/em><\/li>\n<li>Sinfonietta Acad\u00e9mica y Coro juvenil del Orfe\u00f3n Pamplon\u00e9s<\/li>\n<li>Entrada libre, previa retirada de invitaciones (m\u00e1ximo de dos por persona) desde una hora antes del concierto en la puerta de la iglesia<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Lunes, 10 de abril, 20 horas. <\/strong><strong>Baluarte<\/strong><\/p>\n<ul>\n<li><em>Misa de R\u00e9quiem <\/em>de Hilari\u00f3n Eslava<\/li>\n<li>Coro Sinf\u00f3nico de la Federaci\u00f3n de Coros de Navarra y Orquesta Sinf\u00f3nica Goya<\/li>\n<li>Entrada: 10 euros<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Martes 11 de abril, 20 horas. <\/strong><strong>Baluarte<\/strong><\/p>\n<ul>\n<li><em>R\u00e9quiem Alem\u00e1n<\/em> de Johannes Brahms<\/li>\n<li>Versi\u00f3n de dos pianos y percusi\u00f3n<\/li>\n<li>Orfe\u00f3n Pamplon\u00e9s<\/li>\n<li>Entrada: 10 euros<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Mi\u00e9rcoles 12 de abril, 20 horas. <\/strong><strong>Catedral Santa Mar\u00eda de Pamplona<\/strong><\/p>\n<ul>\n<li><em>I cammini de la musica: Italia \u2013 Pamplona. Estrenos del Archivo de M\u00fasica de la Catedral de Pamplona<\/em><\/li>\n<li>Agrupaci\u00f3n Coral de C\u00e1mara de Pamplona, Capilla de M\u00fasica de la Catedral y Conductus Ensemble<\/li>\n<li>Entrada libre, previa retirada de invitaciones (m\u00e1ximo de dos por persona) desde una hora antes del concierto en la puerta de la catedral<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El domingo actuar\u00e1n la Sinfonietta Acad\u00e9mica y el Coro Juvenil del Orfe\u00f3n Pamplon\u00e9s en la iglesia de los Carmelitas Descalzos<\/p>\n","protected":false},"author":1,"featured_media":12532,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-12559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-pamplona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El jazz espiritual de \u2018The Sacred Concert\u2019 de Duke Ellington y el estreno de la \u2018Misa R\u00e9quiem\u2019 de Eslava, s\u00e1bado y lunes en Baluarte en el Festival de M\u00fasica Sacra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El jazz espiritual de \u2018The Sacred Concert\u2019 de Duke Ellington y el estreno de la \u2018Misa R\u00e9quiem\u2019 de Eslava, s\u00e1bado y lunes en Baluarte en el Festival de M\u00fasica Sacra\" \/>\n<meta property=\"og:description\" content=\"El domingo actuar\u00e1n la Sinfonietta Acad\u00e9mica y el Coro Juvenil del Orfe\u00f3n Pamplon\u00e9s en la iglesia de los Carmelitas Descalzos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/\" \/>\n<meta property=\"og:site_name\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-07T11:23:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/04\/Folleto-Festival-Musica-Sacra-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"544\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Gu\u00eda de Pamplona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:site\" content=\"@LaGuiadPamplona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Gu\u00eda de Pamplona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\\\/\"},\"author\":{\"name\":\"La Gu\u00eda de Pamplona\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\"},\"headline\":\"El jazz espiritual de \u2018The Sacred Concert\u2019 de Duke Ellington y el estreno de la \u2018Misa R\u00e9quiem\u2019 de Eslava, s\u00e1bado y lunes en Baluarte en el Festival de M\u00fasica Sacra\",\"datePublished\":\"2017-04-07T11:23:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\\\/\"},\"wordCount\":1191,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Folleto-Festival-Musica-Sacra-1.jpg\",\"articleSection\":[\"Ayto Pamplona\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\\\/\",\"name\":\"El jazz espiritual de \u2018The Sacred Concert\u2019 de Duke Ellington y el estreno de la \u2018Misa R\u00e9quiem\u2019 de Eslava, s\u00e1bado y lunes en Baluarte en el Festival de M\u00fasica Sacra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Folleto-Festival-Musica-Sacra-1.jpg\",\"datePublished\":\"2017-04-07T11:23:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Folleto-Festival-Musica-Sacra-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Folleto-Festival-Musica-Sacra-1.jpg\",\"width\":544,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El jazz espiritual de \u2018The Sacred Concert\u2019 de Duke Ellington y el estreno de la \u2018Misa R\u00e9quiem\u2019 de Eslava, s\u00e1bado y lunes en Baluarte en el Festival de M\u00fasica Sacra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#website\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"name\":\"La gu\u00eda de Pamplona\",\"description\":\"Noticias de Pamplona\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#organization\",\"name\":\"La Gu\u00eda de Pamplona \\\/ Noticias\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"contentUrl\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo-laguiadepamplona18-web1.png\",\"width\":600,\"height\":196,\"caption\":\"La Gu\u00eda de Pamplona \\\/ Noticias\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/laguiadepamplonacom-133175176762273\\\/?ref=hl\",\"https:\\\/\\\/x.com\\\/LaGuiadPamplona\",\"https:\\\/\\\/www.instagram.com\\\/la_guia_de_pamplona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/laguiadepamplona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laguiadepamplona.com\\\/actualidad\\\/#\\\/schema\\\/person\\\/efe887376f0213d4657c93adc50b1fdb\",\"name\":\"La Gu\u00eda de Pamplona\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g\",\"caption\":\"La Gu\u00eda de Pamplona\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El jazz espiritual de \u2018The Sacred Concert\u2019 de Duke Ellington y el estreno de la \u2018Misa R\u00e9quiem\u2019 de Eslava, s\u00e1bado y lunes en Baluarte en el Festival de M\u00fasica Sacra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/","og_locale":"es_ES","og_type":"article","og_title":"El jazz espiritual de \u2018The Sacred Concert\u2019 de Duke Ellington y el estreno de la \u2018Misa R\u00e9quiem\u2019 de Eslava, s\u00e1bado y lunes en Baluarte en el Festival de M\u00fasica Sacra","og_description":"El domingo actuar\u00e1n la Sinfonietta Acad\u00e9mica y el Coro Juvenil del Orfe\u00f3n Pamplon\u00e9s en la iglesia de los Carmelitas Descalzos","og_url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/","og_site_name":"La Gu\u00eda de Pamplona","article_publisher":"https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","article_published_time":"2017-04-07T11:23:56+00:00","og_image":[{"width":544,"height":1000,"url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/04\/Folleto-Festival-Musica-Sacra-1.jpg","type":"image\/jpeg"}],"author":"La Gu\u00eda de Pamplona","twitter_card":"summary_large_image","twitter_creator":"@LaGuiadPamplona","twitter_site":"@LaGuiadPamplona","twitter_misc":{"Escrito por":"La Gu\u00eda de Pamplona","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/#article","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/"},"author":{"name":"La Gu\u00eda de Pamplona","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb"},"headline":"El jazz espiritual de \u2018The Sacred Concert\u2019 de Duke Ellington y el estreno de la \u2018Misa R\u00e9quiem\u2019 de Eslava, s\u00e1bado y lunes en Baluarte en el Festival de M\u00fasica Sacra","datePublished":"2017-04-07T11:23:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/"},"wordCount":1191,"publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/04\/Folleto-Festival-Musica-Sacra-1.jpg","articleSection":["Ayto Pamplona"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/","name":"El jazz espiritual de \u2018The Sacred Concert\u2019 de Duke Ellington y el estreno de la \u2018Misa R\u00e9quiem\u2019 de Eslava, s\u00e1bado y lunes en Baluarte en el Festival de M\u00fasica Sacra","isPartOf":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/#primaryimage"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/04\/Folleto-Festival-Musica-Sacra-1.jpg","datePublished":"2017-04-07T11:23:56+00:00","breadcrumb":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/#primaryimage","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/04\/Folleto-Festival-Musica-Sacra-1.jpg","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2017\/04\/Folleto-Festival-Musica-Sacra-1.jpg","width":544,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/el-jazz-espiritual-de-the-sacred-concert-de-duke-ellington-y-el-estreno-de-la-misa-requiem-de-eslava-sabado-y-lunes-en-baluarte-en-el-festival-de-musica-sacra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.laguiadepamplona.com\/actualidad\/"},{"@type":"ListItem","position":2,"name":"El jazz espiritual de \u2018The Sacred Concert\u2019 de Duke Ellington y el estreno de la \u2018Misa R\u00e9quiem\u2019 de Eslava, s\u00e1bado y lunes en Baluarte en el Festival de M\u00fasica Sacra"}]},{"@type":"WebSite","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#website","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","name":"La gu\u00eda de Pamplona","description":"Noticias de Pamplona","publisher":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laguiadepamplona.com\/actualidad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#organization","name":"La Gu\u00eda de Pamplona \/ Noticias","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/","url":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","contentUrl":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-content\/uploads\/2018\/11\/logo-laguiadepamplona18-web1.png","width":600,"height":196,"caption":"La Gu\u00eda de Pamplona \/ Noticias"},"image":{"@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/laguiadepamplonacom-133175176762273\/?ref=hl","https:\/\/x.com\/LaGuiadPamplona","https:\/\/www.instagram.com\/la_guia_de_pamplona\/","https:\/\/www.youtube.com\/user\/laguiadepamplona"]},{"@type":"Person","@id":"https:\/\/www.laguiadepamplona.com\/actualidad\/#\/schema\/person\/efe887376f0213d4657c93adc50b1fdb","name":"La Gu\u00eda de Pamplona","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6992f131dc8d30ab0dff15446e9d346d9dbd95992de0fef795073f5ea83a81c?s=96&d=mm&r=g","caption":"La Gu\u00eda de Pamplona"}}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/12559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/comments?post=12559"}],"version-history":[{"count":0,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/posts\/12559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media\/12532"}],"wp:attachment":[{"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/media?parent=12559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/categories?post=12559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laguiadepamplona.com\/actualidad\/wp-json\/wp\/v2\/tags?post=12559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}